{"id":93421,"date":"2026-04-16T18:44:01","date_gmt":"2026-04-16T21:44:01","guid":{"rendered":"https:\/\/abifer.org.br\/?p=93421"},"modified":"2026-04-16T18:44:01","modified_gmt":"2026-04-16T21:44:01","slug":"antt-ajusta-data-de-audiencia-publica-e-reforca-compromisso-com-regras-mais-claras-e-seguras-para-o-transporte-ferroviario-de-cargas","status":"publish","type":"post","link":"http:\/\/abifer.org.br\/en\/antt-ajusta-data-de-audiencia-publica-e-reforca-compromisso-com-regras-mais-claras-e-seguras-para-o-transporte-ferroviario-de-cargas\/","title":{"rendered":"ANTT ajusta data de audi\u00eancia p\u00fablica e refor\u00e7a compromisso com regras mais claras e seguras para o transporte ferrovi\u00e1rio de cargas"},"content":{"rendered":"<pre style=\"text-align: right;\"><a href=\"https:\/\/www.gov.br\/antt\/pt-br\/assuntos\/ultimas-noticias\/antt-ajusta-data-de-audiencia-publica-e-reforca-compromisso-com-regras-mais-claras-e-seguras-para-o-transporte-ferroviario-de-cargas\" target=\"_blank\" rel=\"noopener\"><strong><em>Fonte: ANTT\r\nData: 15\/04\/2026<\/em><\/strong><\/a><\/pre>\n<p>A Ag\u00eancia Nacional de Transportes Terrestres (ANTT) informa a nova data da Audi\u00eancia P\u00fablica n\u00ba 05\/2026, etapa essencial para ouvir a sociedade e aprimorar regras que impactam diretamente a qualidade, a seguran\u00e7a e a previsibilidade do transporte ferrovi\u00e1rio de cargas no Brasil. A sess\u00e3o ocorrer\u00e1 no dia 7 de maio de 2026, em formato h\u00edbrido, garantindo participa\u00e7\u00e3o presencial e virtual. O Comunicado Relevante que traz a informa\u00e7\u00e3o est\u00e1 dispon\u00edvel no Di\u00e1rio Oficial da Uni\u00e3o (D.O.U).<\/p>\n<p>A mudan\u00e7a de data n\u00e3o altera o prop\u00f3sito central da audi\u00eancia: construir, com transpar\u00eancia e escuta ativa, uma regula\u00e7\u00e3o mais clara, moderna e eficiente para o setor ferrovi\u00e1rio. O encontro ser\u00e1 realizado das 14h \u00e0s 18h, no Audit\u00f3rio da ANTT, em Bras\u00edlia, com capacidade para 300 participantes, al\u00e9m de transmiss\u00e3o online, cujo acesso ser\u00e1 disponibilizado no mesmo dia do evento, at\u00e9 o meio-dia, no portal oficial da Ag\u00eancia.<\/p>\n<p>Na pr\u00e1tica, o que est\u00e1 em discuss\u00e3o \u00e9 algo que impacta toda a cadeia log\u00edstica do pa\u00eds e, por consequ\u00eancia, a vida das pessoas. A audi\u00eancia vai coletar contribui\u00e7\u00f5es sobre a proposta da primeira norma do Regulamento de Servi\u00e7os e Seguran\u00e7a Ferrovi\u00e1ria (RSF1), que trata dos direitos e garantias dos usu\u00e1rios e define par\u00e2metros para um servi\u00e7o adequado no transporte ferrovi\u00e1rio de cargas, tanto em concess\u00f5es quanto em autoriza\u00e7\u00f5es.<\/p>\n<p>Isso significa estabelecer regras mais claras sobre qualidade, responsabilidade, seguran\u00e7a e previsibilidade na presta\u00e7\u00e3o do servi\u00e7o. Para quem depende da ferrovia para produzir, escoar, abastecer ou trabalhar, esse conjunto de normas representa mais seguran\u00e7a jur\u00eddica, menos incerteza e maior efici\u00eancia log\u00edstica.<\/p>\n<p>A altera\u00e7\u00e3o da data foi motivada por quest\u00f5es administrativas relacionadas ao afastamento do presidente da audi\u00eancia, conforme ato formal j\u00e1 publicado, sem qualquer preju\u00edzo ao processo participativo. Todas as demais condi\u00e7\u00f5es previamente divulgadas permanecem inalteradas.<\/p>\n<p>A ANTT refor\u00e7a que a participa\u00e7\u00e3o social \u00e9 um dos pilares da regula\u00e7\u00e3o moderna. Ouvir diferentes vozes, do setor produtivo, operadores, especialistas e cidad\u00e3os, \u00e9 o que garante decis\u00f5es mais equilibradas, t\u00e9cnicas e conectadas com a realidade do pa\u00eds.<\/p>\n<p>As informa\u00e7\u00f5es completas sobre a Audi\u00eancia P\u00fablica n\u00ba 05\/2026, incluindo orienta\u00e7\u00f5es para participa\u00e7\u00e3o, est\u00e3o dispon\u00edveis no portal ParticipANTT. D\u00favidas adicionais podem ser encaminhadas pelo e-mail oficial do processo.<\/p>\n<p>Com esse di\u00e1logo aberto, a Ag\u00eancia reafirma e refor\u00e7a sua diretriz de construir solu\u00e7\u00f5es regulat\u00f3rias que n\u00e3o fiquem no papel, mas que funcionem na pr\u00e1tica, com foco em quem est\u00e1 na ponta: o usu\u00e1rio, o trabalhador, o cidad\u00e3o. Porque infraestrutura, antes de tudo, \u00e9 sobre pessoas<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fonte: ANTT Data: 15\/04\/2026 A Ag\u00eancia Nacional de Transportes Terrestres (ANTT) informa a nova data da Audi\u00eancia P\u00fablica n\u00ba 05\/2026, etapa essencial para ouvir a sociedade e aprimorar regras que impactam diretamente a qualidade, a seguran\u00e7a e a previsibilidade do transporte ferrovi\u00e1rio de cargas no Brasil. A sess\u00e3o ocorrer\u00e1 no dia 7 de maio de [&hellip;]<\/p>\n","protected":false},"author":55,"featured_media":92535,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[875],"tags":[],"class_list":["post-93421","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-do-mercado"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>ANTT ajusta data de audi\u00eancia p\u00fablica e refor\u00e7a compromisso com regras mais claras e seguras para o transporte ferrovi\u00e1rio de cargas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/abifer.org.br\/antt-ajusta-data-de-audiencia-publica-e-reforca-compromisso-com-regras-mais-claras-e-seguras-para-o-transporte-ferroviario-de-cargas\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ANTT ajusta data de audi\u00eancia p\u00fablica e refor\u00e7a compromisso com regras mais claras e seguras para o transporte ferrovi\u00e1rio de cargas\" \/>\n<meta property=\"og:description\" content=\"Fonte: ANTT Data: 15\/04\/2026 A Ag\u00eancia Nacional de Transportes Terrestres (ANTT) informa a nova data da Audi\u00eancia P\u00fablica n\u00ba 05\/2026, etapa essencial para ouvir a sociedade e aprimorar regras que impactam diretamente a qualidade, a seguran\u00e7a e a previsibilidade do transporte ferrovi\u00e1rio de cargas no Brasil. A sess\u00e3o ocorrer\u00e1 no dia 7 de maio de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/abifer.org.br\/en\/antt-ajusta-data-de-audiencia-publica-e-reforca-compromisso-com-regras-mais-claras-e-seguras-para-o-transporte-ferroviario-de-cargas\/\" \/>\n<meta property=\"og:site_name\" content=\"ABIFER\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/abiferoficial\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-16T21:44:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/abifer.org.br\/wp-content\/uploads\/2026\/02\/NOTICIAS-DO-MERCADO.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@abiferoficial\" \/>\n<meta name=\"twitter:site\" content=\"@abiferoficial\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"ABIFER\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"http:\/\/abifer.org.br\/en\/#organization\",\"name\":\"ABIFER\",\"url\":\"http:\/\/abifer.org.br\/en\/\",\"sameAs\":[\"https:\/\/www.facebook.com\/abiferoficial\/\",\"https:\/\/www.linkedin.com\/company\/abiferoficial\/\",\"https:\/\/twitter.com\/abiferoficial\"],\"logo\":{\"@type\":\"ImageObject\",\"@id\":\"http:\/\/abifer.org.br\/en\/#logo\",\"inLanguage\":\"pt-BR\",\"url\":\"https:\/\/abifer.org.br\/wp-content\/uploads\/2018\/05\/ABF_001_LogoSlogan.jpg\",\"contentUrl\":\"https:\/\/abifer.org.br\/wp-content\/uploads\/2018\/05\/ABF_001_LogoSlogan.jpg\",\"width\":1182,\"height\":486,\"caption\":\"ABIFER\"},\"image\":{\"@id\":\"http:\/\/abifer.org.br\/en\/#logo\"}},{\"@type\":\"WebSite\",\"@id\":\"http:\/\/abifer.org.br\/en\/#website\",\"url\":\"http:\/\/abifer.org.br\/en\/\",\"name\":\"ABIFER\",\"description\":\"Associa\u00e7\u00e3o Brasileira da Ind\u00fastria Ferrovi\u00e1ria\",\"publisher\":{\"@id\":\"http:\/\/abifer.org.br\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\/\/abifer.org.br\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/abifer.org.br\/en\/antt-ajusta-data-de-audiencia-publica-e-reforca-compromisso-com-regras-mais-claras-e-seguras-para-o-transporte-ferroviario-de-cargas\/#primaryimage\",\"inLanguage\":\"pt-BR\",\"url\":\"http:\/\/abifer.org.br\/wp-content\/uploads\/2026\/02\/NOTICIAS-DO-MERCADO.jpg\",\"contentUrl\":\"http:\/\/abifer.org.br\/wp-content\/uploads\/2026\/02\/NOTICIAS-DO-MERCADO.jpg\",\"width\":1920,\"height\":1080},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/abifer.org.br\/en\/antt-ajusta-data-de-audiencia-publica-e-reforca-compromisso-com-regras-mais-claras-e-seguras-para-o-transporte-ferroviario-de-cargas\/#webpage\",\"url\":\"https:\/\/abifer.org.br\/en\/antt-ajusta-data-de-audiencia-publica-e-reforca-compromisso-com-regras-mais-claras-e-seguras-para-o-transporte-ferroviario-de-cargas\/\",\"name\":\"ANTT ajusta data de audi\u00eancia p\u00fablica e refor\u00e7a compromisso com regras mais claras e seguras para o transporte ferrovi\u00e1rio de cargas\",\"isPartOf\":{\"@id\":\"http:\/\/abifer.org.br\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/abifer.org.br\/en\/antt-ajusta-data-de-audiencia-publica-e-reforca-compromisso-com-regras-mais-claras-e-seguras-para-o-transporte-ferroviario-de-cargas\/#primaryimage\"},\"datePublished\":\"2026-04-16T21:44:01+00:00\",\"dateModified\":\"2026-04-16T21:44:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/abifer.org.br\/en\/antt-ajusta-data-de-audiencia-publica-e-reforca-compromisso-com-regras-mais-claras-e-seguras-para-o-transporte-ferroviario-de-cargas\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/abifer.org.br\/en\/antt-ajusta-data-de-audiencia-publica-e-reforca-compromisso-com-regras-mais-claras-e-seguras-para-o-transporte-ferroviario-de-cargas\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/abifer.org.br\/en\/antt-ajusta-data-de-audiencia-publica-e-reforca-compromisso-com-regras-mais-claras-e-seguras-para-o-transporte-ferroviario-de-cargas\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"http:\/\/abifer.org.br\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ANTT ajusta data de audi\u00eancia p\u00fablica e refor\u00e7a compromisso com regras mais claras e seguras para o transporte ferrovi\u00e1rio de cargas\"}]},{\"@type\":\"Article\",\"@id\":\"https:\/\/abifer.org.br\/en\/antt-ajusta-data-de-audiencia-publica-e-reforca-compromisso-com-regras-mais-claras-e-seguras-para-o-transporte-ferroviario-de-cargas\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/abifer.org.br\/en\/antt-ajusta-data-de-audiencia-publica-e-reforca-compromisso-com-regras-mais-claras-e-seguras-para-o-transporte-ferroviario-de-cargas\/#webpage\"},\"author\":{\"@id\":\"http:\/\/abifer.org.br\/en\/#\/schema\/person\/90c38c3286f60a11b363834930f79a1f\"},\"headline\":\"ANTT ajusta data de audi\u00eancia p\u00fablica e refor\u00e7a compromisso com regras mais claras e seguras para o transporte ferrovi\u00e1rio de cargas\",\"datePublished\":\"2026-04-16T21:44:01+00:00\",\"dateModified\":\"2026-04-16T21:44:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/abifer.org.br\/en\/antt-ajusta-data-de-audiencia-publica-e-reforca-compromisso-com-regras-mais-claras-e-seguras-para-o-transporte-ferroviario-de-cargas\/#webpage\"},\"wordCount\":495,\"publisher\":{\"@id\":\"http:\/\/abifer.org.br\/en\/#organization\"},\"image\":{\"@id\":\"https:\/\/abifer.org.br\/en\/antt-ajusta-data-de-audiencia-publica-e-reforca-compromisso-com-regras-mais-claras-e-seguras-para-o-transporte-ferroviario-de-cargas\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/abifer.org.br\/wp-content\/uploads\/2026\/02\/NOTICIAS-DO-MERCADO.jpg\",\"articleSection\":[\"Not\u00edcias do Mercado\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"http:\/\/abifer.org.br\/en\/#\/schema\/person\/90c38c3286f60a11b363834930f79a1f\",\"name\":\"ABIFER\",\"url\":\"http:\/\/abifer.org.br\/author\/abifer\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ANTT ajusta data de audi\u00eancia p\u00fablica e refor\u00e7a compromisso com regras mais claras e seguras para o transporte ferrovi\u00e1rio de cargas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/abifer.org.br\/antt-ajusta-data-de-audiencia-publica-e-reforca-compromisso-com-regras-mais-claras-e-seguras-para-o-transporte-ferroviario-de-cargas\/","og_locale":"pt_BR","og_type":"article","og_title":"ANTT ajusta data de audi\u00eancia p\u00fablica e refor\u00e7a compromisso com regras mais claras e seguras para o transporte ferrovi\u00e1rio de cargas","og_description":"Fonte: ANTT Data: 15\/04\/2026 A Ag\u00eancia Nacional de Transportes Terrestres (ANTT) informa a nova data da Audi\u00eancia P\u00fablica n\u00ba 05\/2026, etapa essencial para ouvir a sociedade e aprimorar regras que impactam diretamente a qualidade, a seguran\u00e7a e a previsibilidade do transporte ferrovi\u00e1rio de cargas no Brasil. A sess\u00e3o ocorrer\u00e1 no dia 7 de maio de [&hellip;]","og_url":"https:\/\/abifer.org.br\/en\/antt-ajusta-data-de-audiencia-publica-e-reforca-compromisso-com-regras-mais-claras-e-seguras-para-o-transporte-ferroviario-de-cargas\/","og_site_name":"ABIFER","article_publisher":"https:\/\/www.facebook.com\/abiferoficial\/","article_published_time":"2026-04-16T21:44:01+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/abifer.org.br\/wp-content\/uploads\/2026\/02\/NOTICIAS-DO-MERCADO.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_creator":"@abiferoficial","twitter_site":"@abiferoficial","twitter_misc":{"Escrito por":"ABIFER","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Organization","@id":"http:\/\/abifer.org.br\/en\/#organization","name":"ABIFER","url":"http:\/\/abifer.org.br\/en\/","sameAs":["https:\/\/www.facebook.com\/abiferoficial\/","https:\/\/www.linkedin.com\/company\/abiferoficial\/","https:\/\/twitter.com\/abiferoficial"],"logo":{"@type":"ImageObject","@id":"http:\/\/abifer.org.br\/en\/#logo","inLanguage":"pt-BR","url":"https:\/\/abifer.org.br\/wp-content\/uploads\/2018\/05\/ABF_001_LogoSlogan.jpg","contentUrl":"https:\/\/abifer.org.br\/wp-content\/uploads\/2018\/05\/ABF_001_LogoSlogan.jpg","width":1182,"height":486,"caption":"ABIFER"},"image":{"@id":"http:\/\/abifer.org.br\/en\/#logo"}},{"@type":"WebSite","@id":"http:\/\/abifer.org.br\/en\/#website","url":"http:\/\/abifer.org.br\/en\/","name":"ABIFER","description":"Associa\u00e7\u00e3o Brasileira da Ind\u00fastria Ferrovi\u00e1ria","publisher":{"@id":"http:\/\/abifer.org.br\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/abifer.org.br\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"ImageObject","@id":"https:\/\/abifer.org.br\/en\/antt-ajusta-data-de-audiencia-publica-e-reforca-compromisso-com-regras-mais-claras-e-seguras-para-o-transporte-ferroviario-de-cargas\/#primaryimage","inLanguage":"pt-BR","url":"http:\/\/abifer.org.br\/wp-content\/uploads\/2026\/02\/NOTICIAS-DO-MERCADO.jpg","contentUrl":"http:\/\/abifer.org.br\/wp-content\/uploads\/2026\/02\/NOTICIAS-DO-MERCADO.jpg","width":1920,"height":1080},{"@type":"WebPage","@id":"https:\/\/abifer.org.br\/en\/antt-ajusta-data-de-audiencia-publica-e-reforca-compromisso-com-regras-mais-claras-e-seguras-para-o-transporte-ferroviario-de-cargas\/#webpage","url":"https:\/\/abifer.org.br\/en\/antt-ajusta-data-de-audiencia-publica-e-reforca-compromisso-com-regras-mais-claras-e-seguras-para-o-transporte-ferroviario-de-cargas\/","name":"ANTT ajusta data de audi\u00eancia p\u00fablica e refor\u00e7a compromisso com regras mais claras e seguras para o transporte ferrovi\u00e1rio de cargas","isPartOf":{"@id":"http:\/\/abifer.org.br\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/abifer.org.br\/en\/antt-ajusta-data-de-audiencia-publica-e-reforca-compromisso-com-regras-mais-claras-e-seguras-para-o-transporte-ferroviario-de-cargas\/#primaryimage"},"datePublished":"2026-04-16T21:44:01+00:00","dateModified":"2026-04-16T21:44:01+00:00","breadcrumb":{"@id":"https:\/\/abifer.org.br\/en\/antt-ajusta-data-de-audiencia-publica-e-reforca-compromisso-com-regras-mais-claras-e-seguras-para-o-transporte-ferroviario-de-cargas\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/abifer.org.br\/en\/antt-ajusta-data-de-audiencia-publica-e-reforca-compromisso-com-regras-mais-claras-e-seguras-para-o-transporte-ferroviario-de-cargas\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/abifer.org.br\/en\/antt-ajusta-data-de-audiencia-publica-e-reforca-compromisso-com-regras-mais-claras-e-seguras-para-o-transporte-ferroviario-de-cargas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"http:\/\/abifer.org.br\/en\/"},{"@type":"ListItem","position":2,"name":"ANTT ajusta data de audi\u00eancia p\u00fablica e refor\u00e7a compromisso com regras mais claras e seguras para o transporte ferrovi\u00e1rio de cargas"}]},{"@type":"Article","@id":"https:\/\/abifer.org.br\/en\/antt-ajusta-data-de-audiencia-publica-e-reforca-compromisso-com-regras-mais-claras-e-seguras-para-o-transporte-ferroviario-de-cargas\/#article","isPartOf":{"@id":"https:\/\/abifer.org.br\/en\/antt-ajusta-data-de-audiencia-publica-e-reforca-compromisso-com-regras-mais-claras-e-seguras-para-o-transporte-ferroviario-de-cargas\/#webpage"},"author":{"@id":"http:\/\/abifer.org.br\/en\/#\/schema\/person\/90c38c3286f60a11b363834930f79a1f"},"headline":"ANTT ajusta data de audi\u00eancia p\u00fablica e refor\u00e7a compromisso com regras mais claras e seguras para o transporte ferrovi\u00e1rio de cargas","datePublished":"2026-04-16T21:44:01+00:00","dateModified":"2026-04-16T21:44:01+00:00","mainEntityOfPage":{"@id":"https:\/\/abifer.org.br\/en\/antt-ajusta-data-de-audiencia-publica-e-reforca-compromisso-com-regras-mais-claras-e-seguras-para-o-transporte-ferroviario-de-cargas\/#webpage"},"wordCount":495,"publisher":{"@id":"http:\/\/abifer.org.br\/en\/#organization"},"image":{"@id":"https:\/\/abifer.org.br\/en\/antt-ajusta-data-de-audiencia-publica-e-reforca-compromisso-com-regras-mais-claras-e-seguras-para-o-transporte-ferroviario-de-cargas\/#primaryimage"},"thumbnailUrl":"http:\/\/abifer.org.br\/wp-content\/uploads\/2026\/02\/NOTICIAS-DO-MERCADO.jpg","articleSection":["Not\u00edcias do Mercado"],"inLanguage":"pt-BR"},{"@type":"Person","@id":"http:\/\/abifer.org.br\/en\/#\/schema\/person\/90c38c3286f60a11b363834930f79a1f","name":"ABIFER","url":"http:\/\/abifer.org.br\/author\/abifer\/"}]}},"_links":{"self":[{"href":"http:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/posts\/93421\/"}],"collection":[{"href":"http:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/posts\/"}],"about":[{"href":"http:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/types\/post\/"}],"author":[{"embeddable":true,"href":"http:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/users\/55\/"}],"replies":[{"embeddable":true,"href":"http:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/comments\/?post=93421"}],"version-history":[{"count":1,"href":"http:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/posts\/93421\/revisions\/"}],"predecessor-version":[{"id":93422,"href":"http:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/posts\/93421\/revisions\/93422\/"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/media\/92535\/"}],"wp:attachment":[{"href":"http:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/media\/?parent=93421"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/categories\/?post=93421"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/tags\/?post=93421"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}