{"id":84844,"date":"2024-11-04T19:26:40","date_gmt":"2024-11-04T22:26:40","guid":{"rendered":"https:\/\/abifer.org.br\/?p=84844"},"modified":"2024-11-04T19:26:40","modified_gmt":"2024-11-04T22:26:40","slug":"desenvolvimento-economico-da-regiao-mobiliza-empresarios-e-poder-publico-em-hortolandia","status":"publish","type":"post","link":"https:\/\/abifer.org.br\/en\/desenvolvimento-economico-da-regiao-mobiliza-empresarios-e-poder-publico-em-hortolandia\/","title":{"rendered":"Desenvolvimento econ\u00f4mico da regi\u00e3o mobiliza empres\u00e1rios e Poder P\u00fablico em Hortol\u00e2ndia"},"content":{"rendered":"<pre style=\"text-align: right;\"><a href=\"https:\/\/www.hortolandia.sp.gov.br\/emprego-e-renda\/desenvolvimento-economico-da-regiao-mobiliza-empresarios-e-poder-publico-em-hortolandia\/\" target=\"_blank\" rel=\"noopener\"><i>Fonte: Departamento de Comunica\u00e7\u00e3o - Prefeitura de Hortol\u00e2ndia\r\nData: 31\/10\/2024<\/i><\/a><\/pre>\n<p>&nbsp;<\/p>\n<p>Cerca de 70 pessoas, dentre elas representantes do Poder P\u00fablico, lideran\u00e7as empresariais e agentes econ\u00f4micos locais e regionais, assistiram, na tarde desta quinta-feira (31\/10), \u00e0 palestra \u201cDesenvolvimento Econ\u00f4mico na regi\u00e3o de Hortol\u00e2ndia\u201d, ministrada pelo secret\u00e1rio de Desenvolvimento Econ\u00f4mico do Estado de S\u00e3o Paulo, Jorge Lima, no plen\u00e1rio da C\u00e2mara Municipal, no Pq. Gabriel. O evento, que teve o apoio da Prefeitura, por meio da Secretaria de Desenvolvimento Econ\u00f4mico, Trabalho, Turismo e Inova\u00e7\u00e3o, contou com a presen\u00e7a do prefeito Jos\u00e9 Nazareno Zez\u00e9 Gomes.<\/p>\n<p>\u201cTratamos as empresas da cidade como uma p\u00e9rola, porque s\u00e3o respons\u00e1veis pela riqueza, por tudo aquilo que produzem. Hortol\u00e2ndia, para quem chega hoje, parece que j\u00e1 nasceu assim. Mas para aqueles mais antigos, principalmente das grandes empresas que estavam h\u00e1 muitos anos na cidade, aos moradores, aos trabalhadores e trabalhadoras, esses sabem que n\u00e3o tinha saneamento b\u00e1sico, n\u00e3o tinha \u00e1gua, n\u00e3o tinha esgoto. Era cidade do barro, do p\u00e9 vermelho e as pessoas tinham vergonha de falar que moravam em Hortol\u00e2ndia. \u00c9 muito importante fazer essa retrospectiva, at\u00e9 porque o crescimento fant\u00e1stico da cidade, hoje aos 33 anos, se d\u00e1 a tudo aquilo que foi constru\u00eddo por v\u00e1rias m\u00e3os, por esses empres\u00e1rios que acreditavam na cidade, uma gest\u00e3o p\u00fablica aut\u00eantica de qualidade, que resolveu fazer o melhor, que foi cuidar do saneamento b\u00e1sico. Hoje, Hortol\u00e2ndia \u00e9 uma cidade que todos querem para morar e \u00e9 um atrativo para as empresas. Estamos naquele eixo entre a Anhanguera e a Bandeirantes e a poucos quil\u00f4metros do aeroporto. Temos 99% de esgoto coletado e 100% tratado, \u00e1gua na torneira, energia de qualidade, mais de 90 km de fibra \u00f3tica. Tudo isso \u00e9 um atrativo interessant\u00edssimo para as empresas que querem tamb\u00e9m estar na nossa cidade e hoje para n\u00f3s \u00e9 um motivo de orgulho\u201d, ressaltou Zez\u00e9 Gomes.<\/p>\n<p>Durante o encontro, Jorge Lima apresentou o Plano de Desenvolvimento Regional do governo paulista e convidou as lideran\u00e7as presentes a formarem uma coaliz\u00e3o empresarial a fim de fomentar o crescimento local e regional, criar impacto na vida da popula\u00e7\u00e3o e estimular tanto uma maior sinergia na cadeia produtiva quanto a voca\u00e7\u00e3o industrial do territ\u00f3rio. Segundo ele, a proposta vem sendo apresentada a todos os munic\u00edpios paulistas e busca discutir medidas deste plano que possam \u201cviabilizar formas de incentivo ao empreendedorismo, atra\u00e7\u00e3o de investimentos e fortalecimento da economia local, de acordo com as voca\u00e7\u00f5es de cada regi\u00e3o\u201d.<\/p>\n<p>\u201cEstamos preparados para fazer S\u00e3o Paulo voltar a ser o destaque industrial. Vamos criar as coaliz\u00f5es para inserir todas as regi\u00f5es administrativas no PIB paulista. Com isso, podemos direcionar os nossos programas para atender as demandas de cada regi\u00e3o\u201d, afirmou Lima.<\/p>\n<p>A coaliza\u00e7\u00e3o tamb\u00e9m contemplaria qualifica\u00e7\u00e3o profissional, linhas de cr\u00e9dito para empreendedorismo e atra\u00e7\u00e3o de novos investimentos para o territ\u00f3rio e a regi\u00e3o.<\/p>\n<blockquote><p><em><strong>Entre os presentes estava o presidente da ABIFER (Associa\u00e7\u00e3o Brasileira da Ind\u00fastria Ferrovi\u00e1ria), Vicente Abate, que v\u00ea com bons olhos a forma\u00e7\u00e3o da coaliz\u00e3o em Hortol\u00e2ndia e regi\u00e3o.<\/strong><\/em><\/p>\n<p><em><strong>\u201cO governo do estado tem feito um trabalho excelente nesse sentido de agregar valor ao estado de S\u00e3o Paulo e Hortol\u00e2ndia est\u00e1 no centro dessas aten\u00e7\u00f5es. Estou muito feliz de estar aqui em Hortol\u00e2ndia, que eu diria que \u00e9 a minha segunda terra, porque temos atividades ferrovi\u00e1rias na cidade, atrav\u00e9s da Greenbrier Maxion e da CAF. Estamos felizes com essa situa\u00e7\u00e3o e dando todo o apoio ao governo do estado de S\u00e3o Paulo, porque sabemos que n\u00f3s teremos uma retribui\u00e7\u00e3o do estado ao setor ferrovi\u00e1rio. Podemos contribuir no sentido de oferecer alternativas a essa coaliz\u00e3o, no sentido de fazer estudos, projetos na \u00e1rea da ind\u00fastria ferrovi\u00e1ria e isso vai ser passado para o governo da cidade, para o prefeito, e tamb\u00e9m para o pr\u00f3prio governador\u201d, afirmou Abate.<\/strong><\/em><\/p><\/blockquote>\n<p>Para o secret\u00e1rio de Desenvolvimento Econ\u00f4mico, Trabalho, Turismo e Inova\u00e7\u00e3o de Hortol\u00e2ndia, Dimas Corr\u00eaa P\u00e1dua, esta sinergia entre o Poder P\u00fablico Estadual e Municipal e a iniciativa privada, na \u00e1rea econ\u00f4mica, \u00e9 bastante relevante, sobretudo pela for\u00e7a do setor industrial no munic\u00edpio.<\/p>\n<p>\u201cEsta pol\u00edtica p\u00fablica estadual vem casar com aquilo que a gente pensa aqui no nosso munic\u00edpio com rela\u00e7\u00e3o \u00e0 amplia\u00e7\u00e3o das unidades produtivas e \u00e0 gera\u00e7\u00e3o de mais emprego. \u00c9\u00a0 de suma import\u00e2ncia otimizar as rela\u00e7\u00f5es entre as unidades produtivas do territ\u00f3rio com a regi\u00e3o. O setor industrial no nosso munic\u00edpio \u00e9 o que mais produz riqueza no territ\u00f3rio. Hoje representa 38% do PIB (Produto Interno Bruto) municipal e, para tanto, \u00e9 fundamental a gente pensar em maximizar e otimizar as rela\u00e7\u00f5es entre as unidades produtivas. Dessa forma, poderemos gerar mais emprego, melhorar a renda e assim desenvolver mais, buscando qualidade de vida aos nossos trabalhadores\u201d, afirmou o secret\u00e1rio.<\/p>\n<p>P\u00e1dua estima que o PIB de Hortol\u00e2ndia em 2024 girar\u00e1 em torno dos R$ 23 bilh\u00f5es, distribuindo-se em quatro setores principais: 38% \u2013 ind\u00fastria, 17% constru\u00e7\u00e3o civil, 13% servi\u00e7os (sobretudo da \u00e1rea tecnol\u00f3gica) e 12% log\u00edstica. Uma das principais ferramentas usadas para aferir a atividade econ\u00f4mica, o PIB mede o valor dos bens e servi\u00e7os finais produzidos, em determinado per\u00edodo, em uma localidade ou regi\u00e3o.<\/p>\n<p style=\"text-align: right;\"><em>Imagem: criada por IA\u00a0<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fonte: Departamento de Comunica\u00e7\u00e3o &#8211; Prefeitura de Hortol\u00e2ndia Data: 31\/10\/2024 &nbsp; Cerca de 70 pessoas, dentre elas representantes do Poder P\u00fablico, lideran\u00e7as empresariais e agentes econ\u00f4micos locais e regionais, assistiram, na tarde desta quinta-feira (31\/10), \u00e0 palestra \u201cDesenvolvimento Econ\u00f4mico na regi\u00e3o de Hortol\u00e2ndia\u201d, ministrada pelo secret\u00e1rio de Desenvolvimento Econ\u00f4mico do Estado de S\u00e3o Paulo, Jorge [&hellip;]<\/p>\n","protected":false},"author":55,"featured_media":84847,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[875],"tags":[],"class_list":["post-84844","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-do-mercado"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Desenvolvimento econ\u00f4mico da regi\u00e3o mobiliza empres\u00e1rios e Poder P\u00fablico em Hortol\u00e2ndia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/abifer.org.br\/desenvolvimento-economico-da-regiao-mobiliza-empresarios-e-poder-publico-em-hortolandia\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Desenvolvimento econ\u00f4mico da regi\u00e3o mobiliza empres\u00e1rios e Poder P\u00fablico em Hortol\u00e2ndia\" \/>\n<meta property=\"og:description\" content=\"Fonte: Departamento de Comunica\u00e7\u00e3o - Prefeitura de Hortol\u00e2ndia Data: 31\/10\/2024 &nbsp; Cerca de 70 pessoas, dentre elas representantes do Poder P\u00fablico, lideran\u00e7as empresariais e agentes econ\u00f4micos locais e regionais, assistiram, na tarde desta quinta-feira (31\/10), \u00e0 palestra \u201cDesenvolvimento Econ\u00f4mico na regi\u00e3o de Hortol\u00e2ndia\u201d, ministrada pelo secret\u00e1rio de Desenvolvimento Econ\u00f4mico do Estado de S\u00e3o Paulo, Jorge [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/abifer.org.br\/en\/desenvolvimento-economico-da-regiao-mobiliza-empresarios-e-poder-publico-em-hortolandia\/\" \/>\n<meta property=\"og:site_name\" content=\"ABIFER\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/abiferoficial\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-11-04T22:26:40+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/abifer.org.br\/wp-content\/uploads\/2024\/11\/cidade-desenvolvimento-economico-criadaporIA.webp\" \/>\n<meta name=\"twitter:creator\" content=\"@abiferoficial\" \/>\n<meta name=\"twitter:site\" content=\"@abiferoficial\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"ABIFER\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/abifer.org.br\/en\/#organization\",\"name\":\"ABIFER\",\"url\":\"https:\/\/abifer.org.br\/en\/\",\"sameAs\":[\"https:\/\/www.facebook.com\/abiferoficial\/\",\"https:\/\/www.linkedin.com\/company\/abiferoficial\/\",\"https:\/\/twitter.com\/abiferoficial\"],\"logo\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/abifer.org.br\/en\/#logo\",\"inLanguage\":\"pt-BR\",\"url\":\"https:\/\/abifer.org.br\/wp-content\/uploads\/2018\/05\/ABF_001_LogoSlogan.jpg\",\"contentUrl\":\"https:\/\/abifer.org.br\/wp-content\/uploads\/2018\/05\/ABF_001_LogoSlogan.jpg\",\"width\":1182,\"height\":486,\"caption\":\"ABIFER\"},\"image\":{\"@id\":\"https:\/\/abifer.org.br\/en\/#logo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/abifer.org.br\/en\/#website\",\"url\":\"https:\/\/abifer.org.br\/en\/\",\"name\":\"ABIFER\",\"description\":\"Associa\u00e7\u00e3o Brasileira da Ind\u00fastria Ferrovi\u00e1ria\",\"publisher\":{\"@id\":\"https:\/\/abifer.org.br\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/abifer.org.br\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/abifer.org.br\/en\/desenvolvimento-economico-da-regiao-mobiliza-empresarios-e-poder-publico-em-hortolandia\/#primaryimage\",\"inLanguage\":\"pt-BR\",\"url\":\"https:\/\/abifer.org.br\/wp-content\/uploads\/2024\/11\/cidade-desenvolvimento-economico-criadaporIA.webp\",\"contentUrl\":\"https:\/\/abifer.org.br\/wp-content\/uploads\/2024\/11\/cidade-desenvolvimento-economico-criadaporIA.webp\",\"width\":1792,\"height\":1024},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/abifer.org.br\/en\/desenvolvimento-economico-da-regiao-mobiliza-empresarios-e-poder-publico-em-hortolandia\/#webpage\",\"url\":\"https:\/\/abifer.org.br\/en\/desenvolvimento-economico-da-regiao-mobiliza-empresarios-e-poder-publico-em-hortolandia\/\",\"name\":\"Desenvolvimento econ\u00f4mico da regi\u00e3o mobiliza empres\u00e1rios e Poder P\u00fablico em Hortol\u00e2ndia\",\"isPartOf\":{\"@id\":\"https:\/\/abifer.org.br\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/abifer.org.br\/en\/desenvolvimento-economico-da-regiao-mobiliza-empresarios-e-poder-publico-em-hortolandia\/#primaryimage\"},\"datePublished\":\"2024-11-04T22:26:40+00:00\",\"dateModified\":\"2024-11-04T22:26:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/abifer.org.br\/en\/desenvolvimento-economico-da-regiao-mobiliza-empresarios-e-poder-publico-em-hortolandia\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/abifer.org.br\/en\/desenvolvimento-economico-da-regiao-mobiliza-empresarios-e-poder-publico-em-hortolandia\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/abifer.org.br\/en\/desenvolvimento-economico-da-regiao-mobiliza-empresarios-e-poder-publico-em-hortolandia\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/abifer.org.br\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Desenvolvimento econ\u00f4mico da regi\u00e3o mobiliza empres\u00e1rios e Poder P\u00fablico em Hortol\u00e2ndia\"}]},{\"@type\":\"Article\",\"@id\":\"https:\/\/abifer.org.br\/en\/desenvolvimento-economico-da-regiao-mobiliza-empresarios-e-poder-publico-em-hortolandia\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/abifer.org.br\/en\/desenvolvimento-economico-da-regiao-mobiliza-empresarios-e-poder-publico-em-hortolandia\/#webpage\"},\"author\":{\"@id\":\"https:\/\/abifer.org.br\/en\/#\/schema\/person\/90c38c3286f60a11b363834930f79a1f\"},\"headline\":\"Desenvolvimento econ\u00f4mico da regi\u00e3o mobiliza empres\u00e1rios e Poder P\u00fablico em Hortol\u00e2ndia\",\"datePublished\":\"2024-11-04T22:26:40+00:00\",\"dateModified\":\"2024-11-04T22:26:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/abifer.org.br\/en\/desenvolvimento-economico-da-regiao-mobiliza-empresarios-e-poder-publico-em-hortolandia\/#webpage\"},\"wordCount\":936,\"publisher\":{\"@id\":\"https:\/\/abifer.org.br\/en\/#organization\"},\"image\":{\"@id\":\"https:\/\/abifer.org.br\/en\/desenvolvimento-economico-da-regiao-mobiliza-empresarios-e-poder-publico-em-hortolandia\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/abifer.org.br\/wp-content\/uploads\/2024\/11\/cidade-desenvolvimento-economico-criadaporIA.webp\",\"articleSection\":[\"Not\u00edcias do Mercado\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/abifer.org.br\/en\/#\/schema\/person\/90c38c3286f60a11b363834930f79a1f\",\"name\":\"ABIFER\",\"url\":\"https:\/\/abifer.org.br\/author\/abifer\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Desenvolvimento econ\u00f4mico da regi\u00e3o mobiliza empres\u00e1rios e Poder P\u00fablico em Hortol\u00e2ndia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/abifer.org.br\/desenvolvimento-economico-da-regiao-mobiliza-empresarios-e-poder-publico-em-hortolandia\/","og_locale":"pt_BR","og_type":"article","og_title":"Desenvolvimento econ\u00f4mico da regi\u00e3o mobiliza empres\u00e1rios e Poder P\u00fablico em Hortol\u00e2ndia","og_description":"Fonte: Departamento de Comunica\u00e7\u00e3o - Prefeitura de Hortol\u00e2ndia Data: 31\/10\/2024 &nbsp; Cerca de 70 pessoas, dentre elas representantes do Poder P\u00fablico, lideran\u00e7as empresariais e agentes econ\u00f4micos locais e regionais, assistiram, na tarde desta quinta-feira (31\/10), \u00e0 palestra \u201cDesenvolvimento Econ\u00f4mico na regi\u00e3o de Hortol\u00e2ndia\u201d, ministrada pelo secret\u00e1rio de Desenvolvimento Econ\u00f4mico do Estado de S\u00e3o Paulo, Jorge [&hellip;]","og_url":"https:\/\/abifer.org.br\/en\/desenvolvimento-economico-da-regiao-mobiliza-empresarios-e-poder-publico-em-hortolandia\/","og_site_name":"ABIFER","article_publisher":"https:\/\/www.facebook.com\/abiferoficial\/","article_published_time":"2024-11-04T22:26:40+00:00","twitter_card":"summary_large_image","twitter_image":"https:\/\/abifer.org.br\/wp-content\/uploads\/2024\/11\/cidade-desenvolvimento-economico-criadaporIA.webp","twitter_creator":"@abiferoficial","twitter_site":"@abiferoficial","twitter_misc":{"Escrito por":"ABIFER","Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Organization","@id":"https:\/\/abifer.org.br\/en\/#organization","name":"ABIFER","url":"https:\/\/abifer.org.br\/en\/","sameAs":["https:\/\/www.facebook.com\/abiferoficial\/","https:\/\/www.linkedin.com\/company\/abiferoficial\/","https:\/\/twitter.com\/abiferoficial"],"logo":{"@type":"ImageObject","@id":"https:\/\/abifer.org.br\/en\/#logo","inLanguage":"pt-BR","url":"https:\/\/abifer.org.br\/wp-content\/uploads\/2018\/05\/ABF_001_LogoSlogan.jpg","contentUrl":"https:\/\/abifer.org.br\/wp-content\/uploads\/2018\/05\/ABF_001_LogoSlogan.jpg","width":1182,"height":486,"caption":"ABIFER"},"image":{"@id":"https:\/\/abifer.org.br\/en\/#logo"}},{"@type":"WebSite","@id":"https:\/\/abifer.org.br\/en\/#website","url":"https:\/\/abifer.org.br\/en\/","name":"ABIFER","description":"Associa\u00e7\u00e3o Brasileira da Ind\u00fastria Ferrovi\u00e1ria","publisher":{"@id":"https:\/\/abifer.org.br\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/abifer.org.br\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"ImageObject","@id":"https:\/\/abifer.org.br\/en\/desenvolvimento-economico-da-regiao-mobiliza-empresarios-e-poder-publico-em-hortolandia\/#primaryimage","inLanguage":"pt-BR","url":"https:\/\/abifer.org.br\/wp-content\/uploads\/2024\/11\/cidade-desenvolvimento-economico-criadaporIA.webp","contentUrl":"https:\/\/abifer.org.br\/wp-content\/uploads\/2024\/11\/cidade-desenvolvimento-economico-criadaporIA.webp","width":1792,"height":1024},{"@type":"WebPage","@id":"https:\/\/abifer.org.br\/en\/desenvolvimento-economico-da-regiao-mobiliza-empresarios-e-poder-publico-em-hortolandia\/#webpage","url":"https:\/\/abifer.org.br\/en\/desenvolvimento-economico-da-regiao-mobiliza-empresarios-e-poder-publico-em-hortolandia\/","name":"Desenvolvimento econ\u00f4mico da regi\u00e3o mobiliza empres\u00e1rios e Poder P\u00fablico em Hortol\u00e2ndia","isPartOf":{"@id":"https:\/\/abifer.org.br\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/abifer.org.br\/en\/desenvolvimento-economico-da-regiao-mobiliza-empresarios-e-poder-publico-em-hortolandia\/#primaryimage"},"datePublished":"2024-11-04T22:26:40+00:00","dateModified":"2024-11-04T22:26:40+00:00","breadcrumb":{"@id":"https:\/\/abifer.org.br\/en\/desenvolvimento-economico-da-regiao-mobiliza-empresarios-e-poder-publico-em-hortolandia\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/abifer.org.br\/en\/desenvolvimento-economico-da-regiao-mobiliza-empresarios-e-poder-publico-em-hortolandia\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/abifer.org.br\/en\/desenvolvimento-economico-da-regiao-mobiliza-empresarios-e-poder-publico-em-hortolandia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/abifer.org.br\/en\/"},{"@type":"ListItem","position":2,"name":"Desenvolvimento econ\u00f4mico da regi\u00e3o mobiliza empres\u00e1rios e Poder P\u00fablico em Hortol\u00e2ndia"}]},{"@type":"Article","@id":"https:\/\/abifer.org.br\/en\/desenvolvimento-economico-da-regiao-mobiliza-empresarios-e-poder-publico-em-hortolandia\/#article","isPartOf":{"@id":"https:\/\/abifer.org.br\/en\/desenvolvimento-economico-da-regiao-mobiliza-empresarios-e-poder-publico-em-hortolandia\/#webpage"},"author":{"@id":"https:\/\/abifer.org.br\/en\/#\/schema\/person\/90c38c3286f60a11b363834930f79a1f"},"headline":"Desenvolvimento econ\u00f4mico da regi\u00e3o mobiliza empres\u00e1rios e Poder P\u00fablico em Hortol\u00e2ndia","datePublished":"2024-11-04T22:26:40+00:00","dateModified":"2024-11-04T22:26:40+00:00","mainEntityOfPage":{"@id":"https:\/\/abifer.org.br\/en\/desenvolvimento-economico-da-regiao-mobiliza-empresarios-e-poder-publico-em-hortolandia\/#webpage"},"wordCount":936,"publisher":{"@id":"https:\/\/abifer.org.br\/en\/#organization"},"image":{"@id":"https:\/\/abifer.org.br\/en\/desenvolvimento-economico-da-regiao-mobiliza-empresarios-e-poder-publico-em-hortolandia\/#primaryimage"},"thumbnailUrl":"https:\/\/abifer.org.br\/wp-content\/uploads\/2024\/11\/cidade-desenvolvimento-economico-criadaporIA.webp","articleSection":["Not\u00edcias do Mercado"],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/abifer.org.br\/en\/#\/schema\/person\/90c38c3286f60a11b363834930f79a1f","name":"ABIFER","url":"https:\/\/abifer.org.br\/author\/abifer\/"}]}},"_links":{"self":[{"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/posts\/84844\/"}],"collection":[{"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/posts\/"}],"about":[{"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/types\/post\/"}],"author":[{"embeddable":true,"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/users\/55\/"}],"replies":[{"embeddable":true,"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/comments\/?post=84844"}],"version-history":[{"count":1,"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/posts\/84844\/revisions\/"}],"predecessor-version":[{"id":84849,"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/posts\/84844\/revisions\/84849\/"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/media\/84847\/"}],"wp:attachment":[{"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/media\/?parent=84844"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/categories\/?post=84844"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/tags\/?post=84844"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}