{"id":85003,"date":"2024-11-14T18:34:11","date_gmt":"2024-11-14T21:34:11","guid":{"rendered":"https:\/\/abifer.org.br\/?p=85003"},"modified":"2024-11-14T18:34:11","modified_gmt":"2024-11-14T21:34:11","slug":"fundo-clima-do-bndes-aprova-em-7-meses-25-vezes-o-valor-liberado-nos-ultimos-11-anos","status":"publish","type":"post","link":"https:\/\/abifer.org.br\/en\/fundo-clima-do-bndes-aprova-em-7-meses-25-vezes-o-valor-liberado-nos-ultimos-11-anos\/","title":{"rendered":"Fundo Clima, do BNDES, aprova em 7 meses 2,5 vezes o valor liberado nos \u00faltimos 11 anos"},"content":{"rendered":"<pre style=\"text-align: right;\"><a href=\"https:\/\/www.estadao.com.br\/economia\/fundo-clima-bndes-projetos\/\" target=\"_blank\" rel=\"noopener\"><strong><em>Fonte: Estad\u00e3o\r\nData: 12\/11\/2024<\/em><\/strong><\/a><\/pre>\n<p>O <strong>Banco Nacional de Desenvolvimento Econ\u00f4mico e Social (BNDES)<\/strong>\u00a0aprovou em sete meses (de abril a outubro), o correspondente a duas vezes e meia todas as aprova\u00e7\u00f5es da hist\u00f3ria do programa BNDES Fundo Clima, de 2013 a 2023 (R$ 3 bilh\u00f5es, a valores de hoje). Ao todo, o banco aprovou este ano R$ 7,3 bilh\u00f5es, ou 70% do total do programa aportado pela Uni\u00e3o ao banco, em abril (R$ 10,4 bilh\u00f5es).<\/p>\n<p>Vinculado ao\u00a0<strong>Minist\u00e9rio do Meio Ambiente e Mudan\u00e7a do Clima (MMA)<\/strong>\u00a0e gerido pelo BNDES, o Fundo \u00e9 um dos instrumentos da Pol\u00edtica Nacional sobre Mudan\u00e7a do Clima do Governo Federal. O BNDES ainda tem R$ 2,7 bilh\u00f5es em opera\u00e7\u00f5es do Fundo Clima a serem deliberadas pelas al\u00e7adas do banco neste ano. J\u00e1 a demanda apresentada para o or\u00e7amento do Fundo Clima de 2025 somam cerca de R$ 11,5 bilh\u00f5es, informou o banco.<\/p>\n<p>\u201cO BNDES est\u00e1 empenhado integralmente na indu\u00e7\u00e3o do desenvolvimento sustent\u00e1vel e na mitiga\u00e7\u00e3o dos efeitos clim\u00e1ticos, prioridades no governo do presidente Lula. Foram R$ 7,3 bilh\u00f5es aprovados para energia e\u00f3lica, solar e biog\u00e1s, mobilidade urbana, eletrifica\u00e7\u00e3o de frota de \u00f4nibus, VLT, al\u00e9m de financiamentos \u00e0 ind\u00fastria verde e a projetos de florestas nativas. Tudo isso com a gera\u00e7\u00e3o de mais de 15 mil empregos verdes\u201d, disse em nota o presidente do BNDES,\u00a0<strong>Aloizio Mercadante<\/strong>.<\/p>\n<p>Segundo Mercadante, a demanda de R$ 167 bilh\u00f5es para projetos de produ\u00e7\u00e3o de combust\u00edveis sustent\u00e1veis d\u00e3o a medida do potencial do mercado e da oportunidade do Brasil em liderar o processo global de descarboniza\u00e7\u00e3o. \u201cSomos l\u00edderes globais da agenda de biocombust\u00edveis h\u00e1 mais de 50 anos e a demanda para entrarmos nos combust\u00edveis sustent\u00e1veis est\u00e1 muito forte. Por isso, precisamos, pelo menos, dobrar os recursos do Fundo Clima, como j\u00e1 est\u00e1 previsto no or\u00e7amento do ano que vem\u201d, afirmou.<\/p>\n<h3 id=\"emissoes\" class=\"wp-block-heading\">Emiss\u00f5es<\/h3>\n<p>Os recursos do Fundo s\u00e3o destinados a projetos de desenvolvimento urbano sustent\u00e1vel, transi\u00e7\u00e3o energ\u00e9tica (como energia solar e biocombust\u00edveis), eletrifica\u00e7\u00e3o da frota p\u00fablica de \u00f4nibus, transporte hidrovi\u00e1rio e investimentos verdes relacionados \u00e0 ind\u00fastria.<\/p>\n<p>As opera\u00e7\u00f5es aprovadas de abril a outubro evitam ou removem 3,3 milh\u00f5es de toneladas de CO2-equivalente por ano, o que representa 16 vezes o total de emiss\u00f5es evitadas em 2023 (204 mil toneladas de CO2 equivalente\/ano). Esses valores representam cerca de 63% de emiss\u00f5es para os voos dom\u00e9sticos brasileiros e 79% das emiss\u00f5es das motocicletas brasileiras.<\/p>\n<p>De acordo com o BNDES, ao apresentar um salto nas aprova\u00e7\u00f5es dos recursos, o Fundo Clima tamb\u00e9m multiplicou a gera\u00e7\u00e3o de empregos verdes. As opera\u00e7\u00f5es aprovadas neste ano, at\u00e9 o m\u00eas passado, geraram 15,2 mil empregos permanentes, cerca de 20 vezes os 753 postos de trabalho criados pelas opera\u00e7\u00f5es de 2023.<\/p>\n<p>Al\u00e9m de elevar a escala, o Fundo Clima ampliou seu alcance nas regi\u00f5es Norte e Nordeste, disse o BNDES. No Nordeste, o valor aprovado nestes sete meses foi 19 vezes maior que as aprova\u00e7\u00f5es de 2022: foi R$ 1 bilh\u00e3o em 2024, ante R$ 51 milh\u00f5es em 2022.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fonte: Estad\u00e3o Data: 12\/11\/2024 O Banco Nacional de Desenvolvimento Econ\u00f4mico e Social (BNDES)\u00a0aprovou em sete meses (de abril a outubro), o correspondente a duas vezes e meia todas as aprova\u00e7\u00f5es da hist\u00f3ria do programa BNDES Fundo Clima, de 2013 a 2023 (R$ 3 bilh\u00f5es, a valores de hoje). Ao todo, o banco aprovou este ano [&hellip;]<\/p>\n","protected":false},"author":55,"featured_media":52593,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[875],"tags":[],"class_list":["post-85003","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-do-mercado"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Fundo Clima, do BNDES, aprova em 7 meses 2,5 vezes o valor liberado nos \u00faltimos 11 anos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/abifer.org.br\/fundo-clima-do-bndes-aprova-em-7-meses-25-vezes-o-valor-liberado-nos-ultimos-11-anos\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fundo Clima, do BNDES, aprova em 7 meses 2,5 vezes o valor liberado nos \u00faltimos 11 anos\" \/>\n<meta property=\"og:description\" content=\"Fonte: Estad\u00e3o Data: 12\/11\/2024 O Banco Nacional de Desenvolvimento Econ\u00f4mico e Social (BNDES)\u00a0aprovou em sete meses (de abril a outubro), o correspondente a duas vezes e meia todas as aprova\u00e7\u00f5es da hist\u00f3ria do programa BNDES Fundo Clima, de 2013 a 2023 (R$ 3 bilh\u00f5es, a valores de hoje). Ao todo, o banco aprovou este ano [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/abifer.org.br\/en\/fundo-clima-do-bndes-aprova-em-7-meses-25-vezes-o-valor-liberado-nos-ultimos-11-anos\/\" \/>\n<meta property=\"og:site_name\" content=\"ABIFER\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/abiferoficial\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-11-14T21:34:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/abifer.org.br\/wp-content\/uploads\/2021\/11\/abifer-logomarca-novembro-azul.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1544\" \/>\n\t<meta property=\"og:image:height\" content=\"512\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@abiferoficial\" \/>\n<meta name=\"twitter:site\" content=\"@abiferoficial\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"ABIFER\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/abifer.org.br\/en\/#organization\",\"name\":\"ABIFER\",\"url\":\"https:\/\/abifer.org.br\/en\/\",\"sameAs\":[\"https:\/\/www.facebook.com\/abiferoficial\/\",\"https:\/\/www.linkedin.com\/company\/abiferoficial\/\",\"https:\/\/twitter.com\/abiferoficial\"],\"logo\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/abifer.org.br\/en\/#logo\",\"inLanguage\":\"pt-BR\",\"url\":\"https:\/\/abifer.org.br\/wp-content\/uploads\/2018\/05\/ABF_001_LogoSlogan.jpg\",\"contentUrl\":\"https:\/\/abifer.org.br\/wp-content\/uploads\/2018\/05\/ABF_001_LogoSlogan.jpg\",\"width\":1182,\"height\":486,\"caption\":\"ABIFER\"},\"image\":{\"@id\":\"https:\/\/abifer.org.br\/en\/#logo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/abifer.org.br\/en\/#website\",\"url\":\"https:\/\/abifer.org.br\/en\/\",\"name\":\"ABIFER\",\"description\":\"Associa\u00e7\u00e3o Brasileira da Ind\u00fastria Ferrovi\u00e1ria\",\"publisher\":{\"@id\":\"https:\/\/abifer.org.br\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/abifer.org.br\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/abifer.org.br\/en\/fundo-clima-do-bndes-aprova-em-7-meses-25-vezes-o-valor-liberado-nos-ultimos-11-anos\/#primaryimage\",\"inLanguage\":\"pt-BR\",\"url\":\"https:\/\/abifer.org.br\/wp-content\/uploads\/2021\/11\/abifer-logomarca-novembro-azul.png\",\"contentUrl\":\"https:\/\/abifer.org.br\/wp-content\/uploads\/2021\/11\/abifer-logomarca-novembro-azul.png\",\"width\":1544,\"height\":512},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/abifer.org.br\/en\/fundo-clima-do-bndes-aprova-em-7-meses-25-vezes-o-valor-liberado-nos-ultimos-11-anos\/#webpage\",\"url\":\"https:\/\/abifer.org.br\/en\/fundo-clima-do-bndes-aprova-em-7-meses-25-vezes-o-valor-liberado-nos-ultimos-11-anos\/\",\"name\":\"Fundo Clima, do BNDES, aprova em 7 meses 2,5 vezes o valor liberado nos \u00faltimos 11 anos\",\"isPartOf\":{\"@id\":\"https:\/\/abifer.org.br\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/abifer.org.br\/en\/fundo-clima-do-bndes-aprova-em-7-meses-25-vezes-o-valor-liberado-nos-ultimos-11-anos\/#primaryimage\"},\"datePublished\":\"2024-11-14T21:34:11+00:00\",\"dateModified\":\"2024-11-14T21:34:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/abifer.org.br\/en\/fundo-clima-do-bndes-aprova-em-7-meses-25-vezes-o-valor-liberado-nos-ultimos-11-anos\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/abifer.org.br\/en\/fundo-clima-do-bndes-aprova-em-7-meses-25-vezes-o-valor-liberado-nos-ultimos-11-anos\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/abifer.org.br\/en\/fundo-clima-do-bndes-aprova-em-7-meses-25-vezes-o-valor-liberado-nos-ultimos-11-anos\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/abifer.org.br\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fundo Clima, do BNDES, aprova em 7 meses 2,5 vezes o valor liberado nos \u00faltimos 11 anos\"}]},{\"@type\":\"Article\",\"@id\":\"https:\/\/abifer.org.br\/en\/fundo-clima-do-bndes-aprova-em-7-meses-25-vezes-o-valor-liberado-nos-ultimos-11-anos\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/abifer.org.br\/en\/fundo-clima-do-bndes-aprova-em-7-meses-25-vezes-o-valor-liberado-nos-ultimos-11-anos\/#webpage\"},\"author\":{\"@id\":\"https:\/\/abifer.org.br\/en\/#\/schema\/person\/90c38c3286f60a11b363834930f79a1f\"},\"headline\":\"Fundo Clima, do BNDES, aprova em 7 meses 2,5 vezes o valor liberado nos \u00faltimos 11 anos\",\"datePublished\":\"2024-11-14T21:34:11+00:00\",\"dateModified\":\"2024-11-14T21:34:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/abifer.org.br\/en\/fundo-clima-do-bndes-aprova-em-7-meses-25-vezes-o-valor-liberado-nos-ultimos-11-anos\/#webpage\"},\"wordCount\":535,\"publisher\":{\"@id\":\"https:\/\/abifer.org.br\/en\/#organization\"},\"image\":{\"@id\":\"https:\/\/abifer.org.br\/en\/fundo-clima-do-bndes-aprova-em-7-meses-25-vezes-o-valor-liberado-nos-ultimos-11-anos\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/abifer.org.br\/wp-content\/uploads\/2021\/11\/abifer-logomarca-novembro-azul.png\",\"articleSection\":[\"Not\u00edcias do Mercado\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/abifer.org.br\/en\/#\/schema\/person\/90c38c3286f60a11b363834930f79a1f\",\"name\":\"ABIFER\",\"url\":\"https:\/\/abifer.org.br\/author\/abifer\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fundo Clima, do BNDES, aprova em 7 meses 2,5 vezes o valor liberado nos \u00faltimos 11 anos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/abifer.org.br\/fundo-clima-do-bndes-aprova-em-7-meses-25-vezes-o-valor-liberado-nos-ultimos-11-anos\/","og_locale":"pt_BR","og_type":"article","og_title":"Fundo Clima, do BNDES, aprova em 7 meses 2,5 vezes o valor liberado nos \u00faltimos 11 anos","og_description":"Fonte: Estad\u00e3o Data: 12\/11\/2024 O Banco Nacional de Desenvolvimento Econ\u00f4mico e Social (BNDES)\u00a0aprovou em sete meses (de abril a outubro), o correspondente a duas vezes e meia todas as aprova\u00e7\u00f5es da hist\u00f3ria do programa BNDES Fundo Clima, de 2013 a 2023 (R$ 3 bilh\u00f5es, a valores de hoje). Ao todo, o banco aprovou este ano [&hellip;]","og_url":"https:\/\/abifer.org.br\/en\/fundo-clima-do-bndes-aprova-em-7-meses-25-vezes-o-valor-liberado-nos-ultimos-11-anos\/","og_site_name":"ABIFER","article_publisher":"https:\/\/www.facebook.com\/abiferoficial\/","article_published_time":"2024-11-14T21:34:11+00:00","og_image":[{"width":1544,"height":512,"url":"https:\/\/abifer.org.br\/wp-content\/uploads\/2021\/11\/abifer-logomarca-novembro-azul.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_creator":"@abiferoficial","twitter_site":"@abiferoficial","twitter_misc":{"Escrito por":"ABIFER","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Organization","@id":"https:\/\/abifer.org.br\/en\/#organization","name":"ABIFER","url":"https:\/\/abifer.org.br\/en\/","sameAs":["https:\/\/www.facebook.com\/abiferoficial\/","https:\/\/www.linkedin.com\/company\/abiferoficial\/","https:\/\/twitter.com\/abiferoficial"],"logo":{"@type":"ImageObject","@id":"https:\/\/abifer.org.br\/en\/#logo","inLanguage":"pt-BR","url":"https:\/\/abifer.org.br\/wp-content\/uploads\/2018\/05\/ABF_001_LogoSlogan.jpg","contentUrl":"https:\/\/abifer.org.br\/wp-content\/uploads\/2018\/05\/ABF_001_LogoSlogan.jpg","width":1182,"height":486,"caption":"ABIFER"},"image":{"@id":"https:\/\/abifer.org.br\/en\/#logo"}},{"@type":"WebSite","@id":"https:\/\/abifer.org.br\/en\/#website","url":"https:\/\/abifer.org.br\/en\/","name":"ABIFER","description":"Associa\u00e7\u00e3o Brasileira da Ind\u00fastria Ferrovi\u00e1ria","publisher":{"@id":"https:\/\/abifer.org.br\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/abifer.org.br\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"ImageObject","@id":"https:\/\/abifer.org.br\/en\/fundo-clima-do-bndes-aprova-em-7-meses-25-vezes-o-valor-liberado-nos-ultimos-11-anos\/#primaryimage","inLanguage":"pt-BR","url":"https:\/\/abifer.org.br\/wp-content\/uploads\/2021\/11\/abifer-logomarca-novembro-azul.png","contentUrl":"https:\/\/abifer.org.br\/wp-content\/uploads\/2021\/11\/abifer-logomarca-novembro-azul.png","width":1544,"height":512},{"@type":"WebPage","@id":"https:\/\/abifer.org.br\/en\/fundo-clima-do-bndes-aprova-em-7-meses-25-vezes-o-valor-liberado-nos-ultimos-11-anos\/#webpage","url":"https:\/\/abifer.org.br\/en\/fundo-clima-do-bndes-aprova-em-7-meses-25-vezes-o-valor-liberado-nos-ultimos-11-anos\/","name":"Fundo Clima, do BNDES, aprova em 7 meses 2,5 vezes o valor liberado nos \u00faltimos 11 anos","isPartOf":{"@id":"https:\/\/abifer.org.br\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/abifer.org.br\/en\/fundo-clima-do-bndes-aprova-em-7-meses-25-vezes-o-valor-liberado-nos-ultimos-11-anos\/#primaryimage"},"datePublished":"2024-11-14T21:34:11+00:00","dateModified":"2024-11-14T21:34:11+00:00","breadcrumb":{"@id":"https:\/\/abifer.org.br\/en\/fundo-clima-do-bndes-aprova-em-7-meses-25-vezes-o-valor-liberado-nos-ultimos-11-anos\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/abifer.org.br\/en\/fundo-clima-do-bndes-aprova-em-7-meses-25-vezes-o-valor-liberado-nos-ultimos-11-anos\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/abifer.org.br\/en\/fundo-clima-do-bndes-aprova-em-7-meses-25-vezes-o-valor-liberado-nos-ultimos-11-anos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/abifer.org.br\/en\/"},{"@type":"ListItem","position":2,"name":"Fundo Clima, do BNDES, aprova em 7 meses 2,5 vezes o valor liberado nos \u00faltimos 11 anos"}]},{"@type":"Article","@id":"https:\/\/abifer.org.br\/en\/fundo-clima-do-bndes-aprova-em-7-meses-25-vezes-o-valor-liberado-nos-ultimos-11-anos\/#article","isPartOf":{"@id":"https:\/\/abifer.org.br\/en\/fundo-clima-do-bndes-aprova-em-7-meses-25-vezes-o-valor-liberado-nos-ultimos-11-anos\/#webpage"},"author":{"@id":"https:\/\/abifer.org.br\/en\/#\/schema\/person\/90c38c3286f60a11b363834930f79a1f"},"headline":"Fundo Clima, do BNDES, aprova em 7 meses 2,5 vezes o valor liberado nos \u00faltimos 11 anos","datePublished":"2024-11-14T21:34:11+00:00","dateModified":"2024-11-14T21:34:11+00:00","mainEntityOfPage":{"@id":"https:\/\/abifer.org.br\/en\/fundo-clima-do-bndes-aprova-em-7-meses-25-vezes-o-valor-liberado-nos-ultimos-11-anos\/#webpage"},"wordCount":535,"publisher":{"@id":"https:\/\/abifer.org.br\/en\/#organization"},"image":{"@id":"https:\/\/abifer.org.br\/en\/fundo-clima-do-bndes-aprova-em-7-meses-25-vezes-o-valor-liberado-nos-ultimos-11-anos\/#primaryimage"},"thumbnailUrl":"https:\/\/abifer.org.br\/wp-content\/uploads\/2021\/11\/abifer-logomarca-novembro-azul.png","articleSection":["Not\u00edcias do Mercado"],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/abifer.org.br\/en\/#\/schema\/person\/90c38c3286f60a11b363834930f79a1f","name":"ABIFER","url":"https:\/\/abifer.org.br\/author\/abifer\/"}]}},"_links":{"self":[{"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/posts\/85003\/"}],"collection":[{"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/posts\/"}],"about":[{"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/types\/post\/"}],"author":[{"embeddable":true,"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/users\/55\/"}],"replies":[{"embeddable":true,"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/comments\/?post=85003"}],"version-history":[{"count":1,"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/posts\/85003\/revisions\/"}],"predecessor-version":[{"id":85006,"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/posts\/85003\/revisions\/85006\/"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/media\/52593\/"}],"wp:attachment":[{"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/media\/?parent=85003"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/categories\/?post=85003"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/tags\/?post=85003"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}