{"id":85285,"date":"2024-11-28T11:01:13","date_gmt":"2024-11-28T14:01:13","guid":{"rendered":"https:\/\/abifer.org.br\/?p=85285"},"modified":"2024-11-28T11:01:13","modified_gmt":"2024-11-28T14:01:13","slug":"com-aporte-de-r-40-bilhoes-quatro-projetos-de-hidrogenio-verde-devem-sair-do-papel-em-2025","status":"publish","type":"post","link":"https:\/\/abifer.org.br\/en\/com-aporte-de-r-40-bilhoes-quatro-projetos-de-hidrogenio-verde-devem-sair-do-papel-em-2025\/","title":{"rendered":"Com aporte de R$ 40 bilh\u00f5es, quatro projetos de hidrog\u00eanio verde devem sair do papel em 2025"},"content":{"rendered":"<pre style=\"text-align: right;\"><strong><em>Fonte: Valor<\/em><\/strong><\/pre>\n<p>Pelo menos quatro projetos para produ\u00e7\u00e3o de hidrog\u00eanio de baixa ou zero emiss\u00e3o de carbono (hidrog\u00eanio verde ou H2V) podem sair do papel a partir de 2025 no Brasil. O Nordeste concentra tr\u00eas desses futuros investimentos, que somam R$ 34 bilh\u00f5es de um aporte que pode chegar a quase R$ 40 bilh\u00f5es, se todas as iniciativas no pa\u00eds forem levadas adiante.<\/p>\n<p>A multinacional australiana Fortescue e a Casa dos Ventos, junto com a TotalEnergies, devem construir sua base no Porto de Pec\u00e9m (CE). Os outros dois est\u00e3o previstos para ser implementados em Pernambuco e Minas Gerais.<\/p>\n<p>Entre projetos anunciados e em estudo, o pa\u00eds j\u00e1 possui mais de 60 iniciativas no setor de hidrog\u00eanio verde, mas ainda h\u00e1 pouca tra\u00e7\u00e3o para escalar de vez. Na pr\u00e1tica, h\u00e1 hoje programas de baixa escala, de acordo com a Associa\u00e7\u00e3o Brasileira de Hidrog\u00eanio Verde (ABIHV).<\/p>\n<p>\u201cO que temos em opera\u00e7\u00e3o s\u00e3o projetos de pesquisa e desenvolvimento em universidades e que s\u00e3o muito pequenos, que n\u00e3o t\u00eam capacidade de produ\u00e7\u00e3o comercial\u201d, diz Fernanda Delgado, presidente da ABIHV.<\/p>\n<p>Ap\u00f3s as san\u00e7\u00f5es das leis que garantiram o marco legal do hidrog\u00eanio de baixa emiss\u00e3o de carbono, e preveem incentivos fiscais com o intuito de fomentar os investimentos na \u00e1rea, segundo a presidente da ABIHV, o H2V tem potencial de impactar o Produto Interno Bruto (PIB) brasileiro em aproximadamente R$ 7 trilh\u00f5es, considerando que o Brasil atenda a 4% da fatia da demanda internacional.<\/p>\n<p>H\u00e1 quatro anos, o mercado praticamente n\u00e3o existia ou era muito pequeno, na vis\u00e3o do gerente nacional da Fortescue no Brasil, Luis Viga. Segundo ele, as empresas ainda estavam pensando que o hidrog\u00eanio verde era algo para o futuro e, hoje, j\u00e1 \u00e9 poss\u00edvel ver mais movimentos do setor no pa\u00eds.<\/p>\n<p>\u201c[O mercado ainda] n\u00e3o est\u00e1 100% amadurecido, mas est\u00e1 caminhando a passos largos para ter essas decis\u00f5es de investimentos. Uma vez decidido, n\u00e3o tem mais volta. S\u00e3o v\u00e1rias pe\u00e7as de um quebra-cabe\u00e7a que v\u00e3o se encaixando e a\u00ed voc\u00ea come\u00e7a a ter possibilidades. Se as coisas ocorrerem bem, depender\u00e1 de como est\u00e1 o mercado global. A\u00ed, entra a regulamenta\u00e7\u00e3o e o Brasil tem que entrar nos incentivos para reduzir o \u2018gap\u2019 entre o hidrog\u00eanio verde e o cinza\u201d, diz.<\/p>\n<p>Para tomar uma decis\u00e3o de investimento e alavancar o hidrog\u00eanio verde em 2025, segundo Viga, seria importante ter iniciado neste ano o projeto de engenharia. Como as plantas s\u00e3o grandes, ele explica que o processo para se organizar um planejamento de H2V demanda prazo. Neste momento, o projeto da Fortescue no Cear\u00e1 est\u00e1 come\u00e7ando a terraplenagem para logo depois iniciar as constru\u00e7\u00f5es. O volume de produ\u00e7\u00e3o anual de H2V da empresa, ap\u00f3s a conclus\u00e3o do projeto, ser\u00e1 de 175 mil toneladas.<\/p>\n<p>\u201cNo mundo inteiro \u00e9 poss\u00edvel ver que o mercado de hidrog\u00eanio verde est\u00e1 andando para escalonar para uma produ\u00e7\u00e3o comercial maior, e \u00e9 poss\u00edvel ver que a regulamenta\u00e7\u00e3o vai se desenvolvendo e vai criando condi\u00e7\u00f5es n\u00e3o s\u00f3 aqui, mas tamb\u00e9m no mundo para ter esse mercado. Para se ter uma ideia, estamos h\u00e1 quase tr\u00eas anos fazendo engenharia nisso. Ent\u00e3o, n\u00e3o \u00e9 um processo qualquer, s\u00e3o plantas muito grandes e com muito investimento. N\u00e3o \u00e9 algo que voc\u00ea come\u00e7a do nada. Diferente quando voc\u00ea est\u00e1 fazendo pesquisa e desenvolvimento, que a\u00ed \u00e9 outra hist\u00f3ria\u201d, afirma.<\/p>\n<p>A Casa dos Ventos, associada \u00e0 TotalEnergies, que tamb\u00e9m trabalha no projeto no complexo de Pec\u00e9m, ter\u00e1 um volume ainda maior do que a produ\u00e7\u00e3o da Fortescue, atingindo 900 mil toneladas ao ano. A empresa n\u00e3o quis dar entrevista.<\/p>\n<p>Segundo Markus Francke, diretor da H2 Brasil, os projetos de pesquisa e desenvolvimento s\u00e3o importantes para desenvolver m\u00e3o de obra especializada num setor que ir\u00e1 abastecer futuramente essas grandes f\u00e1bricas, que tem como foco uma escala de gera\u00e7\u00e3o comercial maior. Com uma planta de produ\u00e7\u00e3o de hidrog\u00eanio verde estabelecida na Universidade Federal de Itajub\u00e1 (Unifei), em Minas Gerais, implementada em parceria com a H2 Brasil e a Ag\u00eancia Alem\u00e3 para Coopera\u00e7\u00e3o Internacional (GIZ), atrelada ao centro de pesquisas de H2V da universidade, o projeto ter\u00e1 capacidade de produ\u00e7\u00e3o de hidrog\u00eanio verde a uma taxa de 60 normal metro c\u00fabico por hora (Nm\u00b3\/h).<\/p>\n<p>\u201c\u00c9 um produto novo e parte da tecnologia tamb\u00e9m \u00e9 nova, ent\u00e3o, precisamos de engenheiros e de professores nas universidades que sabem ensinar isto e que sabem como tratar esse novo tema. \u00c9 algo fundamental toda essa pesquisa e a capacita\u00e7\u00e3o dessas pessoas. Para as plantas de hidrog\u00eanio verde funcionarem, \u00e9 preciso pessoas que trabalhem nela e teremos que primeiro educar. Portanto, \u00e9 necess\u00e1rio tempo\u201d, diz.<\/p>\n<p>Al\u00e9m da m\u00e3o de obra que ainda \u00e9 necess\u00e1ria para escalar o mercado, uma das barreiras que impedem o H2V de avan\u00e7ar segundo a coordenadora do Laborat\u00f3rio de Transportes Sustent\u00e1veis (LabTS) da Coppe, ligado \u00e0 planta de hidrog\u00eanio verde da Universidade Federal do Rio de Janeiro (UFRJ), Andrea Santos, s\u00e3o as limita\u00e7\u00f5es financeiras, tecnol\u00f3gicas e falta de capacidade e assist\u00eancia t\u00e9cnica para o mercado. Na vis\u00e3o da professora, a baixa oferta de equipamentos e capacita\u00e7\u00e3o tamb\u00e9m s\u00e3o um problema.<\/p>\n<p>\u201cAlguns s\u00f3 querem vender a tecnologia e os eletrolisadores. Existe grande possibilidade de o mercado decolar em algum momento, mas, na minha opini\u00e3o, ainda est\u00e1 longe disso. No futuro, de fato, o Brasil ser\u00e1 um grande produtor de H2V de baixa emiss\u00e3o de carbono e ter\u00e1 mercado competitivo pela perspectiva de conseguirmos produzir em custos mais baixos e poderemos suprir algo em torno de 10% da demanda internacional\u201d, diz a pesquisadora.<\/p>\n<p>Em termos globais, diversos pa\u00edses j\u00e1 adotaram ou est\u00e3o implementando pol\u00edticas p\u00fablicas de incentivo \u00e0 produ\u00e7\u00e3o de hidrog\u00eanio de baixo carbono. Entre os segmentos industriais que est\u00e3o investindo no tema no Brasil, o setor de gera\u00e7\u00e3o el\u00e9trica lidera com 42 projetos. A maioria deles, conforme a Confedera\u00e7\u00e3o Nacional da Ind\u00fastria (CNI), \u00e9 voltada para exporta\u00e7\u00e3o. Dependendo da aplica\u00e7\u00e3o a que se refere, o H2V poder\u00e1 ser competitivo, segundo o CEO da thyssenkrupp na Am\u00e9rica Latina, Paulo Alvarenga.<\/p>\n<p>\u201cAcho que existe, naturalmente, um mercado l\u00e1 fora que tamb\u00e9m vai ficar vi\u00e1vel. O mercado brasileiro est\u00e1 nesse momento, em um pouco daquilo que acontece no mundo, tem projetos que est\u00e3o um pouco mais avan\u00e7ados e um pouco menos avan\u00e7ados. De maneira geral, tem muito estudo para poder identificar os primeiros projetos e no caso espec\u00edfico do Brasil e Estados Unidos aguarda-se clareza do aspecto regulat\u00f3rio. O Brasil publicou as leis que d\u00e3o, inclusive, os subs\u00eddios. Os investidores est\u00e3o todos avaliando como \u00e9 que vai ser a regulamenta\u00e7\u00e3o. Essa \u00e9 minha vis\u00e3o sobre o mercado de H2V hoje\u201d, destaca.<\/p>\n<p>A fabrica\u00e7\u00e3o dos eletrolisadores, essencial para a produ\u00e7\u00e3o do hidrog\u00eanio, segundo o CEO, est\u00e1 avan\u00e7ada. \u201cA thyssenkrupp \u00e9 l\u00edder do mercado e temos hoje uma capacidade global de produzir efetivamente mais ou menos tr\u00eas gigawatts de eletrolisadores por ano e devemos chegar at\u00e9 o final do ano que vem at\u00e9 cinco gigawatts de capacidade por ano. Isso \u00e9 uma capacidade global, ent\u00e3o, como a gente n\u00e3o est\u00e1 fazendo isso no Brasil no momento, essa seria a capacidade nossa de fornecimento a n\u00edvel global e eu espero que uma parcela relevante disso pudesse vir ao Brasil\u201d, afirma.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fonte: Valor Pelo menos quatro projetos para produ\u00e7\u00e3o de hidrog\u00eanio de baixa ou zero emiss\u00e3o de carbono (hidrog\u00eanio verde ou H2V) podem sair do papel a partir de 2025 no Brasil. O Nordeste concentra tr\u00eas desses futuros investimentos, que somam R$ 34 bilh\u00f5es de um aporte que pode chegar a quase R$ 40 bilh\u00f5es, se [&hellip;]<\/p>\n","protected":false},"author":55,"featured_media":85286,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[875],"tags":[],"class_list":["post-85285","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-do-mercado"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Com aporte de R$ 40 bilh\u00f5es, quatro projetos de hidrog\u00eanio verde devem sair do papel em 2025<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/abifer.org.br\/com-aporte-de-r-40-bilhoes-quatro-projetos-de-hidrogenio-verde-devem-sair-do-papel-em-2025\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Com aporte de R$ 40 bilh\u00f5es, quatro projetos de hidrog\u00eanio verde devem sair do papel em 2025\" \/>\n<meta property=\"og:description\" content=\"Fonte: Valor Pelo menos quatro projetos para produ\u00e7\u00e3o de hidrog\u00eanio de baixa ou zero emiss\u00e3o de carbono (hidrog\u00eanio verde ou H2V) podem sair do papel a partir de 2025 no Brasil. O Nordeste concentra tr\u00eas desses futuros investimentos, que somam R$ 34 bilh\u00f5es de um aporte que pode chegar a quase R$ 40 bilh\u00f5es, se [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"http:\/\/abifer.org.br\/com-aporte-de-r-40-bilhoes-quatro-projetos-de-hidrogenio-verde-devem-sair-do-papel-em-2025\/\" \/>\n<meta property=\"og:site_name\" content=\"ABIFER\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/abiferoficial\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-11-28T14:01:13+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/abifer.org.br\/wp-content\/uploads\/2024\/11\/Green-Hydrogen.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"2134\" \/>\n\t<meta property=\"og:image:height\" content=\"1404\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@abiferoficial\" \/>\n<meta name=\"twitter:site\" content=\"@abiferoficial\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"ABIFER\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/abifer.org.br\/en\/#organization\",\"name\":\"ABIFER\",\"url\":\"https:\/\/abifer.org.br\/en\/\",\"sameAs\":[\"https:\/\/www.facebook.com\/abiferoficial\/\",\"https:\/\/www.linkedin.com\/company\/abiferoficial\/\",\"https:\/\/twitter.com\/abiferoficial\"],\"logo\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/abifer.org.br\/en\/#logo\",\"inLanguage\":\"pt-BR\",\"url\":\"https:\/\/abifer.org.br\/wp-content\/uploads\/2018\/05\/ABF_001_LogoSlogan.jpg\",\"contentUrl\":\"https:\/\/abifer.org.br\/wp-content\/uploads\/2018\/05\/ABF_001_LogoSlogan.jpg\",\"width\":1182,\"height\":486,\"caption\":\"ABIFER\"},\"image\":{\"@id\":\"https:\/\/abifer.org.br\/en\/#logo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/abifer.org.br\/en\/#website\",\"url\":\"https:\/\/abifer.org.br\/en\/\",\"name\":\"ABIFER\",\"description\":\"Associa\u00e7\u00e3o Brasileira da Ind\u00fastria Ferrovi\u00e1ria\",\"publisher\":{\"@id\":\"https:\/\/abifer.org.br\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/abifer.org.br\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"ImageObject\",\"@id\":\"http:\/\/abifer.org.br\/com-aporte-de-r-40-bilhoes-quatro-projetos-de-hidrogenio-verde-devem-sair-do-papel-em-2025\/#primaryimage\",\"inLanguage\":\"pt-BR\",\"url\":\"https:\/\/abifer.org.br\/wp-content\/uploads\/2024\/11\/Green-Hydrogen.jpeg\",\"contentUrl\":\"https:\/\/abifer.org.br\/wp-content\/uploads\/2024\/11\/Green-Hydrogen.jpeg\",\"width\":2134,\"height\":1404,\"caption\":\"Eco friendly clean hydrogen energy concept. 3d rendering of hydrogen icon on fresh spring meadow with blue sky in background.\"},{\"@type\":\"WebPage\",\"@id\":\"http:\/\/abifer.org.br\/com-aporte-de-r-40-bilhoes-quatro-projetos-de-hidrogenio-verde-devem-sair-do-papel-em-2025\/#webpage\",\"url\":\"http:\/\/abifer.org.br\/com-aporte-de-r-40-bilhoes-quatro-projetos-de-hidrogenio-verde-devem-sair-do-papel-em-2025\/\",\"name\":\"Com aporte de R$ 40 bilh\u00f5es, quatro projetos de hidrog\u00eanio verde devem sair do papel em 2025\",\"isPartOf\":{\"@id\":\"https:\/\/abifer.org.br\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\/\/abifer.org.br\/com-aporte-de-r-40-bilhoes-quatro-projetos-de-hidrogenio-verde-devem-sair-do-papel-em-2025\/#primaryimage\"},\"datePublished\":\"2024-11-28T14:01:13+00:00\",\"dateModified\":\"2024-11-28T14:01:13+00:00\",\"breadcrumb\":{\"@id\":\"http:\/\/abifer.org.br\/com-aporte-de-r-40-bilhoes-quatro-projetos-de-hidrogenio-verde-devem-sair-do-papel-em-2025\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/abifer.org.br\/com-aporte-de-r-40-bilhoes-quatro-projetos-de-hidrogenio-verde-devem-sair-do-papel-em-2025\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/abifer.org.br\/com-aporte-de-r-40-bilhoes-quatro-projetos-de-hidrogenio-verde-devem-sair-do-papel-em-2025\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/abifer.org.br\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Com aporte de R$ 40 bilh\u00f5es, quatro projetos de hidrog\u00eanio verde devem sair do papel em 2025\"}]},{\"@type\":\"Article\",\"@id\":\"http:\/\/abifer.org.br\/com-aporte-de-r-40-bilhoes-quatro-projetos-de-hidrogenio-verde-devem-sair-do-papel-em-2025\/#article\",\"isPartOf\":{\"@id\":\"http:\/\/abifer.org.br\/com-aporte-de-r-40-bilhoes-quatro-projetos-de-hidrogenio-verde-devem-sair-do-papel-em-2025\/#webpage\"},\"author\":{\"@id\":\"https:\/\/abifer.org.br\/en\/#\/schema\/person\/90c38c3286f60a11b363834930f79a1f\"},\"headline\":\"Com aporte de R$ 40 bilh\u00f5es, quatro projetos de hidrog\u00eanio verde devem sair do papel em 2025\",\"datePublished\":\"2024-11-28T14:01:13+00:00\",\"dateModified\":\"2024-11-28T14:01:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\/\/abifer.org.br\/com-aporte-de-r-40-bilhoes-quatro-projetos-de-hidrogenio-verde-devem-sair-do-papel-em-2025\/#webpage\"},\"wordCount\":1305,\"publisher\":{\"@id\":\"https:\/\/abifer.org.br\/en\/#organization\"},\"image\":{\"@id\":\"http:\/\/abifer.org.br\/com-aporte-de-r-40-bilhoes-quatro-projetos-de-hidrogenio-verde-devem-sair-do-papel-em-2025\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/abifer.org.br\/wp-content\/uploads\/2024\/11\/Green-Hydrogen.jpeg\",\"articleSection\":[\"Not\u00edcias do Mercado\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/abifer.org.br\/en\/#\/schema\/person\/90c38c3286f60a11b363834930f79a1f\",\"name\":\"ABIFER\",\"url\":\"https:\/\/abifer.org.br\/author\/abifer\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Com aporte de R$ 40 bilh\u00f5es, quatro projetos de hidrog\u00eanio verde devem sair do papel em 2025","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/abifer.org.br\/com-aporte-de-r-40-bilhoes-quatro-projetos-de-hidrogenio-verde-devem-sair-do-papel-em-2025\/","og_locale":"pt_BR","og_type":"article","og_title":"Com aporte de R$ 40 bilh\u00f5es, quatro projetos de hidrog\u00eanio verde devem sair do papel em 2025","og_description":"Fonte: Valor Pelo menos quatro projetos para produ\u00e7\u00e3o de hidrog\u00eanio de baixa ou zero emiss\u00e3o de carbono (hidrog\u00eanio verde ou H2V) podem sair do papel a partir de 2025 no Brasil. O Nordeste concentra tr\u00eas desses futuros investimentos, que somam R$ 34 bilh\u00f5es de um aporte que pode chegar a quase R$ 40 bilh\u00f5es, se [&hellip;]","og_url":"http:\/\/abifer.org.br\/com-aporte-de-r-40-bilhoes-quatro-projetos-de-hidrogenio-verde-devem-sair-do-papel-em-2025\/","og_site_name":"ABIFER","article_publisher":"https:\/\/www.facebook.com\/abiferoficial\/","article_published_time":"2024-11-28T14:01:13+00:00","og_image":[{"width":2134,"height":1404,"url":"http:\/\/abifer.org.br\/wp-content\/uploads\/2024\/11\/Green-Hydrogen.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_creator":"@abiferoficial","twitter_site":"@abiferoficial","twitter_misc":{"Escrito por":"ABIFER","Est. tempo de leitura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Organization","@id":"https:\/\/abifer.org.br\/en\/#organization","name":"ABIFER","url":"https:\/\/abifer.org.br\/en\/","sameAs":["https:\/\/www.facebook.com\/abiferoficial\/","https:\/\/www.linkedin.com\/company\/abiferoficial\/","https:\/\/twitter.com\/abiferoficial"],"logo":{"@type":"ImageObject","@id":"https:\/\/abifer.org.br\/en\/#logo","inLanguage":"pt-BR","url":"https:\/\/abifer.org.br\/wp-content\/uploads\/2018\/05\/ABF_001_LogoSlogan.jpg","contentUrl":"https:\/\/abifer.org.br\/wp-content\/uploads\/2018\/05\/ABF_001_LogoSlogan.jpg","width":1182,"height":486,"caption":"ABIFER"},"image":{"@id":"https:\/\/abifer.org.br\/en\/#logo"}},{"@type":"WebSite","@id":"https:\/\/abifer.org.br\/en\/#website","url":"https:\/\/abifer.org.br\/en\/","name":"ABIFER","description":"Associa\u00e7\u00e3o Brasileira da Ind\u00fastria Ferrovi\u00e1ria","publisher":{"@id":"https:\/\/abifer.org.br\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/abifer.org.br\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"ImageObject","@id":"http:\/\/abifer.org.br\/com-aporte-de-r-40-bilhoes-quatro-projetos-de-hidrogenio-verde-devem-sair-do-papel-em-2025\/#primaryimage","inLanguage":"pt-BR","url":"https:\/\/abifer.org.br\/wp-content\/uploads\/2024\/11\/Green-Hydrogen.jpeg","contentUrl":"https:\/\/abifer.org.br\/wp-content\/uploads\/2024\/11\/Green-Hydrogen.jpeg","width":2134,"height":1404,"caption":"Eco friendly clean hydrogen energy concept. 3d rendering of hydrogen icon on fresh spring meadow with blue sky in background."},{"@type":"WebPage","@id":"http:\/\/abifer.org.br\/com-aporte-de-r-40-bilhoes-quatro-projetos-de-hidrogenio-verde-devem-sair-do-papel-em-2025\/#webpage","url":"http:\/\/abifer.org.br\/com-aporte-de-r-40-bilhoes-quatro-projetos-de-hidrogenio-verde-devem-sair-do-papel-em-2025\/","name":"Com aporte de R$ 40 bilh\u00f5es, quatro projetos de hidrog\u00eanio verde devem sair do papel em 2025","isPartOf":{"@id":"https:\/\/abifer.org.br\/en\/#website"},"primaryImageOfPage":{"@id":"http:\/\/abifer.org.br\/com-aporte-de-r-40-bilhoes-quatro-projetos-de-hidrogenio-verde-devem-sair-do-papel-em-2025\/#primaryimage"},"datePublished":"2024-11-28T14:01:13+00:00","dateModified":"2024-11-28T14:01:13+00:00","breadcrumb":{"@id":"http:\/\/abifer.org.br\/com-aporte-de-r-40-bilhoes-quatro-projetos-de-hidrogenio-verde-devem-sair-do-papel-em-2025\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["http:\/\/abifer.org.br\/com-aporte-de-r-40-bilhoes-quatro-projetos-de-hidrogenio-verde-devem-sair-do-papel-em-2025\/"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/abifer.org.br\/com-aporte-de-r-40-bilhoes-quatro-projetos-de-hidrogenio-verde-devem-sair-do-papel-em-2025\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/abifer.org.br\/en\/"},{"@type":"ListItem","position":2,"name":"Com aporte de R$ 40 bilh\u00f5es, quatro projetos de hidrog\u00eanio verde devem sair do papel em 2025"}]},{"@type":"Article","@id":"http:\/\/abifer.org.br\/com-aporte-de-r-40-bilhoes-quatro-projetos-de-hidrogenio-verde-devem-sair-do-papel-em-2025\/#article","isPartOf":{"@id":"http:\/\/abifer.org.br\/com-aporte-de-r-40-bilhoes-quatro-projetos-de-hidrogenio-verde-devem-sair-do-papel-em-2025\/#webpage"},"author":{"@id":"https:\/\/abifer.org.br\/en\/#\/schema\/person\/90c38c3286f60a11b363834930f79a1f"},"headline":"Com aporte de R$ 40 bilh\u00f5es, quatro projetos de hidrog\u00eanio verde devem sair do papel em 2025","datePublished":"2024-11-28T14:01:13+00:00","dateModified":"2024-11-28T14:01:13+00:00","mainEntityOfPage":{"@id":"http:\/\/abifer.org.br\/com-aporte-de-r-40-bilhoes-quatro-projetos-de-hidrogenio-verde-devem-sair-do-papel-em-2025\/#webpage"},"wordCount":1305,"publisher":{"@id":"https:\/\/abifer.org.br\/en\/#organization"},"image":{"@id":"http:\/\/abifer.org.br\/com-aporte-de-r-40-bilhoes-quatro-projetos-de-hidrogenio-verde-devem-sair-do-papel-em-2025\/#primaryimage"},"thumbnailUrl":"https:\/\/abifer.org.br\/wp-content\/uploads\/2024\/11\/Green-Hydrogen.jpeg","articleSection":["Not\u00edcias do Mercado"],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/abifer.org.br\/en\/#\/schema\/person\/90c38c3286f60a11b363834930f79a1f","name":"ABIFER","url":"https:\/\/abifer.org.br\/author\/abifer\/"}]}},"_links":{"self":[{"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/posts\/85285\/"}],"collection":[{"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/posts\/"}],"about":[{"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/types\/post\/"}],"author":[{"embeddable":true,"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/users\/55\/"}],"replies":[{"embeddable":true,"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/comments\/?post=85285"}],"version-history":[{"count":1,"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/posts\/85285\/revisions\/"}],"predecessor-version":[{"id":85288,"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/posts\/85285\/revisions\/85288\/"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/media\/85286\/"}],"wp:attachment":[{"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/media\/?parent=85285"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/categories\/?post=85285"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/tags\/?post=85285"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}