{"id":86641,"date":"2025-02-04T10:53:34","date_gmt":"2025-02-04T13:53:34","guid":{"rendered":"https:\/\/abifer.org.br\/?p=86641"},"modified":"2025-02-04T10:53:34","modified_gmt":"2025-02-04T13:53:34","slug":"reforma-administrativa-de-tarcisio-reduz-em-29-os-cargos-no-metro-de-sp","status":"publish","type":"post","link":"https:\/\/abifer.org.br\/en\/reforma-administrativa-de-tarcisio-reduz-em-29-os-cargos-no-metro-de-sp\/","title":{"rendered":"Reforma administrativa de Tarc\u00edsio reduz em 29% os cargos no Metr\u00f4 de SP"},"content":{"rendered":"<pre style=\"text-align: right;\"><a href=\"https:\/\/veja.abril.com.br\/coluna\/radar\/reforma-administrativa-de-tarcisio-reduz-em-29-os-cargos-no-metro-de-sp\" target=\"_blank\" rel=\"noopener\"><strong><em>Fonte: Veja \r\nData: 29\/01\/2025<\/em><\/strong><\/a><\/pre>\n<p>Com a reforma administrativa aprovada no ano passado pelo governador Tarc\u00edsio de Freitas, a Companhia do Metropolitano reduziu em 29% o quadro de empregados do Metr\u00f4 de S\u00e3o Paulo.<\/p>\n<p>A institui\u00e7\u00e3o vai operar com 7.248 vagas ante as 10.224 autorizadas anteriormente. \u201cO corte est\u00e1 em linha com o plano S\u00e3o Paulo na Dire\u00e7\u00e3o Certa, que vem trabalhando para modernizar e tornar o Estado mais eficiente\u201d, diz a gest\u00e3o de Tarc\u00edsio.<\/p>\n<p>\u201cO novo n\u00famero j\u00e1 contempla as atuais necessidades da empresa, que tem alcan\u00e7ado metas expressivas na opera\u00e7\u00e3o da rede e expans\u00e3o da malha com o atual quadro preenchido de 6.195 contratados diretos\u201d, segue o governo.<\/p>\n<p>A reforma no Metr\u00f4 tamb\u00e9m reduziu em 21% os cargos em comiss\u00e3o e de livre provimento. Eram 918 vagas e agora s\u00e3o 722.<\/p>\n<p>\u201cDesde o in\u00edcio da atual gest\u00e3o, o Metr\u00f4 tem adotado diferentes medidas para qualificar o custeio, otimizar e reorganizar a estrutura da estatal. O n\u00famero de funcion\u00e1rios n\u00e3o concursados, por exemplo, foi reduzido em 33,7%, chegando a 101 empregados, que representam 1,6% do total de colaboradores diretos da empresa\u201d, diz o governo.<\/p>\n<p>O plano S\u00e3o Paulo Na Dire\u00e7\u00e3o Certa re\u00fane a\u00e7\u00f5es voltadas \u00e0 moderniza\u00e7\u00e3o da gest\u00e3o estadual e \u00e9 composto por eixos que passam pela expans\u00e3o dos investimentos, melhoria e efetividade do gasto, al\u00e9m da moderniza\u00e7\u00e3o da administra\u00e7\u00e3o p\u00fablica.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fonte: Veja Data: 29\/01\/2025 Com a reforma administrativa aprovada no ano passado pelo governador Tarc\u00edsio de Freitas, a Companhia do Metropolitano reduziu em 29% o quadro de empregados do Metr\u00f4 de S\u00e3o Paulo. A institui\u00e7\u00e3o vai operar com 7.248 vagas ante as 10.224 autorizadas anteriormente. \u201cO corte est\u00e1 em linha com o plano S\u00e3o Paulo [&hellip;]<\/p>\n","protected":false},"author":55,"featured_media":85903,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[875],"tags":[],"class_list":["post-86641","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-do-mercado"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Reforma administrativa de Tarc\u00edsio reduz em 29% os cargos no Metr\u00f4 de SP<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/abifer.org.br\/reforma-administrativa-de-tarcisio-reduz-em-29-os-cargos-no-metro-de-sp\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Reforma administrativa de Tarc\u00edsio reduz em 29% os cargos no Metr\u00f4 de SP\" \/>\n<meta property=\"og:description\" content=\"Fonte: Veja Data: 29\/01\/2025 Com a reforma administrativa aprovada no ano passado pelo governador Tarc\u00edsio de Freitas, a Companhia do Metropolitano reduziu em 29% o quadro de empregados do Metr\u00f4 de S\u00e3o Paulo. A institui\u00e7\u00e3o vai operar com 7.248 vagas ante as 10.224 autorizadas anteriormente. \u201cO corte est\u00e1 em linha com o plano S\u00e3o Paulo [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"http:\/\/abifer.org.br\/reforma-administrativa-de-tarcisio-reduz-em-29-os-cargos-no-metro-de-sp\/\" \/>\n<meta property=\"og:site_name\" content=\"ABIFER\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/abiferoficial\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-02-04T13:53:34+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/abifer.org.br\/wp-content\/uploads\/2025\/01\/debentures.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@abiferoficial\" \/>\n<meta name=\"twitter:site\" content=\"@abiferoficial\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"ABIFER\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/abifer.org.br\/en\/#organization\",\"name\":\"ABIFER\",\"url\":\"https:\/\/abifer.org.br\/en\/\",\"sameAs\":[\"https:\/\/www.facebook.com\/abiferoficial\/\",\"https:\/\/www.linkedin.com\/company\/abiferoficial\/\",\"https:\/\/twitter.com\/abiferoficial\"],\"logo\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/abifer.org.br\/en\/#logo\",\"inLanguage\":\"pt-BR\",\"url\":\"https:\/\/abifer.org.br\/wp-content\/uploads\/2018\/05\/ABF_001_LogoSlogan.jpg\",\"contentUrl\":\"https:\/\/abifer.org.br\/wp-content\/uploads\/2018\/05\/ABF_001_LogoSlogan.jpg\",\"width\":1182,\"height\":486,\"caption\":\"ABIFER\"},\"image\":{\"@id\":\"https:\/\/abifer.org.br\/en\/#logo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/abifer.org.br\/en\/#website\",\"url\":\"https:\/\/abifer.org.br\/en\/\",\"name\":\"ABIFER\",\"description\":\"Associa\u00e7\u00e3o Brasileira da Ind\u00fastria Ferrovi\u00e1ria\",\"publisher\":{\"@id\":\"https:\/\/abifer.org.br\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/abifer.org.br\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"ImageObject\",\"@id\":\"http:\/\/abifer.org.br\/reforma-administrativa-de-tarcisio-reduz-em-29-os-cargos-no-metro-de-sp\/#primaryimage\",\"inLanguage\":\"pt-BR\",\"url\":\"https:\/\/abifer.org.br\/wp-content\/uploads\/2025\/01\/debentures.jpeg\",\"contentUrl\":\"https:\/\/abifer.org.br\/wp-content\/uploads\/2025\/01\/debentures.jpeg\",\"width\":1280,\"height\":720},{\"@type\":\"WebPage\",\"@id\":\"http:\/\/abifer.org.br\/reforma-administrativa-de-tarcisio-reduz-em-29-os-cargos-no-metro-de-sp\/#webpage\",\"url\":\"http:\/\/abifer.org.br\/reforma-administrativa-de-tarcisio-reduz-em-29-os-cargos-no-metro-de-sp\/\",\"name\":\"Reforma administrativa de Tarc\u00edsio reduz em 29% os cargos no Metr\u00f4 de SP\",\"isPartOf\":{\"@id\":\"https:\/\/abifer.org.br\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\/\/abifer.org.br\/reforma-administrativa-de-tarcisio-reduz-em-29-os-cargos-no-metro-de-sp\/#primaryimage\"},\"datePublished\":\"2025-02-04T13:53:34+00:00\",\"dateModified\":\"2025-02-04T13:53:34+00:00\",\"breadcrumb\":{\"@id\":\"http:\/\/abifer.org.br\/reforma-administrativa-de-tarcisio-reduz-em-29-os-cargos-no-metro-de-sp\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/abifer.org.br\/reforma-administrativa-de-tarcisio-reduz-em-29-os-cargos-no-metro-de-sp\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/abifer.org.br\/reforma-administrativa-de-tarcisio-reduz-em-29-os-cargos-no-metro-de-sp\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/abifer.org.br\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Reforma administrativa de Tarc\u00edsio reduz em 29% os cargos no Metr\u00f4 de SP\"}]},{\"@type\":\"Article\",\"@id\":\"http:\/\/abifer.org.br\/reforma-administrativa-de-tarcisio-reduz-em-29-os-cargos-no-metro-de-sp\/#article\",\"isPartOf\":{\"@id\":\"http:\/\/abifer.org.br\/reforma-administrativa-de-tarcisio-reduz-em-29-os-cargos-no-metro-de-sp\/#webpage\"},\"author\":{\"@id\":\"https:\/\/abifer.org.br\/en\/#\/schema\/person\/90c38c3286f60a11b363834930f79a1f\"},\"headline\":\"Reforma administrativa de Tarc\u00edsio reduz em 29% os cargos no Metr\u00f4 de SP\",\"datePublished\":\"2025-02-04T13:53:34+00:00\",\"dateModified\":\"2025-02-04T13:53:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\/\/abifer.org.br\/reforma-administrativa-de-tarcisio-reduz-em-29-os-cargos-no-metro-de-sp\/#webpage\"},\"wordCount\":248,\"publisher\":{\"@id\":\"https:\/\/abifer.org.br\/en\/#organization\"},\"image\":{\"@id\":\"http:\/\/abifer.org.br\/reforma-administrativa-de-tarcisio-reduz-em-29-os-cargos-no-metro-de-sp\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/abifer.org.br\/wp-content\/uploads\/2025\/01\/debentures.jpeg\",\"articleSection\":[\"Not\u00edcias do Mercado\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/abifer.org.br\/en\/#\/schema\/person\/90c38c3286f60a11b363834930f79a1f\",\"name\":\"ABIFER\",\"url\":\"https:\/\/abifer.org.br\/author\/abifer\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Reforma administrativa de Tarc\u00edsio reduz em 29% os cargos no Metr\u00f4 de SP","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/abifer.org.br\/reforma-administrativa-de-tarcisio-reduz-em-29-os-cargos-no-metro-de-sp\/","og_locale":"pt_BR","og_type":"article","og_title":"Reforma administrativa de Tarc\u00edsio reduz em 29% os cargos no Metr\u00f4 de SP","og_description":"Fonte: Veja Data: 29\/01\/2025 Com a reforma administrativa aprovada no ano passado pelo governador Tarc\u00edsio de Freitas, a Companhia do Metropolitano reduziu em 29% o quadro de empregados do Metr\u00f4 de S\u00e3o Paulo. A institui\u00e7\u00e3o vai operar com 7.248 vagas ante as 10.224 autorizadas anteriormente. \u201cO corte est\u00e1 em linha com o plano S\u00e3o Paulo [&hellip;]","og_url":"http:\/\/abifer.org.br\/reforma-administrativa-de-tarcisio-reduz-em-29-os-cargos-no-metro-de-sp\/","og_site_name":"ABIFER","article_publisher":"https:\/\/www.facebook.com\/abiferoficial\/","article_published_time":"2025-02-04T13:53:34+00:00","og_image":[{"width":1280,"height":720,"url":"http:\/\/abifer.org.br\/wp-content\/uploads\/2025\/01\/debentures.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_creator":"@abiferoficial","twitter_site":"@abiferoficial","twitter_misc":{"Escrito por":"ABIFER","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Organization","@id":"https:\/\/abifer.org.br\/en\/#organization","name":"ABIFER","url":"https:\/\/abifer.org.br\/en\/","sameAs":["https:\/\/www.facebook.com\/abiferoficial\/","https:\/\/www.linkedin.com\/company\/abiferoficial\/","https:\/\/twitter.com\/abiferoficial"],"logo":{"@type":"ImageObject","@id":"https:\/\/abifer.org.br\/en\/#logo","inLanguage":"pt-BR","url":"https:\/\/abifer.org.br\/wp-content\/uploads\/2018\/05\/ABF_001_LogoSlogan.jpg","contentUrl":"https:\/\/abifer.org.br\/wp-content\/uploads\/2018\/05\/ABF_001_LogoSlogan.jpg","width":1182,"height":486,"caption":"ABIFER"},"image":{"@id":"https:\/\/abifer.org.br\/en\/#logo"}},{"@type":"WebSite","@id":"https:\/\/abifer.org.br\/en\/#website","url":"https:\/\/abifer.org.br\/en\/","name":"ABIFER","description":"Associa\u00e7\u00e3o Brasileira da Ind\u00fastria Ferrovi\u00e1ria","publisher":{"@id":"https:\/\/abifer.org.br\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/abifer.org.br\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"ImageObject","@id":"http:\/\/abifer.org.br\/reforma-administrativa-de-tarcisio-reduz-em-29-os-cargos-no-metro-de-sp\/#primaryimage","inLanguage":"pt-BR","url":"https:\/\/abifer.org.br\/wp-content\/uploads\/2025\/01\/debentures.jpeg","contentUrl":"https:\/\/abifer.org.br\/wp-content\/uploads\/2025\/01\/debentures.jpeg","width":1280,"height":720},{"@type":"WebPage","@id":"http:\/\/abifer.org.br\/reforma-administrativa-de-tarcisio-reduz-em-29-os-cargos-no-metro-de-sp\/#webpage","url":"http:\/\/abifer.org.br\/reforma-administrativa-de-tarcisio-reduz-em-29-os-cargos-no-metro-de-sp\/","name":"Reforma administrativa de Tarc\u00edsio reduz em 29% os cargos no Metr\u00f4 de SP","isPartOf":{"@id":"https:\/\/abifer.org.br\/en\/#website"},"primaryImageOfPage":{"@id":"http:\/\/abifer.org.br\/reforma-administrativa-de-tarcisio-reduz-em-29-os-cargos-no-metro-de-sp\/#primaryimage"},"datePublished":"2025-02-04T13:53:34+00:00","dateModified":"2025-02-04T13:53:34+00:00","breadcrumb":{"@id":"http:\/\/abifer.org.br\/reforma-administrativa-de-tarcisio-reduz-em-29-os-cargos-no-metro-de-sp\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["http:\/\/abifer.org.br\/reforma-administrativa-de-tarcisio-reduz-em-29-os-cargos-no-metro-de-sp\/"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/abifer.org.br\/reforma-administrativa-de-tarcisio-reduz-em-29-os-cargos-no-metro-de-sp\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/abifer.org.br\/en\/"},{"@type":"ListItem","position":2,"name":"Reforma administrativa de Tarc\u00edsio reduz em 29% os cargos no Metr\u00f4 de SP"}]},{"@type":"Article","@id":"http:\/\/abifer.org.br\/reforma-administrativa-de-tarcisio-reduz-em-29-os-cargos-no-metro-de-sp\/#article","isPartOf":{"@id":"http:\/\/abifer.org.br\/reforma-administrativa-de-tarcisio-reduz-em-29-os-cargos-no-metro-de-sp\/#webpage"},"author":{"@id":"https:\/\/abifer.org.br\/en\/#\/schema\/person\/90c38c3286f60a11b363834930f79a1f"},"headline":"Reforma administrativa de Tarc\u00edsio reduz em 29% os cargos no Metr\u00f4 de SP","datePublished":"2025-02-04T13:53:34+00:00","dateModified":"2025-02-04T13:53:34+00:00","mainEntityOfPage":{"@id":"http:\/\/abifer.org.br\/reforma-administrativa-de-tarcisio-reduz-em-29-os-cargos-no-metro-de-sp\/#webpage"},"wordCount":248,"publisher":{"@id":"https:\/\/abifer.org.br\/en\/#organization"},"image":{"@id":"http:\/\/abifer.org.br\/reforma-administrativa-de-tarcisio-reduz-em-29-os-cargos-no-metro-de-sp\/#primaryimage"},"thumbnailUrl":"https:\/\/abifer.org.br\/wp-content\/uploads\/2025\/01\/debentures.jpeg","articleSection":["Not\u00edcias do Mercado"],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/abifer.org.br\/en\/#\/schema\/person\/90c38c3286f60a11b363834930f79a1f","name":"ABIFER","url":"https:\/\/abifer.org.br\/author\/abifer\/"}]}},"_links":{"self":[{"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/posts\/86641\/"}],"collection":[{"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/posts\/"}],"about":[{"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/types\/post\/"}],"author":[{"embeddable":true,"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/users\/55\/"}],"replies":[{"embeddable":true,"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/comments\/?post=86641"}],"version-history":[{"count":1,"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/posts\/86641\/revisions\/"}],"predecessor-version":[{"id":86642,"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/posts\/86641\/revisions\/86642\/"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/media\/85903\/"}],"wp:attachment":[{"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/media\/?parent=86641"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/categories\/?post=86641"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/tags\/?post=86641"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}