{"id":87968,"date":"2025-04-24T10:14:40","date_gmt":"2025-04-24T13:14:40","guid":{"rendered":"https:\/\/abifer.org.br\/?p=87968"},"modified":"2025-04-24T10:14:40","modified_gmt":"2025-04-24T13:14:40","slug":"cbtu-recife-investe-em-equipamentos-de-ultrassom-para-inspecao-em-trilhos-rodas-e-eixos","status":"publish","type":"post","link":"https:\/\/abifer.org.br\/en\/cbtu-recife-investe-em-equipamentos-de-ultrassom-para-inspecao-em-trilhos-rodas-e-eixos\/","title":{"rendered":"CBTU Recife investe em equipamentos de ultrassom para inspe\u00e7\u00e3o em trilhos, rodas e eixos"},"content":{"rendered":"<p style=\"text-align: right;\"><em>Fonte: CBTU<\/em><\/p>\n<p>A CBTU adquiriu, em novembro de 2024, dois equipamentos de ultrassonografia de \u00faltima gera\u00e7\u00e3o. As ferramentas ser\u00e3o utilizadas na inspe\u00e7\u00e3o ultrass\u00f4nica de rodas e eixos montados de Trens de Unidade El\u00e9trico (TUE\u00b4s), Ve\u00edculos Leve sobre Trilho (VLT) e M\u00e1quinas especiais. O valor do investimento foi de aproximadamente R$ 1,2 milh\u00e3o.<\/p>\n<p>Anteriormente, a Superintend\u00eancia de Recife j\u00e1 havia investido R$ 800 mil na aquisi\u00e7\u00e3o de um trolley de inspe\u00e7\u00e3o de ultrassom em trilhos \u2013 uma m\u00e1quina port\u00e1til de bitola mista (larga e m\u00e9trica). Com o trolley, a CBTU poder\u00e1 realizar ensaios ultrass\u00f4nicos diretamente nos trilhos da via permanente, abrangendo tanto a malha metroferrovi\u00e1ria el\u00e9trica quanto as linhas diesel de todas as unidades da Companhia.<\/p>\n<p>As novas tecnologias s\u00e3o essenciais para detectar trincas internas e microfissuras invis\u00edveis a olho nu, promovendo a seguran\u00e7a operacional e a antecipa\u00e7\u00e3o de falhas. A possibilidade de realizar inspe\u00e7\u00f5es por ultrassom em rodas montadas no trem \u00e9 um diferencial da Companhia no cen\u00e1rio nacional \u2014 at\u00e9 o momento, n\u00e3o se tem conhecimento de outra operadora brasileira que execute da mesma maneira esse tipo de inspe\u00e7\u00e3o. \u00c9 a CBTU na vanguarda da tecnologia, promovendo seguran\u00e7a e confiabilidade para seus usu\u00e1rios.<\/p>\n<p>&#8220;Isso causar\u00e1 um impacto positivo em nossas opera\u00e7\u00f5es, pois elevaremos o padr\u00e3o de seguran\u00e7a, seguindo todos os par\u00e2metros das normas internacionais&#8221;, explicou Rafael Teixeira, Gerente Operacional &#8211; Material Rodante da CBTU Recife.<\/p>\n<p>Al\u00e9m das aquisi\u00e7\u00f5es dos equipamentos, a CBTU est\u00e1 em processo de capacita\u00e7\u00e3o da equipe t\u00e9cnica local para operar os novos aparelhos. Isso n\u00e3o apenas garante autonomia e efici\u00eancia, como tamb\u00e9m habilita a unidade Recife a realizar inspe\u00e7\u00f5es nos VLT\u00b4s de Natal, Jo\u00e3o Pessoa e Macei\u00f3, consolidando-se como refer\u00eancia nacional na aplica\u00e7\u00e3o de ultrassom ferrovi\u00e1rio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fonte: CBTU A CBTU adquiriu, em novembro de 2024, dois equipamentos de ultrassonografia de \u00faltima gera\u00e7\u00e3o. As ferramentas ser\u00e3o utilizadas na inspe\u00e7\u00e3o ultrass\u00f4nica de rodas e eixos montados de Trens de Unidade El\u00e9trico (TUE\u00b4s), Ve\u00edculos Leve sobre Trilho (VLT) e M\u00e1quinas especiais. O valor do investimento foi de aproximadamente R$ 1,2 milh\u00e3o. Anteriormente, a Superintend\u00eancia [&hellip;]<\/p>\n","protected":false},"author":55,"featured_media":86710,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[875],"tags":[],"class_list":["post-87968","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-do-mercado"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>CBTU Recife investe em equipamentos de ultrassom para inspe\u00e7\u00e3o em trilhos, rodas e eixos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/abifer.org.br\/cbtu-recife-investe-em-equipamentos-de-ultrassom-para-inspecao-em-trilhos-rodas-e-eixos\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CBTU Recife investe em equipamentos de ultrassom para inspe\u00e7\u00e3o em trilhos, rodas e eixos\" \/>\n<meta property=\"og:description\" content=\"Fonte: CBTU A CBTU adquiriu, em novembro de 2024, dois equipamentos de ultrassonografia de \u00faltima gera\u00e7\u00e3o. As ferramentas ser\u00e3o utilizadas na inspe\u00e7\u00e3o ultrass\u00f4nica de rodas e eixos montados de Trens de Unidade El\u00e9trico (TUE\u00b4s), Ve\u00edculos Leve sobre Trilho (VLT) e M\u00e1quinas especiais. O valor do investimento foi de aproximadamente R$ 1,2 milh\u00e3o. Anteriormente, a Superintend\u00eancia [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/abifer.org.br\/cbtu-recife-investe-em-equipamentos-de-ultrassom-para-inspecao-em-trilhos-rodas-e-eixos\/\" \/>\n<meta property=\"og:site_name\" content=\"ABIFER\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/abiferoficial\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-24T13:14:40+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/abifer.org.br\/wp-content\/uploads\/2025\/02\/bandeira-brasil.webp\" \/>\n<meta name=\"twitter:creator\" content=\"@abiferoficial\" \/>\n<meta name=\"twitter:site\" content=\"@abiferoficial\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"ABIFER\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/abifer.org.br\/en\/#organization\",\"name\":\"ABIFER\",\"url\":\"https:\/\/abifer.org.br\/en\/\",\"sameAs\":[\"https:\/\/www.facebook.com\/abiferoficial\/\",\"https:\/\/www.linkedin.com\/company\/abiferoficial\/\",\"https:\/\/twitter.com\/abiferoficial\"],\"logo\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/abifer.org.br\/en\/#logo\",\"inLanguage\":\"pt-BR\",\"url\":\"https:\/\/abifer.org.br\/wp-content\/uploads\/2018\/05\/ABF_001_LogoSlogan.jpg\",\"contentUrl\":\"https:\/\/abifer.org.br\/wp-content\/uploads\/2018\/05\/ABF_001_LogoSlogan.jpg\",\"width\":1182,\"height\":486,\"caption\":\"ABIFER\"},\"image\":{\"@id\":\"https:\/\/abifer.org.br\/en\/#logo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/abifer.org.br\/en\/#website\",\"url\":\"https:\/\/abifer.org.br\/en\/\",\"name\":\"ABIFER\",\"description\":\"Associa\u00e7\u00e3o Brasileira da Ind\u00fastria Ferrovi\u00e1ria\",\"publisher\":{\"@id\":\"https:\/\/abifer.org.br\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/abifer.org.br\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/abifer.org.br\/cbtu-recife-investe-em-equipamentos-de-ultrassom-para-inspecao-em-trilhos-rodas-e-eixos\/#primaryimage\",\"inLanguage\":\"pt-BR\",\"url\":\"https:\/\/abifer.org.br\/wp-content\/uploads\/2025\/02\/bandeira-brasil.webp\",\"contentUrl\":\"https:\/\/abifer.org.br\/wp-content\/uploads\/2025\/02\/bandeira-brasil.webp\",\"width\":1024,\"height\":1024},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/abifer.org.br\/cbtu-recife-investe-em-equipamentos-de-ultrassom-para-inspecao-em-trilhos-rodas-e-eixos\/#webpage\",\"url\":\"https:\/\/abifer.org.br\/cbtu-recife-investe-em-equipamentos-de-ultrassom-para-inspecao-em-trilhos-rodas-e-eixos\/\",\"name\":\"CBTU Recife investe em equipamentos de ultrassom para inspe\u00e7\u00e3o em trilhos, rodas e eixos\",\"isPartOf\":{\"@id\":\"https:\/\/abifer.org.br\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/abifer.org.br\/cbtu-recife-investe-em-equipamentos-de-ultrassom-para-inspecao-em-trilhos-rodas-e-eixos\/#primaryimage\"},\"datePublished\":\"2025-04-24T13:14:40+00:00\",\"dateModified\":\"2025-04-24T13:14:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/abifer.org.br\/cbtu-recife-investe-em-equipamentos-de-ultrassom-para-inspecao-em-trilhos-rodas-e-eixos\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/abifer.org.br\/cbtu-recife-investe-em-equipamentos-de-ultrassom-para-inspecao-em-trilhos-rodas-e-eixos\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/abifer.org.br\/cbtu-recife-investe-em-equipamentos-de-ultrassom-para-inspecao-em-trilhos-rodas-e-eixos\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/abifer.org.br\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CBTU Recife investe em equipamentos de ultrassom para inspe\u00e7\u00e3o em trilhos, rodas e eixos\"}]},{\"@type\":\"Article\",\"@id\":\"https:\/\/abifer.org.br\/cbtu-recife-investe-em-equipamentos-de-ultrassom-para-inspecao-em-trilhos-rodas-e-eixos\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/abifer.org.br\/cbtu-recife-investe-em-equipamentos-de-ultrassom-para-inspecao-em-trilhos-rodas-e-eixos\/#webpage\"},\"author\":{\"@id\":\"https:\/\/abifer.org.br\/en\/#\/schema\/person\/90c38c3286f60a11b363834930f79a1f\"},\"headline\":\"CBTU Recife investe em equipamentos de ultrassom para inspe\u00e7\u00e3o em trilhos, rodas e eixos\",\"datePublished\":\"2025-04-24T13:14:40+00:00\",\"dateModified\":\"2025-04-24T13:14:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/abifer.org.br\/cbtu-recife-investe-em-equipamentos-de-ultrassom-para-inspecao-em-trilhos-rodas-e-eixos\/#webpage\"},\"wordCount\":333,\"publisher\":{\"@id\":\"https:\/\/abifer.org.br\/en\/#organization\"},\"image\":{\"@id\":\"https:\/\/abifer.org.br\/cbtu-recife-investe-em-equipamentos-de-ultrassom-para-inspecao-em-trilhos-rodas-e-eixos\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/abifer.org.br\/wp-content\/uploads\/2025\/02\/bandeira-brasil.webp\",\"articleSection\":[\"Not\u00edcias do Mercado\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/abifer.org.br\/en\/#\/schema\/person\/90c38c3286f60a11b363834930f79a1f\",\"name\":\"ABIFER\",\"url\":\"https:\/\/abifer.org.br\/author\/abifer\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CBTU Recife investe em equipamentos de ultrassom para inspe\u00e7\u00e3o em trilhos, rodas e eixos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/abifer.org.br\/cbtu-recife-investe-em-equipamentos-de-ultrassom-para-inspecao-em-trilhos-rodas-e-eixos\/","og_locale":"pt_BR","og_type":"article","og_title":"CBTU Recife investe em equipamentos de ultrassom para inspe\u00e7\u00e3o em trilhos, rodas e eixos","og_description":"Fonte: CBTU A CBTU adquiriu, em novembro de 2024, dois equipamentos de ultrassonografia de \u00faltima gera\u00e7\u00e3o. As ferramentas ser\u00e3o utilizadas na inspe\u00e7\u00e3o ultrass\u00f4nica de rodas e eixos montados de Trens de Unidade El\u00e9trico (TUE\u00b4s), Ve\u00edculos Leve sobre Trilho (VLT) e M\u00e1quinas especiais. O valor do investimento foi de aproximadamente R$ 1,2 milh\u00e3o. Anteriormente, a Superintend\u00eancia [&hellip;]","og_url":"https:\/\/abifer.org.br\/cbtu-recife-investe-em-equipamentos-de-ultrassom-para-inspecao-em-trilhos-rodas-e-eixos\/","og_site_name":"ABIFER","article_publisher":"https:\/\/www.facebook.com\/abiferoficial\/","article_published_time":"2025-04-24T13:14:40+00:00","twitter_card":"summary_large_image","twitter_image":"https:\/\/abifer.org.br\/wp-content\/uploads\/2025\/02\/bandeira-brasil.webp","twitter_creator":"@abiferoficial","twitter_site":"@abiferoficial","twitter_misc":{"Escrito por":"ABIFER","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Organization","@id":"https:\/\/abifer.org.br\/en\/#organization","name":"ABIFER","url":"https:\/\/abifer.org.br\/en\/","sameAs":["https:\/\/www.facebook.com\/abiferoficial\/","https:\/\/www.linkedin.com\/company\/abiferoficial\/","https:\/\/twitter.com\/abiferoficial"],"logo":{"@type":"ImageObject","@id":"https:\/\/abifer.org.br\/en\/#logo","inLanguage":"pt-BR","url":"https:\/\/abifer.org.br\/wp-content\/uploads\/2018\/05\/ABF_001_LogoSlogan.jpg","contentUrl":"https:\/\/abifer.org.br\/wp-content\/uploads\/2018\/05\/ABF_001_LogoSlogan.jpg","width":1182,"height":486,"caption":"ABIFER"},"image":{"@id":"https:\/\/abifer.org.br\/en\/#logo"}},{"@type":"WebSite","@id":"https:\/\/abifer.org.br\/en\/#website","url":"https:\/\/abifer.org.br\/en\/","name":"ABIFER","description":"Associa\u00e7\u00e3o Brasileira da Ind\u00fastria Ferrovi\u00e1ria","publisher":{"@id":"https:\/\/abifer.org.br\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/abifer.org.br\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"ImageObject","@id":"https:\/\/abifer.org.br\/cbtu-recife-investe-em-equipamentos-de-ultrassom-para-inspecao-em-trilhos-rodas-e-eixos\/#primaryimage","inLanguage":"pt-BR","url":"https:\/\/abifer.org.br\/wp-content\/uploads\/2025\/02\/bandeira-brasil.webp","contentUrl":"https:\/\/abifer.org.br\/wp-content\/uploads\/2025\/02\/bandeira-brasil.webp","width":1024,"height":1024},{"@type":"WebPage","@id":"https:\/\/abifer.org.br\/cbtu-recife-investe-em-equipamentos-de-ultrassom-para-inspecao-em-trilhos-rodas-e-eixos\/#webpage","url":"https:\/\/abifer.org.br\/cbtu-recife-investe-em-equipamentos-de-ultrassom-para-inspecao-em-trilhos-rodas-e-eixos\/","name":"CBTU Recife investe em equipamentos de ultrassom para inspe\u00e7\u00e3o em trilhos, rodas e eixos","isPartOf":{"@id":"https:\/\/abifer.org.br\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/abifer.org.br\/cbtu-recife-investe-em-equipamentos-de-ultrassom-para-inspecao-em-trilhos-rodas-e-eixos\/#primaryimage"},"datePublished":"2025-04-24T13:14:40+00:00","dateModified":"2025-04-24T13:14:40+00:00","breadcrumb":{"@id":"https:\/\/abifer.org.br\/cbtu-recife-investe-em-equipamentos-de-ultrassom-para-inspecao-em-trilhos-rodas-e-eixos\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/abifer.org.br\/cbtu-recife-investe-em-equipamentos-de-ultrassom-para-inspecao-em-trilhos-rodas-e-eixos\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/abifer.org.br\/cbtu-recife-investe-em-equipamentos-de-ultrassom-para-inspecao-em-trilhos-rodas-e-eixos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/abifer.org.br\/en\/"},{"@type":"ListItem","position":2,"name":"CBTU Recife investe em equipamentos de ultrassom para inspe\u00e7\u00e3o em trilhos, rodas e eixos"}]},{"@type":"Article","@id":"https:\/\/abifer.org.br\/cbtu-recife-investe-em-equipamentos-de-ultrassom-para-inspecao-em-trilhos-rodas-e-eixos\/#article","isPartOf":{"@id":"https:\/\/abifer.org.br\/cbtu-recife-investe-em-equipamentos-de-ultrassom-para-inspecao-em-trilhos-rodas-e-eixos\/#webpage"},"author":{"@id":"https:\/\/abifer.org.br\/en\/#\/schema\/person\/90c38c3286f60a11b363834930f79a1f"},"headline":"CBTU Recife investe em equipamentos de ultrassom para inspe\u00e7\u00e3o em trilhos, rodas e eixos","datePublished":"2025-04-24T13:14:40+00:00","dateModified":"2025-04-24T13:14:40+00:00","mainEntityOfPage":{"@id":"https:\/\/abifer.org.br\/cbtu-recife-investe-em-equipamentos-de-ultrassom-para-inspecao-em-trilhos-rodas-e-eixos\/#webpage"},"wordCount":333,"publisher":{"@id":"https:\/\/abifer.org.br\/en\/#organization"},"image":{"@id":"https:\/\/abifer.org.br\/cbtu-recife-investe-em-equipamentos-de-ultrassom-para-inspecao-em-trilhos-rodas-e-eixos\/#primaryimage"},"thumbnailUrl":"https:\/\/abifer.org.br\/wp-content\/uploads\/2025\/02\/bandeira-brasil.webp","articleSection":["Not\u00edcias do Mercado"],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/abifer.org.br\/en\/#\/schema\/person\/90c38c3286f60a11b363834930f79a1f","name":"ABIFER","url":"https:\/\/abifer.org.br\/author\/abifer\/"}]}},"_links":{"self":[{"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/posts\/87968\/"}],"collection":[{"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/posts\/"}],"about":[{"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/types\/post\/"}],"author":[{"embeddable":true,"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/users\/55\/"}],"replies":[{"embeddable":true,"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/comments\/?post=87968"}],"version-history":[{"count":1,"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/posts\/87968\/revisions\/"}],"predecessor-version":[{"id":87969,"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/posts\/87968\/revisions\/87969\/"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/media\/86710\/"}],"wp:attachment":[{"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/media\/?parent=87968"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/categories\/?post=87968"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/tags\/?post=87968"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}