{"id":88369,"date":"2025-05-19T18:52:52","date_gmt":"2025-05-19T21:52:52","guid":{"rendered":"https:\/\/abifer.org.br\/?p=88369"},"modified":"2025-05-19T18:52:52","modified_gmt":"2025-05-19T21:52:52","slug":"feira-norte-americana-reunira-23-empresas-brasileiras","status":"publish","type":"post","link":"https:\/\/abifer.org.br\/en\/feira-norte-americana-reunira-23-empresas-brasileiras\/","title":{"rendered":"Feira norte-americana reunir\u00e1 23 empresas brasileiras"},"content":{"rendered":"<pre style=\"text-align: right;\"><strong><em>Fonte: Assessoria Brazil on Rails<\/em><\/strong><\/pre>\n<p>A Railway Interchange ser\u00e1 realizada de 20 a 22 de maio, em Indian\u00e1polis, nos Estados Unidos, e contar\u00e1 com a comitiva brasileira no estande Brazil on Rails.<\/p>\n<p>Indian\u00e1polis, nos Estados Unidos, receber\u00e1 nos pr\u00f3ximos dias a comitiva brasileira composta por 23 empresas, que participar\u00e1 da Railway Interchange, a maior exposi\u00e7\u00e3o ferrovi\u00e1ria e confer\u00eancia da Am\u00e9rica do Norte, que deve reunir mais de cinco mil profissionais de todo o mudo.<\/p>\n<p>\u201cSer\u00e3o tr\u00eas dias de feira com apresenta\u00e7\u00f5es de equipamentos, pe\u00e7as, m\u00e1quinas e tecnologias. Uma grande oportunidade de networking e neg\u00f3cios para os brasileiros que estar\u00e3o conosco no Brazil on Rails\u201d, explica Rodrigo Vila\u00e7a, Presidente da RV Conecta, a organizadora do projeto que re\u00fane empres\u00e1rios e gestores em feiras ferrovi\u00e1rias internacionais.<\/p>\n<p>\u201cA Railway Interchange \u00e9 um espa\u00e7o que agregar\u00e1 inova\u00e7\u00f5es, tecnologias e debates importantes para o avan\u00e7o das ferrovias no Brasil. \u00c9 um momento de atualiza\u00e7\u00e3o do que h\u00e1 de mais moderno no setor\u201d, explica Vinicius Scartezini, executivo do Brazil on Rails.<\/p>\n<p>As empresas confirmadas s\u00e3o:<\/p>\n<p>\u2022 Infra S.A.<br \/>\n\u2022 CBFA &#8211; Companhia Brasileira de Ferro e A\u00e7o;<br \/>\n\u2022 Cindumel;<br \/>\n\u2022 Comexport;<br \/>\n\u2022 Grana\u00e7o;<br \/>\n\u2022 Harsco do Brasil;<br \/>\n\u2022 Macro Investimentos;<br \/>\n\u2022 MacroEx;<br \/>\n\u2022 Timbro;<br \/>\n\u2022 Retesp;<br \/>\n\u2022 Vessel Engenharia El\u00e9trica;<br \/>\n\u2022 Construtora Barbosa Mello;<br \/>\n\u2022 Loram;<br \/>\n\u2022 Sysfer;<br \/>\n\u2022 Cavan;<br \/>\n\u2022 Conprem;<br \/>\n\u2022 Fras-le;<br \/>\n\u2022 Hidremec;<br \/>\n\u2022 Marcopolo Rail;<br \/>\n\u2022 Plasser do Brasil;<br \/>\n\u2022 Frum;<br \/>\n\u2022 EGTC;<br \/>\n\u2022 Queiroz &amp; Maluf Associados.<\/p>\n<p>O projeto Brazil on Rails conta com o apoio da Secretaria Nacional de Transporte Ferrovi\u00e1rio do Minist\u00e9rio dos Transportes; da Ag\u00eancia Nacional de Transportes Terrestres (ANTT); e da Associa\u00e7\u00e3o Brasileira da Ind\u00fastria Ferrovi\u00e1ria (ABIFER); da Associa\u00e7\u00e3o Nacional dos Transportadores Ferrovi\u00e1rios (ANTF); Associa\u00e7\u00e3o Latino-Americana de Ferrovias (ALAF); Grupo Permanente de Auto Ajuda na \u00c1rea de Manuten\u00e7\u00e3o Metroferrovi\u00e1ria (GPAA);NT Expo; Informa Markets; Revista Ferrovi\u00e1ria; Governo do Estado do Paran\u00e1; Ferroeste; IHHA; Trem do Corcovado; Aeamesp; e Mais Trilhos.<\/p>\n<p>\u201cA feira \u00e9 uma grande oportunidade de networking dos empres\u00e1rios brasileiros com os fornecedores internacionais, estreitando rela\u00e7\u00f5es e desenvolvendo neg\u00f3cios\u201d, destaca Alexandre Barros, executivo da RV Conecta e respons\u00e1vel pela comercializa\u00e7\u00e3o do evento.<\/p>\n<p>Sandra Holanda, ex-Secret\u00e1ria Nacional de Mobilidade Urbana do Minist\u00e9rio dos Transportes e executiva do Brazil on Rails, refor\u00e7a que \u201ca presen\u00e7a em eventos de grande porte, como a Railway Interchange, n\u00e3o s\u00f3 proporciona estreitar rela\u00e7\u00f5es comerciais como agregam valores para as empresas\u201d.<\/p>\n<p>Informa\u00e7\u00f5es sobre a participa\u00e7\u00e3o na Railway Interchange podem ser obtidas atrav\u00e9s do e-mail alexandre.barros@rvconecta.com .<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fonte: Assessoria Brazil on Rails A Railway Interchange ser\u00e1 realizada de 20 a 22 de maio, em Indian\u00e1polis, nos Estados Unidos, e contar\u00e1 com a comitiva brasileira no estande Brazil on Rails. Indian\u00e1polis, nos Estados Unidos, receber\u00e1 nos pr\u00f3ximos dias a comitiva brasileira composta por 23 empresas, que participar\u00e1 da Railway Interchange, a maior exposi\u00e7\u00e3o [&hellip;]<\/p>\n","protected":false},"author":55,"featured_media":88370,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[875],"tags":[],"class_list":["post-88369","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-do-mercado"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Feira norte-americana reunir\u00e1 23 empresas brasileiras<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/abifer.org.br\/feira-norte-americana-reunira-23-empresas-brasileiras\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Feira norte-americana reunir\u00e1 23 empresas brasileiras\" \/>\n<meta property=\"og:description\" content=\"Fonte: Assessoria Brazil on Rails A Railway Interchange ser\u00e1 realizada de 20 a 22 de maio, em Indian\u00e1polis, nos Estados Unidos, e contar\u00e1 com a comitiva brasileira no estande Brazil on Rails. Indian\u00e1polis, nos Estados Unidos, receber\u00e1 nos pr\u00f3ximos dias a comitiva brasileira composta por 23 empresas, que participar\u00e1 da Railway Interchange, a maior exposi\u00e7\u00e3o [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"http:\/\/abifer.org.br\/feira-norte-americana-reunira-23-empresas-brasileiras\/\" \/>\n<meta property=\"og:site_name\" content=\"ABIFER\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/abiferoficial\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-19T21:52:52+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/abifer.org.br\/wp-content\/uploads\/2025\/05\/th.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"442\" \/>\n\t<meta property=\"og:image:height\" content=\"180\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@abiferoficial\" \/>\n<meta name=\"twitter:site\" content=\"@abiferoficial\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"ABIFER\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/abifer.org.br\/en\/#organization\",\"name\":\"ABIFER\",\"url\":\"https:\/\/abifer.org.br\/en\/\",\"sameAs\":[\"https:\/\/www.facebook.com\/abiferoficial\/\",\"https:\/\/www.linkedin.com\/company\/abiferoficial\/\",\"https:\/\/twitter.com\/abiferoficial\"],\"logo\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/abifer.org.br\/en\/#logo\",\"inLanguage\":\"pt-BR\",\"url\":\"https:\/\/abifer.org.br\/wp-content\/uploads\/2018\/05\/ABF_001_LogoSlogan.jpg\",\"contentUrl\":\"https:\/\/abifer.org.br\/wp-content\/uploads\/2018\/05\/ABF_001_LogoSlogan.jpg\",\"width\":1182,\"height\":486,\"caption\":\"ABIFER\"},\"image\":{\"@id\":\"https:\/\/abifer.org.br\/en\/#logo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/abifer.org.br\/en\/#website\",\"url\":\"https:\/\/abifer.org.br\/en\/\",\"name\":\"ABIFER\",\"description\":\"Associa\u00e7\u00e3o Brasileira da Ind\u00fastria Ferrovi\u00e1ria\",\"publisher\":{\"@id\":\"https:\/\/abifer.org.br\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/abifer.org.br\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"ImageObject\",\"@id\":\"http:\/\/abifer.org.br\/feira-norte-americana-reunira-23-empresas-brasileiras\/#primaryimage\",\"inLanguage\":\"pt-BR\",\"url\":\"https:\/\/abifer.org.br\/wp-content\/uploads\/2025\/05\/th.jpg\",\"contentUrl\":\"https:\/\/abifer.org.br\/wp-content\/uploads\/2025\/05\/th.jpg\",\"width\":442,\"height\":180},{\"@type\":\"WebPage\",\"@id\":\"http:\/\/abifer.org.br\/feira-norte-americana-reunira-23-empresas-brasileiras\/#webpage\",\"url\":\"http:\/\/abifer.org.br\/feira-norte-americana-reunira-23-empresas-brasileiras\/\",\"name\":\"Feira norte-americana reunir\u00e1 23 empresas brasileiras\",\"isPartOf\":{\"@id\":\"https:\/\/abifer.org.br\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\/\/abifer.org.br\/feira-norte-americana-reunira-23-empresas-brasileiras\/#primaryimage\"},\"datePublished\":\"2025-05-19T21:52:52+00:00\",\"dateModified\":\"2025-05-19T21:52:52+00:00\",\"breadcrumb\":{\"@id\":\"http:\/\/abifer.org.br\/feira-norte-americana-reunira-23-empresas-brasileiras\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/abifer.org.br\/feira-norte-americana-reunira-23-empresas-brasileiras\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/abifer.org.br\/feira-norte-americana-reunira-23-empresas-brasileiras\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/abifer.org.br\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Feira norte-americana reunir\u00e1 23 empresas brasileiras\"}]},{\"@type\":\"Article\",\"@id\":\"http:\/\/abifer.org.br\/feira-norte-americana-reunira-23-empresas-brasileiras\/#article\",\"isPartOf\":{\"@id\":\"http:\/\/abifer.org.br\/feira-norte-americana-reunira-23-empresas-brasileiras\/#webpage\"},\"author\":{\"@id\":\"https:\/\/abifer.org.br\/en\/#\/schema\/person\/90c38c3286f60a11b363834930f79a1f\"},\"headline\":\"Feira norte-americana reunir\u00e1 23 empresas brasileiras\",\"datePublished\":\"2025-05-19T21:52:52+00:00\",\"dateModified\":\"2025-05-19T21:52:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\/\/abifer.org.br\/feira-norte-americana-reunira-23-empresas-brasileiras\/#webpage\"},\"wordCount\":429,\"publisher\":{\"@id\":\"https:\/\/abifer.org.br\/en\/#organization\"},\"image\":{\"@id\":\"http:\/\/abifer.org.br\/feira-norte-americana-reunira-23-empresas-brasileiras\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/abifer.org.br\/wp-content\/uploads\/2025\/05\/th.jpg\",\"articleSection\":[\"Not\u00edcias do Mercado\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/abifer.org.br\/en\/#\/schema\/person\/90c38c3286f60a11b363834930f79a1f\",\"name\":\"ABIFER\",\"url\":\"https:\/\/abifer.org.br\/author\/abifer\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Feira norte-americana reunir\u00e1 23 empresas brasileiras","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/abifer.org.br\/feira-norte-americana-reunira-23-empresas-brasileiras\/","og_locale":"pt_BR","og_type":"article","og_title":"Feira norte-americana reunir\u00e1 23 empresas brasileiras","og_description":"Fonte: Assessoria Brazil on Rails A Railway Interchange ser\u00e1 realizada de 20 a 22 de maio, em Indian\u00e1polis, nos Estados Unidos, e contar\u00e1 com a comitiva brasileira no estande Brazil on Rails. Indian\u00e1polis, nos Estados Unidos, receber\u00e1 nos pr\u00f3ximos dias a comitiva brasileira composta por 23 empresas, que participar\u00e1 da Railway Interchange, a maior exposi\u00e7\u00e3o [&hellip;]","og_url":"http:\/\/abifer.org.br\/feira-norte-americana-reunira-23-empresas-brasileiras\/","og_site_name":"ABIFER","article_publisher":"https:\/\/www.facebook.com\/abiferoficial\/","article_published_time":"2025-05-19T21:52:52+00:00","og_image":[{"width":442,"height":180,"url":"http:\/\/abifer.org.br\/wp-content\/uploads\/2025\/05\/th.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_creator":"@abiferoficial","twitter_site":"@abiferoficial","twitter_misc":{"Escrito por":"ABIFER","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Organization","@id":"https:\/\/abifer.org.br\/en\/#organization","name":"ABIFER","url":"https:\/\/abifer.org.br\/en\/","sameAs":["https:\/\/www.facebook.com\/abiferoficial\/","https:\/\/www.linkedin.com\/company\/abiferoficial\/","https:\/\/twitter.com\/abiferoficial"],"logo":{"@type":"ImageObject","@id":"https:\/\/abifer.org.br\/en\/#logo","inLanguage":"pt-BR","url":"https:\/\/abifer.org.br\/wp-content\/uploads\/2018\/05\/ABF_001_LogoSlogan.jpg","contentUrl":"https:\/\/abifer.org.br\/wp-content\/uploads\/2018\/05\/ABF_001_LogoSlogan.jpg","width":1182,"height":486,"caption":"ABIFER"},"image":{"@id":"https:\/\/abifer.org.br\/en\/#logo"}},{"@type":"WebSite","@id":"https:\/\/abifer.org.br\/en\/#website","url":"https:\/\/abifer.org.br\/en\/","name":"ABIFER","description":"Associa\u00e7\u00e3o Brasileira da Ind\u00fastria Ferrovi\u00e1ria","publisher":{"@id":"https:\/\/abifer.org.br\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/abifer.org.br\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"ImageObject","@id":"http:\/\/abifer.org.br\/feira-norte-americana-reunira-23-empresas-brasileiras\/#primaryimage","inLanguage":"pt-BR","url":"https:\/\/abifer.org.br\/wp-content\/uploads\/2025\/05\/th.jpg","contentUrl":"https:\/\/abifer.org.br\/wp-content\/uploads\/2025\/05\/th.jpg","width":442,"height":180},{"@type":"WebPage","@id":"http:\/\/abifer.org.br\/feira-norte-americana-reunira-23-empresas-brasileiras\/#webpage","url":"http:\/\/abifer.org.br\/feira-norte-americana-reunira-23-empresas-brasileiras\/","name":"Feira norte-americana reunir\u00e1 23 empresas brasileiras","isPartOf":{"@id":"https:\/\/abifer.org.br\/en\/#website"},"primaryImageOfPage":{"@id":"http:\/\/abifer.org.br\/feira-norte-americana-reunira-23-empresas-brasileiras\/#primaryimage"},"datePublished":"2025-05-19T21:52:52+00:00","dateModified":"2025-05-19T21:52:52+00:00","breadcrumb":{"@id":"http:\/\/abifer.org.br\/feira-norte-americana-reunira-23-empresas-brasileiras\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["http:\/\/abifer.org.br\/feira-norte-americana-reunira-23-empresas-brasileiras\/"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/abifer.org.br\/feira-norte-americana-reunira-23-empresas-brasileiras\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/abifer.org.br\/en\/"},{"@type":"ListItem","position":2,"name":"Feira norte-americana reunir\u00e1 23 empresas brasileiras"}]},{"@type":"Article","@id":"http:\/\/abifer.org.br\/feira-norte-americana-reunira-23-empresas-brasileiras\/#article","isPartOf":{"@id":"http:\/\/abifer.org.br\/feira-norte-americana-reunira-23-empresas-brasileiras\/#webpage"},"author":{"@id":"https:\/\/abifer.org.br\/en\/#\/schema\/person\/90c38c3286f60a11b363834930f79a1f"},"headline":"Feira norte-americana reunir\u00e1 23 empresas brasileiras","datePublished":"2025-05-19T21:52:52+00:00","dateModified":"2025-05-19T21:52:52+00:00","mainEntityOfPage":{"@id":"http:\/\/abifer.org.br\/feira-norte-americana-reunira-23-empresas-brasileiras\/#webpage"},"wordCount":429,"publisher":{"@id":"https:\/\/abifer.org.br\/en\/#organization"},"image":{"@id":"http:\/\/abifer.org.br\/feira-norte-americana-reunira-23-empresas-brasileiras\/#primaryimage"},"thumbnailUrl":"https:\/\/abifer.org.br\/wp-content\/uploads\/2025\/05\/th.jpg","articleSection":["Not\u00edcias do Mercado"],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/abifer.org.br\/en\/#\/schema\/person\/90c38c3286f60a11b363834930f79a1f","name":"ABIFER","url":"https:\/\/abifer.org.br\/author\/abifer\/"}]}},"_links":{"self":[{"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/posts\/88369\/"}],"collection":[{"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/posts\/"}],"about":[{"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/types\/post\/"}],"author":[{"embeddable":true,"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/users\/55\/"}],"replies":[{"embeddable":true,"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/comments\/?post=88369"}],"version-history":[{"count":1,"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/posts\/88369\/revisions\/"}],"predecessor-version":[{"id":88372,"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/posts\/88369\/revisions\/88372\/"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/media\/88370\/"}],"wp:attachment":[{"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/media\/?parent=88369"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/categories\/?post=88369"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/tags\/?post=88369"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}