{"id":89604,"date":"2025-08-12T17:54:02","date_gmt":"2025-08-12T20:54:02","guid":{"rendered":"https:\/\/abifer.org.br\/?p=89604"},"modified":"2025-08-12T17:54:02","modified_gmt":"2025-08-12T20:54:02","slug":"abifer-na-midia-industria-de-trens-de-passageiros-vive-boom","status":"publish","type":"post","link":"https:\/\/abifer.org.br\/en\/abifer-na-midia-industria-de-trens-de-passageiros-vive-boom\/","title":{"rendered":"ABIFER na m\u00eddia &#8211; Ind\u00fastria de trens de passageiros vive \u2018boom\u2019"},"content":{"rendered":"<pre style=\"text-align: right;\"><a href=\"https:\/\/valor.globo.com\/empresas\/noticia\/2025\/08\/05\/industria-de-trens-de-passageiros-vive-boom.ghtml\" target=\"_blank\" rel=\"noopener\"><strong><em>Fonte: Valor\r\nData: 05\/08\/2025<\/em><\/strong><\/a><\/pre>\n<p><em>Onda de licita\u00e7\u00f5es bilion\u00e1rias e de PPPs de mobilidade urbana atraiu novos investidores<\/em><\/p>\n<p>At\u00e9 mesmo a CAF, que segundo fontes do setor estava com sua produ\u00e7\u00e3o no interior de S\u00e3o Paulo praticamente parada, voltou \u00e0 atividade. A empresa far\u00e1 a readequa\u00e7\u00e3o de carros de VLT (Ve\u00edculo Leve sobre Trilhos) que havia fabricado no passado para um projeto em Cuiab\u00e1 (MT), que n\u00e3o saiu do papel, e agora ser\u00e3o destinados ao governo da Bahia, para uma nova opera\u00e7\u00e3o em Salvador.<br \/>\n\u201c\u00c9 um momento especial para o setor. Nem na \u00e9poca da Copa do Mundo o mercado foi t\u00e3o aquecido no pa\u00eds como est\u00e1 agora. H\u00e1 realmente um \u2018boom\u2019 do setor metroferrovi\u00e1rio que nunca vi. Isso n\u00e3o s\u00f3 no Brasil, mas na Am\u00e9rica Latina, com muitas linhas novas\u201d, afirmou a diretora-geral da Alstom no Brasil, Suely Sola.<\/p>\n<p>Hoje, a f\u00e1brica da companhia em Taubat\u00e9 (SP) opera sem ociosidade, com projetos no Brasil e para exporta\u00e7\u00e3o. A empresa j\u00e1 tem diversos projetos no radar para manter o ritmo de produ\u00e7\u00e3o \u00e0 medida que as encomendas atuais forem entregues.<br \/>\nUma das licita\u00e7\u00f5es em estudo \u00e9 a PPP das Linhas 10 e 14 de trens urbanos em S\u00e3o Paulo, que a Alstom avalia disputar em cons\u00f3rcio com um grupo de constru\u00e7\u00e3o civil, segundo Sola. Em geral, a fabricante tem atuado nas concess\u00f5es como fornecedora, por\u00e9m agora poder\u00e1 se tornar operadora direta. O governo paulista planeja licitar ainda neste ano a concess\u00e3o &#8211; outra prov\u00e1vel concorrente no leil\u00e3o \u00e9 a chinesa CRRC.<br \/>\nSegundo a executiva, a estrat\u00e9gia de entrar no capital do projeto busca elevar a probabilidade de o grupo ser o fornecedor dos trens e dos sistemas de sinaliza\u00e7\u00e3o. Al\u00e9m disso, ela avalia que as condi\u00e7\u00f5es do edital s\u00e3o positivas, embora a empresa ainda esteja em di\u00e1logo com o Estado sobre sugest\u00f5es de mudan\u00e7as.<\/p>\n<p>Na vis\u00e3o de uma fonte, trata-se de uma forma de a empresa se manter competitiva diante do avan\u00e7o da chinesa no mercado brasileiro. A CRRC, que j\u00e1 conquistou PPPs em S\u00e3o Paulo e em Minas Gerais, decidiu instalar uma f\u00e1brica no pa\u00eds ap\u00f3s vencer uma concorr\u00eancia do Metr\u00f4 paulista para fornecer 44 trens. O investimento ser\u00e1 de R$ 50 milh\u00f5es a princ\u00edpio, o que foi visto no setor como uma indica\u00e7\u00e3o de que, por ora, a atividade ser\u00e1 limitada, apenas com a montagem final no local.<\/p>\n<blockquote><p><em><strong>Na vis\u00e3o de Vicente Abate, presidente da Associa\u00e7\u00e3o Brasileira da Ind\u00fastria Ferrovi\u00e1ria (ABIFER), a instala\u00e7\u00e3o da chinesa no pa\u00eds \u00e9 importante, porque traz isonomia tribut\u00e1ria com as empresas presentes no Brasil. \u201cQuando trazem os trens completos e a importa\u00e7\u00e3o \u00e9 feita pelo governo, h\u00e1 isen\u00e7\u00e3o tribut\u00e1ria, eles ficam mais competitivos. Mas, estando no Brasil, ter\u00e3o os mesmos benef\u00edcios e as mesmas agruras das demais fabricantes\u201d, disse.<\/strong><\/em><\/p><\/blockquote>\n<p>Hoje, a maior parte das oportunidades da ind\u00fastria est\u00e1 em S\u00e3o Paulo. Al\u00e9m do leil\u00e3o das linhas 10 e 14, outros projetos que dever\u00e3o sair at\u00e9 2026 s\u00e3o os aditivos de extens\u00e3o das linhas 4 e 5 do Metr\u00f4, em negocia\u00e7\u00e3o com a Motiva (ex-CCR); a extens\u00e3o da linha 6, da Acciona; e o Trem Intercidades de Sorocaba, que dever\u00e1 ter leil\u00e3o no pr\u00f3ximo ano. Adicionalmente, o governo dever\u00e1 abrir em agosto as audi\u00eancias p\u00fablicas para a nova linha 16, que est\u00e1 sendo estudada pela Acciona, segundo o secret\u00e1rio de parcerias em investimentos do Estado, Rafael Benini.<\/p>\n<p>\u201cAl\u00e9m disso, nos pr\u00f3ximos dez anos vai haver uma grande renova\u00e7\u00e3o da frota do Metr\u00f4 de S\u00e3o Paulo. O ciclo de vida de um trem \u00e9 de at\u00e9 50 anos aproximadamente, e o Metr\u00f4 completou 50 anos\u201d, afirmou o secret\u00e1rio.<\/p>\n<blockquote><p><em><strong>E<\/strong><strong><em>m<\/em> outros Estados, Abate cita tamb\u00e9m poss\u00edveis oportunidades de VLT em Curitiba, renova\u00e7\u00f5es de frota e expans\u00f5es no Metr\u00f4 de Bras\u00edlia, compra de trens no sistema do Rio Grande do Sul e eventuais projetos no Cear\u00e1, entre outros. \u201cNossa expectativa \u00e9 que esses sistemas de transporte v\u00e3o avan\u00e7ar e, com isso, naturalmente a ind\u00fastria ter\u00e1 um aumento das encomendas\u201d, disse.<\/strong><\/em><\/p><\/blockquote>\n<p>A Marcopolo Rail, cujo foco de atua\u00e7\u00e3o tem sido projetos de menor porte de VLT, trens regionais e tur\u00edsticos, tamb\u00e9m enxerga um potencial de crescimento do mercado. A companhia, criada como uma nova divis\u00e3o da Marcopolo em 2019, est\u00e1 finalizando a entrega dos trens para o \u201cpeople mover\u201d que ir\u00e1 conectar os trens urbanos de S\u00e3o Paulo ao aeroporto de Guarulhos, e dever\u00e1 fornecer trens para o VLT de Teresina.<br \/>\nHoje, a planta da empresa tem capacidade para produ\u00e7\u00e3o de at\u00e9 30 carros por ano, mas conforme novos projetos forem conquistados, a companhia planeja expandir a unidade, afirmou Petras Amaral Santos, gerente executivo da Marcopolo Rail. \u201cTemos mapeado o mercado e j\u00e1 vemos a possibilidade de aumento de volume de produ\u00e7\u00e3o\u201d, disse.<\/p>\n<p>ntre as oportunidades que interessam \u00e0 empresa est\u00e3o linhas entre cidades, como os projetos de Bras\u00edlia-Luzi\u00e2nia, Salvador-Feira de Santana, entre outros.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fonte: Valor Data: 05\/08\/2025 Onda de licita\u00e7\u00f5es bilion\u00e1rias e de PPPs de mobilidade urbana atraiu novos investidores At\u00e9 mesmo a CAF, que segundo fontes do setor estava com sua produ\u00e7\u00e3o no interior de S\u00e3o Paulo praticamente parada, voltou \u00e0 atividade. A empresa far\u00e1 a readequa\u00e7\u00e3o de carros de VLT (Ve\u00edculo Leve sobre Trilhos) que havia [&hellip;]<\/p>\n","protected":false},"author":55,"featured_media":88837,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[875],"tags":[],"class_list":["post-89604","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-do-mercado"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>ABIFER na m\u00eddia - Ind\u00fastria de trens de passageiros vive \u2018boom\u2019<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/abifer.org.br\/abifer-na-midia-industria-de-trens-de-passageiros-vive-boom\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ABIFER na m\u00eddia - Ind\u00fastria de trens de passageiros vive \u2018boom\u2019\" \/>\n<meta property=\"og:description\" content=\"Fonte: Valor Data: 05\/08\/2025 Onda de licita\u00e7\u00f5es bilion\u00e1rias e de PPPs de mobilidade urbana atraiu novos investidores At\u00e9 mesmo a CAF, que segundo fontes do setor estava com sua produ\u00e7\u00e3o no interior de S\u00e3o Paulo praticamente parada, voltou \u00e0 atividade. A empresa far\u00e1 a readequa\u00e7\u00e3o de carros de VLT (Ve\u00edculo Leve sobre Trilhos) que havia [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"http:\/\/abifer.org.br\/en\/abifer-na-midia-industria-de-trens-de-passageiros-vive-boom\/\" \/>\n<meta property=\"og:site_name\" content=\"ABIFER\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/abiferoficial\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-08-12T20:54:02+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/abifer.org.br\/wp-content\/uploads\/2025\/06\/mais-trilhos-brasil-logo-fundo-branco.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@abiferoficial\" \/>\n<meta name=\"twitter:site\" content=\"@abiferoficial\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"ABIFER\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/abifer.org.br\/en\/#organization\",\"name\":\"ABIFER\",\"url\":\"https:\/\/abifer.org.br\/en\/\",\"sameAs\":[\"https:\/\/www.facebook.com\/abiferoficial\/\",\"https:\/\/www.linkedin.com\/company\/abiferoficial\/\",\"https:\/\/twitter.com\/abiferoficial\"],\"logo\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/abifer.org.br\/en\/#logo\",\"inLanguage\":\"pt-BR\",\"url\":\"https:\/\/abifer.org.br\/wp-content\/uploads\/2018\/05\/ABF_001_LogoSlogan.jpg\",\"contentUrl\":\"https:\/\/abifer.org.br\/wp-content\/uploads\/2018\/05\/ABF_001_LogoSlogan.jpg\",\"width\":1182,\"height\":486,\"caption\":\"ABIFER\"},\"image\":{\"@id\":\"https:\/\/abifer.org.br\/en\/#logo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/abifer.org.br\/en\/#website\",\"url\":\"https:\/\/abifer.org.br\/en\/\",\"name\":\"ABIFER\",\"description\":\"Associa\u00e7\u00e3o Brasileira da Ind\u00fastria Ferrovi\u00e1ria\",\"publisher\":{\"@id\":\"https:\/\/abifer.org.br\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/abifer.org.br\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"ImageObject\",\"@id\":\"http:\/\/abifer.org.br\/en\/abifer-na-midia-industria-de-trens-de-passageiros-vive-boom\/#primaryimage\",\"inLanguage\":\"pt-BR\",\"url\":\"https:\/\/abifer.org.br\/wp-content\/uploads\/2025\/06\/mais-trilhos-brasil-logo-fundo-branco.jpeg\",\"contentUrl\":\"https:\/\/abifer.org.br\/wp-content\/uploads\/2025\/06\/mais-trilhos-brasil-logo-fundo-branco.jpeg\",\"width\":1024,\"height\":1024},{\"@type\":\"WebPage\",\"@id\":\"http:\/\/abifer.org.br\/en\/abifer-na-midia-industria-de-trens-de-passageiros-vive-boom\/#webpage\",\"url\":\"http:\/\/abifer.org.br\/en\/abifer-na-midia-industria-de-trens-de-passageiros-vive-boom\/\",\"name\":\"ABIFER na m\u00eddia - Ind\u00fastria de trens de passageiros vive \u2018boom\u2019\",\"isPartOf\":{\"@id\":\"https:\/\/abifer.org.br\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\/\/abifer.org.br\/en\/abifer-na-midia-industria-de-trens-de-passageiros-vive-boom\/#primaryimage\"},\"datePublished\":\"2025-08-12T20:54:02+00:00\",\"dateModified\":\"2025-08-12T20:54:02+00:00\",\"breadcrumb\":{\"@id\":\"http:\/\/abifer.org.br\/en\/abifer-na-midia-industria-de-trens-de-passageiros-vive-boom\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/abifer.org.br\/en\/abifer-na-midia-industria-de-trens-de-passageiros-vive-boom\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/abifer.org.br\/en\/abifer-na-midia-industria-de-trens-de-passageiros-vive-boom\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/abifer.org.br\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ABIFER na m\u00eddia &#8211; Ind\u00fastria de trens de passageiros vive \u2018boom\u2019\"}]},{\"@type\":\"Article\",\"@id\":\"http:\/\/abifer.org.br\/en\/abifer-na-midia-industria-de-trens-de-passageiros-vive-boom\/#article\",\"isPartOf\":{\"@id\":\"http:\/\/abifer.org.br\/en\/abifer-na-midia-industria-de-trens-de-passageiros-vive-boom\/#webpage\"},\"author\":{\"@id\":\"https:\/\/abifer.org.br\/en\/#\/schema\/person\/90c38c3286f60a11b363834930f79a1f\"},\"headline\":\"ABIFER na m\u00eddia &#8211; Ind\u00fastria de trens de passageiros vive \u2018boom\u2019\",\"datePublished\":\"2025-08-12T20:54:02+00:00\",\"dateModified\":\"2025-08-12T20:54:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\/\/abifer.org.br\/en\/abifer-na-midia-industria-de-trens-de-passageiros-vive-boom\/#webpage\"},\"wordCount\":872,\"publisher\":{\"@id\":\"https:\/\/abifer.org.br\/en\/#organization\"},\"image\":{\"@id\":\"http:\/\/abifer.org.br\/en\/abifer-na-midia-industria-de-trens-de-passageiros-vive-boom\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/abifer.org.br\/wp-content\/uploads\/2025\/06\/mais-trilhos-brasil-logo-fundo-branco.jpeg\",\"articleSection\":[\"Not\u00edcias do Mercado\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/abifer.org.br\/en\/#\/schema\/person\/90c38c3286f60a11b363834930f79a1f\",\"name\":\"ABIFER\",\"url\":\"https:\/\/abifer.org.br\/author\/abifer\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ABIFER na m\u00eddia - Ind\u00fastria de trens de passageiros vive \u2018boom\u2019","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/abifer.org.br\/abifer-na-midia-industria-de-trens-de-passageiros-vive-boom\/","og_locale":"pt_BR","og_type":"article","og_title":"ABIFER na m\u00eddia - Ind\u00fastria de trens de passageiros vive \u2018boom\u2019","og_description":"Fonte: Valor Data: 05\/08\/2025 Onda de licita\u00e7\u00f5es bilion\u00e1rias e de PPPs de mobilidade urbana atraiu novos investidores At\u00e9 mesmo a CAF, que segundo fontes do setor estava com sua produ\u00e7\u00e3o no interior de S\u00e3o Paulo praticamente parada, voltou \u00e0 atividade. A empresa far\u00e1 a readequa\u00e7\u00e3o de carros de VLT (Ve\u00edculo Leve sobre Trilhos) que havia [&hellip;]","og_url":"http:\/\/abifer.org.br\/en\/abifer-na-midia-industria-de-trens-de-passageiros-vive-boom\/","og_site_name":"ABIFER","article_publisher":"https:\/\/www.facebook.com\/abiferoficial\/","article_published_time":"2025-08-12T20:54:02+00:00","og_image":[{"width":1024,"height":1024,"url":"http:\/\/abifer.org.br\/wp-content\/uploads\/2025\/06\/mais-trilhos-brasil-logo-fundo-branco.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_creator":"@abiferoficial","twitter_site":"@abiferoficial","twitter_misc":{"Escrito por":"ABIFER","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Organization","@id":"https:\/\/abifer.org.br\/en\/#organization","name":"ABIFER","url":"https:\/\/abifer.org.br\/en\/","sameAs":["https:\/\/www.facebook.com\/abiferoficial\/","https:\/\/www.linkedin.com\/company\/abiferoficial\/","https:\/\/twitter.com\/abiferoficial"],"logo":{"@type":"ImageObject","@id":"https:\/\/abifer.org.br\/en\/#logo","inLanguage":"pt-BR","url":"https:\/\/abifer.org.br\/wp-content\/uploads\/2018\/05\/ABF_001_LogoSlogan.jpg","contentUrl":"https:\/\/abifer.org.br\/wp-content\/uploads\/2018\/05\/ABF_001_LogoSlogan.jpg","width":1182,"height":486,"caption":"ABIFER"},"image":{"@id":"https:\/\/abifer.org.br\/en\/#logo"}},{"@type":"WebSite","@id":"https:\/\/abifer.org.br\/en\/#website","url":"https:\/\/abifer.org.br\/en\/","name":"ABIFER","description":"Associa\u00e7\u00e3o Brasileira da Ind\u00fastria Ferrovi\u00e1ria","publisher":{"@id":"https:\/\/abifer.org.br\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/abifer.org.br\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"ImageObject","@id":"http:\/\/abifer.org.br\/en\/abifer-na-midia-industria-de-trens-de-passageiros-vive-boom\/#primaryimage","inLanguage":"pt-BR","url":"https:\/\/abifer.org.br\/wp-content\/uploads\/2025\/06\/mais-trilhos-brasil-logo-fundo-branco.jpeg","contentUrl":"https:\/\/abifer.org.br\/wp-content\/uploads\/2025\/06\/mais-trilhos-brasil-logo-fundo-branco.jpeg","width":1024,"height":1024},{"@type":"WebPage","@id":"http:\/\/abifer.org.br\/en\/abifer-na-midia-industria-de-trens-de-passageiros-vive-boom\/#webpage","url":"http:\/\/abifer.org.br\/en\/abifer-na-midia-industria-de-trens-de-passageiros-vive-boom\/","name":"ABIFER na m\u00eddia - Ind\u00fastria de trens de passageiros vive \u2018boom\u2019","isPartOf":{"@id":"https:\/\/abifer.org.br\/en\/#website"},"primaryImageOfPage":{"@id":"http:\/\/abifer.org.br\/en\/abifer-na-midia-industria-de-trens-de-passageiros-vive-boom\/#primaryimage"},"datePublished":"2025-08-12T20:54:02+00:00","dateModified":"2025-08-12T20:54:02+00:00","breadcrumb":{"@id":"http:\/\/abifer.org.br\/en\/abifer-na-midia-industria-de-trens-de-passageiros-vive-boom\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["http:\/\/abifer.org.br\/en\/abifer-na-midia-industria-de-trens-de-passageiros-vive-boom\/"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/abifer.org.br\/en\/abifer-na-midia-industria-de-trens-de-passageiros-vive-boom\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/abifer.org.br\/en\/"},{"@type":"ListItem","position":2,"name":"ABIFER na m\u00eddia &#8211; Ind\u00fastria de trens de passageiros vive \u2018boom\u2019"}]},{"@type":"Article","@id":"http:\/\/abifer.org.br\/en\/abifer-na-midia-industria-de-trens-de-passageiros-vive-boom\/#article","isPartOf":{"@id":"http:\/\/abifer.org.br\/en\/abifer-na-midia-industria-de-trens-de-passageiros-vive-boom\/#webpage"},"author":{"@id":"https:\/\/abifer.org.br\/en\/#\/schema\/person\/90c38c3286f60a11b363834930f79a1f"},"headline":"ABIFER na m\u00eddia &#8211; Ind\u00fastria de trens de passageiros vive \u2018boom\u2019","datePublished":"2025-08-12T20:54:02+00:00","dateModified":"2025-08-12T20:54:02+00:00","mainEntityOfPage":{"@id":"http:\/\/abifer.org.br\/en\/abifer-na-midia-industria-de-trens-de-passageiros-vive-boom\/#webpage"},"wordCount":872,"publisher":{"@id":"https:\/\/abifer.org.br\/en\/#organization"},"image":{"@id":"http:\/\/abifer.org.br\/en\/abifer-na-midia-industria-de-trens-de-passageiros-vive-boom\/#primaryimage"},"thumbnailUrl":"https:\/\/abifer.org.br\/wp-content\/uploads\/2025\/06\/mais-trilhos-brasil-logo-fundo-branco.jpeg","articleSection":["Not\u00edcias do Mercado"],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/abifer.org.br\/en\/#\/schema\/person\/90c38c3286f60a11b363834930f79a1f","name":"ABIFER","url":"https:\/\/abifer.org.br\/author\/abifer\/"}]}},"_links":{"self":[{"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/posts\/89604\/"}],"collection":[{"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/posts\/"}],"about":[{"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/types\/post\/"}],"author":[{"embeddable":true,"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/users\/55\/"}],"replies":[{"embeddable":true,"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/comments\/?post=89604"}],"version-history":[{"count":1,"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/posts\/89604\/revisions\/"}],"predecessor-version":[{"id":89605,"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/posts\/89604\/revisions\/89605\/"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/media\/88837\/"}],"wp:attachment":[{"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/media\/?parent=89604"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/categories\/?post=89604"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/tags\/?post=89604"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}