{"id":90889,"date":"2025-10-27T18:52:42","date_gmt":"2025-10-27T21:52:42","guid":{"rendered":"https:\/\/abifer.org.br\/?p=90889"},"modified":"2025-10-27T18:52:42","modified_gmt":"2025-10-27T21:52:42","slug":"trem-entre-porto-alegre-e-gramado-fara-viagem-de-1h-em-2032-veja-como-sera-o-trajeto-expresso","status":"publish","type":"post","link":"https:\/\/abifer.org.br\/en\/trem-entre-porto-alegre-e-gramado-fara-viagem-de-1h-em-2032-veja-como-sera-o-trajeto-expresso\/","title":{"rendered":"Trem entre Porto Alegre e Gramado far\u00e1 viagem de 1h em 2032; veja como ser\u00e1 o trajeto expresso"},"content":{"rendered":"<pre style=\"text-align: right;\"><a href=\"https:\/\/www.estadao.com.br\/viagem\/trem-entre-porto-alegre-e-gramado-fara-viagem-de-1h-em-2032-veja-como-sera-o-trajeto-expresso\/\" target=\"_blank\" rel=\"noopener\"><strong><em>Fonte: Estad\u00e3o\r\nData: 25\/10\/2025<\/em><\/strong><\/a><\/pre>\n<p>De Porto Alegre a Gramado em apenas uma hora \u2013 e n\u00e3o ser\u00e1 de carro. Esse \u00e9 o tempo que o viajante levar\u00e1 para percorrer a dist\u00e2ncia entre as duas cidades quando elas estiverem interligadas pelo trem expresso em 2032. O projeto de constru\u00e7\u00e3o da ferrovia foi autorizado pelo governo do Rio Grande do Sul e a concession\u00e1ria SulTrens prev\u00ea o in\u00edcio de obras para 2029. A linha ter\u00e1 como ponto de partida o Aeroporto Internacional Salgado Filho e chegada pela Avenida das Hort\u00eansias, entre Gramado e Canela. Hoje esse trajeto leva no m\u00ednimo duas horas para ser percorrido.<\/p>\n<p>\u201cQuem chega ao aeroporto de Porto Alegre com destino a Gramado precisa pegar uma van ou alugar um carro para subir a serra, em um trajeto que pode durar at\u00e9 quatro horas. Com o trem, haver\u00e1 uma passarela climatizada, com esteira rolante, de 700 metros at\u00e9 a esta\u00e7\u00e3o. O turista vai acessar o trem e chegar a Gramado em at\u00e9 uma hora\u201d, afirmou o administrador da SulTrens, Renato Ely.<\/p>\n<p>Ser\u00e3o duas linhas f\u00e9rreas com at\u00e9 dez trens de passageiros, que v\u00e3o cruzar e impactar 22 cidades ao longo do percurso. A previs\u00e3o \u00e9 que o novo modal fa\u00e7a at\u00e9 28 viagens por dia, com sa\u00eddas planejadas no per\u00edodo das 7h \u00e0s 22h. N\u00e3o foi definido ainda qual dever\u00e1 ser o valor das passagens. A expectativa para o primeiro ano \u00e9 de transportar 2 milh\u00f5es de passageiros.<\/p>\n<p>Impulso \u00e0 economia local<\/p>\n<p>O trajeto incluir\u00e1 27 cruzamentos rodoferrovi\u00e1rios, 15 pontes e viadutos e 9 t\u00faneis. O contrato tem investimento previsto na ordem de R$ 4,5 bilh\u00f5es e dura\u00e7\u00e3o de 99 anos, prorrog\u00e1veis por outros 99. A estimativa \u00e9 que a obra gere mais de 22 mil empregos diretos e indiretos.<\/p>\n<p>Com o objetivo de gerar recursos financeiros para a obra, ser\u00e3o constru\u00eddos dois condom\u00ednios no curso da ferrovia, em local a ser definido. \u201cO trem vai ter parada nesses pontos exclusivos, levando os moradores para Gramado, Canela ou Porto Alegre\u201d, completou Ely. Por enquanto, s\u00e3o as \u00fanicas paradas previstas para o trajeto.<\/p>\n<p>O secret\u00e1rio de transportes do Rio Grande do Sul, Juvir Costella, ressalta que o novo modal se soma aos outros meios poss\u00edveis para chegar \u00e0 Serra Ga\u00facha e vai impulsionar o turismo na regi\u00e3o. \u201cTemos o Aeroporto de Canela\u00a0<em>(para aeronaves de pequeno porte)<\/em>, as estradas e as rodovi\u00e1rias e, agora, o ferrovi\u00e1rio\u201d.<\/p>\n<h3 id=\"gramado-visitantes-o-ano-todo\" class=\"wp-block-heading\">Gramado: visitantes o ano todo<\/h3>\n<p>Diante da perspectiva de receber mais turistas, o secret\u00e1rio de Turismo de Gramado, Ricardo Bertolucci, explica que o poder p\u00fablico tem projetos de melhoria de infraestrutura e servi\u00e7os da cidade, hoje com 40 mil habitantes, de acordo com o \u00faltimo Censo do Instituto Brasileiro de Geografia e Estat\u00edstica (IBGE).<\/p>\n<p>\u201cDentre eles, desenvolver um novo territ\u00f3rio urbano em uma \u00e1rea que n\u00e3o \u00e9 habitada na cidade atualmente. Vamos fazer um planejamento urbano de empreendimentos e moradia. Outro ponto \u00e9 descentralizar os servi\u00e7os p\u00fablicos: escolas e prefeituras, por exemplo, podem sair da regi\u00e3o central\u201d, informou Bertolucci.<\/p>\n<p>Para o CEO da Gramado Parks, rede de hot\u00e9is e parques na cidade, Ronaldo Costa Beber, a nova possibilidade de transporte pode ajudar a diminuir a sazonalidade do turismo na regi\u00e3o, somada \u00e0s atratividades tur\u00edsticas. \u201cA gente tem trabalhado para diminuir essas t\u00f4nicas entre os per\u00edodos mais cheios de Gramado, como a P\u00e1scoa, o inverno e o Natal Luz. Eventos como a Oktoberfest e o Festival de Cinema, por exemplo, entre a alta temporada, junto com as novas possibilidades de transportes, fazem com que a cidade atenda turistas o ano inteiro\u201d, contou.<\/p>\n<h3 id=\"porto-alegre-mais-do-que-passagem\" class=\"wp-block-heading\">Porto Alegre: mais do que passagem<\/h3>\n<p>Do outro lado da linha, Porto Alegre come\u00e7a a planejar como atrair os turistas com destino \u00e0 Serra Ga\u00facha, evitando que seja apenas uma cidade de passagem. \u201cTemos at\u00e9 2032 para pensar em maneiras de reten\u00e7\u00e3o do turista que veio para subir a serra, tornar Porto Alegre um local atrativo para os estrangeiros tamb\u00e9m\u201d, comenta a secret\u00e1ria de Turismo de Porto Alegre, Fernanda Barth. \u201cCom certeza, num primeiro momento, vamos trabalhar o receptivo para quem mora em Gramado e se sente prejudicado durante a alta temporada\u201d, diz ela, referindo-se ao deslocamento de moradores da serra \u00e0 capital.<\/p>\n<p>Segundo a secret\u00e1ria, a cidade busca se firmar como a capital mundial do churrasco, fortalecer o polo cervejeiro e se consolidar como destino esportivo, com a constru\u00e7\u00e3o do polo n\u00e1utico a partir de 2026.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fonte: Estad\u00e3o Data: 25\/10\/2025 De Porto Alegre a Gramado em apenas uma hora \u2013 e n\u00e3o ser\u00e1 de carro. Esse \u00e9 o tempo que o viajante levar\u00e1 para percorrer a dist\u00e2ncia entre as duas cidades quando elas estiverem interligadas pelo trem expresso em 2032. O projeto de constru\u00e7\u00e3o da ferrovia foi autorizado pelo governo do [&hellip;]<\/p>\n","protected":false},"author":55,"featured_media":88837,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[875],"tags":[],"class_list":["post-90889","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-do-mercado"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Trem entre Porto Alegre e Gramado far\u00e1 viagem de 1h em 2032; veja como ser\u00e1 o trajeto expresso<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/abifer.org.br\/trem-entre-porto-alegre-e-gramado-fara-viagem-de-1h-em-2032-veja-como-sera-o-trajeto-expresso\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Trem entre Porto Alegre e Gramado far\u00e1 viagem de 1h em 2032; veja como ser\u00e1 o trajeto expresso\" \/>\n<meta property=\"og:description\" content=\"Fonte: Estad\u00e3o Data: 25\/10\/2025 De Porto Alegre a Gramado em apenas uma hora \u2013 e n\u00e3o ser\u00e1 de carro. Esse \u00e9 o tempo que o viajante levar\u00e1 para percorrer a dist\u00e2ncia entre as duas cidades quando elas estiverem interligadas pelo trem expresso em 2032. O projeto de constru\u00e7\u00e3o da ferrovia foi autorizado pelo governo do [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/abifer.org.br\/en\/trem-entre-porto-alegre-e-gramado-fara-viagem-de-1h-em-2032-veja-como-sera-o-trajeto-expresso\/\" \/>\n<meta property=\"og:site_name\" content=\"ABIFER\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/abiferoficial\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-27T21:52:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/abifer.org.br\/wp-content\/uploads\/2025\/06\/mais-trilhos-brasil-logo-fundo-branco.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@abiferoficial\" \/>\n<meta name=\"twitter:site\" content=\"@abiferoficial\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"ABIFER\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/abifer.org.br\/en\/#organization\",\"name\":\"ABIFER\",\"url\":\"https:\/\/abifer.org.br\/en\/\",\"sameAs\":[\"https:\/\/www.facebook.com\/abiferoficial\/\",\"https:\/\/www.linkedin.com\/company\/abiferoficial\/\",\"https:\/\/twitter.com\/abiferoficial\"],\"logo\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/abifer.org.br\/en\/#logo\",\"inLanguage\":\"pt-BR\",\"url\":\"https:\/\/abifer.org.br\/wp-content\/uploads\/2018\/05\/ABF_001_LogoSlogan.jpg\",\"contentUrl\":\"https:\/\/abifer.org.br\/wp-content\/uploads\/2018\/05\/ABF_001_LogoSlogan.jpg\",\"width\":1182,\"height\":486,\"caption\":\"ABIFER\"},\"image\":{\"@id\":\"https:\/\/abifer.org.br\/en\/#logo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/abifer.org.br\/en\/#website\",\"url\":\"https:\/\/abifer.org.br\/en\/\",\"name\":\"ABIFER\",\"description\":\"Associa\u00e7\u00e3o Brasileira da Ind\u00fastria Ferrovi\u00e1ria\",\"publisher\":{\"@id\":\"https:\/\/abifer.org.br\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/abifer.org.br\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/abifer.org.br\/en\/trem-entre-porto-alegre-e-gramado-fara-viagem-de-1h-em-2032-veja-como-sera-o-trajeto-expresso\/#primaryimage\",\"inLanguage\":\"pt-BR\",\"url\":\"https:\/\/abifer.org.br\/wp-content\/uploads\/2025\/06\/mais-trilhos-brasil-logo-fundo-branco.jpeg\",\"contentUrl\":\"https:\/\/abifer.org.br\/wp-content\/uploads\/2025\/06\/mais-trilhos-brasil-logo-fundo-branco.jpeg\",\"width\":1024,\"height\":1024},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/abifer.org.br\/en\/trem-entre-porto-alegre-e-gramado-fara-viagem-de-1h-em-2032-veja-como-sera-o-trajeto-expresso\/#webpage\",\"url\":\"https:\/\/abifer.org.br\/en\/trem-entre-porto-alegre-e-gramado-fara-viagem-de-1h-em-2032-veja-como-sera-o-trajeto-expresso\/\",\"name\":\"Trem entre Porto Alegre e Gramado far\u00e1 viagem de 1h em 2032; veja como ser\u00e1 o trajeto expresso\",\"isPartOf\":{\"@id\":\"https:\/\/abifer.org.br\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/abifer.org.br\/en\/trem-entre-porto-alegre-e-gramado-fara-viagem-de-1h-em-2032-veja-como-sera-o-trajeto-expresso\/#primaryimage\"},\"datePublished\":\"2025-10-27T21:52:42+00:00\",\"dateModified\":\"2025-10-27T21:52:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/abifer.org.br\/en\/trem-entre-porto-alegre-e-gramado-fara-viagem-de-1h-em-2032-veja-como-sera-o-trajeto-expresso\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/abifer.org.br\/en\/trem-entre-porto-alegre-e-gramado-fara-viagem-de-1h-em-2032-veja-como-sera-o-trajeto-expresso\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/abifer.org.br\/en\/trem-entre-porto-alegre-e-gramado-fara-viagem-de-1h-em-2032-veja-como-sera-o-trajeto-expresso\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/abifer.org.br\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Trem entre Porto Alegre e Gramado far\u00e1 viagem de 1h em 2032; veja como ser\u00e1 o trajeto expresso\"}]},{\"@type\":\"Article\",\"@id\":\"https:\/\/abifer.org.br\/en\/trem-entre-porto-alegre-e-gramado-fara-viagem-de-1h-em-2032-veja-como-sera-o-trajeto-expresso\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/abifer.org.br\/en\/trem-entre-porto-alegre-e-gramado-fara-viagem-de-1h-em-2032-veja-como-sera-o-trajeto-expresso\/#webpage\"},\"author\":{\"@id\":\"https:\/\/abifer.org.br\/en\/#\/schema\/person\/90c38c3286f60a11b363834930f79a1f\"},\"headline\":\"Trem entre Porto Alegre e Gramado far\u00e1 viagem de 1h em 2032; veja como ser\u00e1 o trajeto expresso\",\"datePublished\":\"2025-10-27T21:52:42+00:00\",\"dateModified\":\"2025-10-27T21:52:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/abifer.org.br\/en\/trem-entre-porto-alegre-e-gramado-fara-viagem-de-1h-em-2032-veja-como-sera-o-trajeto-expresso\/#webpage\"},\"wordCount\":765,\"publisher\":{\"@id\":\"https:\/\/abifer.org.br\/en\/#organization\"},\"image\":{\"@id\":\"https:\/\/abifer.org.br\/en\/trem-entre-porto-alegre-e-gramado-fara-viagem-de-1h-em-2032-veja-como-sera-o-trajeto-expresso\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/abifer.org.br\/wp-content\/uploads\/2025\/06\/mais-trilhos-brasil-logo-fundo-branco.jpeg\",\"articleSection\":[\"Not\u00edcias do Mercado\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/abifer.org.br\/en\/#\/schema\/person\/90c38c3286f60a11b363834930f79a1f\",\"name\":\"ABIFER\",\"url\":\"https:\/\/abifer.org.br\/author\/abifer\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Trem entre Porto Alegre e Gramado far\u00e1 viagem de 1h em 2032; veja como ser\u00e1 o trajeto expresso","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/abifer.org.br\/trem-entre-porto-alegre-e-gramado-fara-viagem-de-1h-em-2032-veja-como-sera-o-trajeto-expresso\/","og_locale":"pt_BR","og_type":"article","og_title":"Trem entre Porto Alegre e Gramado far\u00e1 viagem de 1h em 2032; veja como ser\u00e1 o trajeto expresso","og_description":"Fonte: Estad\u00e3o Data: 25\/10\/2025 De Porto Alegre a Gramado em apenas uma hora \u2013 e n\u00e3o ser\u00e1 de carro. Esse \u00e9 o tempo que o viajante levar\u00e1 para percorrer a dist\u00e2ncia entre as duas cidades quando elas estiverem interligadas pelo trem expresso em 2032. O projeto de constru\u00e7\u00e3o da ferrovia foi autorizado pelo governo do [&hellip;]","og_url":"https:\/\/abifer.org.br\/en\/trem-entre-porto-alegre-e-gramado-fara-viagem-de-1h-em-2032-veja-como-sera-o-trajeto-expresso\/","og_site_name":"ABIFER","article_publisher":"https:\/\/www.facebook.com\/abiferoficial\/","article_published_time":"2025-10-27T21:52:42+00:00","og_image":[{"width":1024,"height":1024,"url":"https:\/\/abifer.org.br\/wp-content\/uploads\/2025\/06\/mais-trilhos-brasil-logo-fundo-branco.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_creator":"@abiferoficial","twitter_site":"@abiferoficial","twitter_misc":{"Escrito por":"ABIFER","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Organization","@id":"https:\/\/abifer.org.br\/en\/#organization","name":"ABIFER","url":"https:\/\/abifer.org.br\/en\/","sameAs":["https:\/\/www.facebook.com\/abiferoficial\/","https:\/\/www.linkedin.com\/company\/abiferoficial\/","https:\/\/twitter.com\/abiferoficial"],"logo":{"@type":"ImageObject","@id":"https:\/\/abifer.org.br\/en\/#logo","inLanguage":"pt-BR","url":"https:\/\/abifer.org.br\/wp-content\/uploads\/2018\/05\/ABF_001_LogoSlogan.jpg","contentUrl":"https:\/\/abifer.org.br\/wp-content\/uploads\/2018\/05\/ABF_001_LogoSlogan.jpg","width":1182,"height":486,"caption":"ABIFER"},"image":{"@id":"https:\/\/abifer.org.br\/en\/#logo"}},{"@type":"WebSite","@id":"https:\/\/abifer.org.br\/en\/#website","url":"https:\/\/abifer.org.br\/en\/","name":"ABIFER","description":"Associa\u00e7\u00e3o Brasileira da Ind\u00fastria Ferrovi\u00e1ria","publisher":{"@id":"https:\/\/abifer.org.br\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/abifer.org.br\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"ImageObject","@id":"https:\/\/abifer.org.br\/en\/trem-entre-porto-alegre-e-gramado-fara-viagem-de-1h-em-2032-veja-como-sera-o-trajeto-expresso\/#primaryimage","inLanguage":"pt-BR","url":"https:\/\/abifer.org.br\/wp-content\/uploads\/2025\/06\/mais-trilhos-brasil-logo-fundo-branco.jpeg","contentUrl":"https:\/\/abifer.org.br\/wp-content\/uploads\/2025\/06\/mais-trilhos-brasil-logo-fundo-branco.jpeg","width":1024,"height":1024},{"@type":"WebPage","@id":"https:\/\/abifer.org.br\/en\/trem-entre-porto-alegre-e-gramado-fara-viagem-de-1h-em-2032-veja-como-sera-o-trajeto-expresso\/#webpage","url":"https:\/\/abifer.org.br\/en\/trem-entre-porto-alegre-e-gramado-fara-viagem-de-1h-em-2032-veja-como-sera-o-trajeto-expresso\/","name":"Trem entre Porto Alegre e Gramado far\u00e1 viagem de 1h em 2032; veja como ser\u00e1 o trajeto expresso","isPartOf":{"@id":"https:\/\/abifer.org.br\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/abifer.org.br\/en\/trem-entre-porto-alegre-e-gramado-fara-viagem-de-1h-em-2032-veja-como-sera-o-trajeto-expresso\/#primaryimage"},"datePublished":"2025-10-27T21:52:42+00:00","dateModified":"2025-10-27T21:52:42+00:00","breadcrumb":{"@id":"https:\/\/abifer.org.br\/en\/trem-entre-porto-alegre-e-gramado-fara-viagem-de-1h-em-2032-veja-como-sera-o-trajeto-expresso\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/abifer.org.br\/en\/trem-entre-porto-alegre-e-gramado-fara-viagem-de-1h-em-2032-veja-como-sera-o-trajeto-expresso\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/abifer.org.br\/en\/trem-entre-porto-alegre-e-gramado-fara-viagem-de-1h-em-2032-veja-como-sera-o-trajeto-expresso\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/abifer.org.br\/en\/"},{"@type":"ListItem","position":2,"name":"Trem entre Porto Alegre e Gramado far\u00e1 viagem de 1h em 2032; veja como ser\u00e1 o trajeto expresso"}]},{"@type":"Article","@id":"https:\/\/abifer.org.br\/en\/trem-entre-porto-alegre-e-gramado-fara-viagem-de-1h-em-2032-veja-como-sera-o-trajeto-expresso\/#article","isPartOf":{"@id":"https:\/\/abifer.org.br\/en\/trem-entre-porto-alegre-e-gramado-fara-viagem-de-1h-em-2032-veja-como-sera-o-trajeto-expresso\/#webpage"},"author":{"@id":"https:\/\/abifer.org.br\/en\/#\/schema\/person\/90c38c3286f60a11b363834930f79a1f"},"headline":"Trem entre Porto Alegre e Gramado far\u00e1 viagem de 1h em 2032; veja como ser\u00e1 o trajeto expresso","datePublished":"2025-10-27T21:52:42+00:00","dateModified":"2025-10-27T21:52:42+00:00","mainEntityOfPage":{"@id":"https:\/\/abifer.org.br\/en\/trem-entre-porto-alegre-e-gramado-fara-viagem-de-1h-em-2032-veja-como-sera-o-trajeto-expresso\/#webpage"},"wordCount":765,"publisher":{"@id":"https:\/\/abifer.org.br\/en\/#organization"},"image":{"@id":"https:\/\/abifer.org.br\/en\/trem-entre-porto-alegre-e-gramado-fara-viagem-de-1h-em-2032-veja-como-sera-o-trajeto-expresso\/#primaryimage"},"thumbnailUrl":"https:\/\/abifer.org.br\/wp-content\/uploads\/2025\/06\/mais-trilhos-brasil-logo-fundo-branco.jpeg","articleSection":["Not\u00edcias do Mercado"],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/abifer.org.br\/en\/#\/schema\/person\/90c38c3286f60a11b363834930f79a1f","name":"ABIFER","url":"https:\/\/abifer.org.br\/author\/abifer\/"}]}},"_links":{"self":[{"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/posts\/90889\/"}],"collection":[{"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/posts\/"}],"about":[{"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/types\/post\/"}],"author":[{"embeddable":true,"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/users\/55\/"}],"replies":[{"embeddable":true,"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/comments\/?post=90889"}],"version-history":[{"count":1,"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/posts\/90889\/revisions\/"}],"predecessor-version":[{"id":90890,"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/posts\/90889\/revisions\/90890\/"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/media\/88837\/"}],"wp:attachment":[{"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/media\/?parent=90889"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/categories\/?post=90889"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/tags\/?post=90889"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}