{"id":90893,"date":"2025-10-27T19:07:53","date_gmt":"2025-10-27T22:07:53","guid":{"rendered":"https:\/\/abifer.org.br\/?p=90893"},"modified":"2025-10-27T19:07:53","modified_gmt":"2025-10-27T22:07:53","slug":"renovacao-da-fca-antt-analisa-incluir-contorno-de-belo-horizonte-no-contrato","status":"publish","type":"post","link":"https:\/\/abifer.org.br\/en\/renovacao-da-fca-antt-analisa-incluir-contorno-de-belo-horizonte-no-contrato\/","title":{"rendered":"Renova\u00e7\u00e3o da FCA: ANTT analisa incluir contorno de Belo Horizonte no contrato"},"content":{"rendered":"<pre style=\"text-align: right;\"><a href=\"https:\/\/www.agazeta.com.br\/es\/economia\/renovacao-da-fca-antt-analisa-incluir-contorno-de-belo-horizonte-no-contrato-1025\" target=\"_blank\" rel=\"noopener\"><strong><em>Fonte: A Gazeta\r\nData: 24\/10\/2025<\/em><\/strong><\/a><\/pre>\n<p>A Ag\u00eancia Nacional dos Transportes Terrestres (ANTT) est\u00e1 avaliando as propostas feitas pelos governos do Esp\u00edrito Santo e Minas Gerais para a constru\u00e7\u00e3o do contorno ferrovi\u00e1rio de Belo Horizonte em substitui\u00e7\u00e3o ao da Serra do Tigre. Essa alternativa \u00e9 um pedido dos Estados para ser realizada a renova\u00e7\u00e3o da concess\u00e3o da Ferrovia Centro-Atl\u00e2ntica (FCA), controlada pela VLI, at\u00e9 2056.<\/p>\n<p id=\"paragrafo-fyinzvlbml\">A negocia\u00e7\u00e3o prev\u00ea a extens\u00e3o da vig\u00eancia por mais 30 anos, com investimentos de cerca de R$ 30 bilh\u00f5es. O ministro dos Transportes,\u00a0Renan Filho, chegou a informar que a decis\u00e3o sobre o caso sairia at\u00e9 agosto, mas o contrato segue em avalia\u00e7\u00e3o na ANTT, que analisa o pedido do Esp\u00edrito Santo feito com Minas Gerais.<\/p>\n<p id=\"paragrafo-cwz6d6dpap\">Durante evento no Estado para\u00a0libera\u00e7\u00e3o de um trecho de sete quil\u00f4metros de duplica\u00e7\u00e3o da BR 101 entre Guarapari e Anchieta, o diretor da ANTT, Guilherme Theo Sampaio, afirmou que\u00a0renova\u00e7\u00e3o da FCA est\u00e1 atualmente em fase de refinamento na ag\u00eancia, ressaltando que ainda h\u00e1 tempo h\u00e1bil para analisar os pedidos dos Estados antes da decis\u00e3o final.<\/p>\n<p>\u201cN\u00f3s estamos refinando o trabalho, vendo que est\u00e1 aderente e o que precisa melhorar para mandar pro Tribunal de Contas da Uni\u00e3o.\u00a0\u00a0Estamos dialogando com a concession\u00e1ria e com os Estados de Minas Gerais e do Esp\u00edrito Santo para ver a melhor forma de endere\u00e7ar esse anseio\u201d, afirmou Sampaio, sobre incluir os pedidos dos Estados na avalia\u00e7\u00e3o final da renova\u00e7\u00e3o do contrato.<\/p>\n<p id=\"paragrafo-os0up2hzt4\">Para o governador\u00a0Renato Casagrande\u00a0(PSB),\u00a0a principal quest\u00e3o em debate \u00e9 a inclus\u00e3o de obras estruturais no projeto de renova\u00e7\u00e3o, como o contorno de Belo Horizonte. Casagrande lembrou que o Estado est\u00e1 debatendo essa quest\u00e3o com o Minist\u00e9rio dos Transportes visando uma ferrovia mais moderna.<\/p>\n<p id=\"paragrafo-gs329t11fl\">A proposta \u00e9 a constru\u00e7\u00e3o do contorno ferrovi\u00e1rio de Belo Horizonte, que passaria por Vespasiano e Itabira. Esse ramal substituiria a ideia inicial do contorno da Serra do Tigre, em Minas Gerais, que previa a constru\u00e7\u00e3o de um trecho ferrovi\u00e1rio com mais de 450 quil\u00f4metros, um investimento que vem sendo descartado por ser considerado de alto valor. O objetivo desse contorno \u00e9 melhorar a liga\u00e7\u00e3o entre o Centro-Oeste, o Estado mineiro e o Esp\u00edrito Santo.<\/p>\n<p id=\"paragrafo-lelnh68p0q\">A FCA tem tra\u00e7ado no Esp\u00edrito Santo. A VLI, por\u00e9m, n\u00e3o usa o trecho local. Apenas transporta cargas por direito de passagem na Estrada de Ferro Vit\u00f3ria a Minas (EFVM), controlada pela Vale.<\/p>\n<p id=\"paragrafo-b3gdlayt4s\">A concess\u00e3o atual da FCA expira em agosto de 2026. A ferrovia tem 7,2 mil quil\u00f4metros de extens\u00e3o e cruza os Estados de Bahia, Esp\u00edrito Santo, Goi\u00e1s, Minas Gerais, Rio de Janeiro, S\u00e3o Paulo e Sergipe, al\u00e9m do Distrito Federal.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fonte: A Gazeta Data: 24\/10\/2025 A Ag\u00eancia Nacional dos Transportes Terrestres (ANTT) est\u00e1 avaliando as propostas feitas pelos governos do Esp\u00edrito Santo e Minas Gerais para a constru\u00e7\u00e3o do contorno ferrovi\u00e1rio de Belo Horizonte em substitui\u00e7\u00e3o ao da Serra do Tigre. Essa alternativa \u00e9 um pedido dos Estados para ser realizada a renova\u00e7\u00e3o da concess\u00e3o [&hellip;]<\/p>\n","protected":false},"author":55,"featured_media":88837,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[875],"tags":[],"class_list":["post-90893","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-do-mercado"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Renova\u00e7\u00e3o da FCA: ANTT analisa incluir contorno de Belo Horizonte no contrato<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/abifer.org.br\/renovacao-da-fca-antt-analisa-incluir-contorno-de-belo-horizonte-no-contrato\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Renova\u00e7\u00e3o da FCA: ANTT analisa incluir contorno de Belo Horizonte no contrato\" \/>\n<meta property=\"og:description\" content=\"Fonte: A Gazeta Data: 24\/10\/2025 A Ag\u00eancia Nacional dos Transportes Terrestres (ANTT) est\u00e1 avaliando as propostas feitas pelos governos do Esp\u00edrito Santo e Minas Gerais para a constru\u00e7\u00e3o do contorno ferrovi\u00e1rio de Belo Horizonte em substitui\u00e7\u00e3o ao da Serra do Tigre. Essa alternativa \u00e9 um pedido dos Estados para ser realizada a renova\u00e7\u00e3o da concess\u00e3o [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/abifer.org.br\/renovacao-da-fca-antt-analisa-incluir-contorno-de-belo-horizonte-no-contrato\/\" \/>\n<meta property=\"og:site_name\" content=\"ABIFER\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/abiferoficial\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-27T22:07:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/abifer.org.br\/wp-content\/uploads\/2025\/06\/mais-trilhos-brasil-logo-fundo-branco.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@abiferoficial\" \/>\n<meta name=\"twitter:site\" content=\"@abiferoficial\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"ABIFER\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/abifer.org.br\/en\/#organization\",\"name\":\"ABIFER\",\"url\":\"https:\/\/abifer.org.br\/en\/\",\"sameAs\":[\"https:\/\/www.facebook.com\/abiferoficial\/\",\"https:\/\/www.linkedin.com\/company\/abiferoficial\/\",\"https:\/\/twitter.com\/abiferoficial\"],\"logo\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/abifer.org.br\/en\/#logo\",\"inLanguage\":\"pt-BR\",\"url\":\"https:\/\/abifer.org.br\/wp-content\/uploads\/2018\/05\/ABF_001_LogoSlogan.jpg\",\"contentUrl\":\"https:\/\/abifer.org.br\/wp-content\/uploads\/2018\/05\/ABF_001_LogoSlogan.jpg\",\"width\":1182,\"height\":486,\"caption\":\"ABIFER\"},\"image\":{\"@id\":\"https:\/\/abifer.org.br\/en\/#logo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/abifer.org.br\/en\/#website\",\"url\":\"https:\/\/abifer.org.br\/en\/\",\"name\":\"ABIFER\",\"description\":\"Associa\u00e7\u00e3o Brasileira da Ind\u00fastria Ferrovi\u00e1ria\",\"publisher\":{\"@id\":\"https:\/\/abifer.org.br\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/abifer.org.br\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/abifer.org.br\/renovacao-da-fca-antt-analisa-incluir-contorno-de-belo-horizonte-no-contrato\/#primaryimage\",\"inLanguage\":\"pt-BR\",\"url\":\"https:\/\/abifer.org.br\/wp-content\/uploads\/2025\/06\/mais-trilhos-brasil-logo-fundo-branco.jpeg\",\"contentUrl\":\"https:\/\/abifer.org.br\/wp-content\/uploads\/2025\/06\/mais-trilhos-brasil-logo-fundo-branco.jpeg\",\"width\":1024,\"height\":1024},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/abifer.org.br\/renovacao-da-fca-antt-analisa-incluir-contorno-de-belo-horizonte-no-contrato\/#webpage\",\"url\":\"https:\/\/abifer.org.br\/renovacao-da-fca-antt-analisa-incluir-contorno-de-belo-horizonte-no-contrato\/\",\"name\":\"Renova\u00e7\u00e3o da FCA: ANTT analisa incluir contorno de Belo Horizonte no contrato\",\"isPartOf\":{\"@id\":\"https:\/\/abifer.org.br\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/abifer.org.br\/renovacao-da-fca-antt-analisa-incluir-contorno-de-belo-horizonte-no-contrato\/#primaryimage\"},\"datePublished\":\"2025-10-27T22:07:53+00:00\",\"dateModified\":\"2025-10-27T22:07:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/abifer.org.br\/renovacao-da-fca-antt-analisa-incluir-contorno-de-belo-horizonte-no-contrato\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/abifer.org.br\/renovacao-da-fca-antt-analisa-incluir-contorno-de-belo-horizonte-no-contrato\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/abifer.org.br\/renovacao-da-fca-antt-analisa-incluir-contorno-de-belo-horizonte-no-contrato\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/abifer.org.br\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Renova\u00e7\u00e3o da FCA: ANTT analisa incluir contorno de Belo Horizonte no contrato\"}]},{\"@type\":\"Article\",\"@id\":\"https:\/\/abifer.org.br\/renovacao-da-fca-antt-analisa-incluir-contorno-de-belo-horizonte-no-contrato\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/abifer.org.br\/renovacao-da-fca-antt-analisa-incluir-contorno-de-belo-horizonte-no-contrato\/#webpage\"},\"author\":{\"@id\":\"https:\/\/abifer.org.br\/en\/#\/schema\/person\/90c38c3286f60a11b363834930f79a1f\"},\"headline\":\"Renova\u00e7\u00e3o da FCA: ANTT analisa incluir contorno de Belo Horizonte no contrato\",\"datePublished\":\"2025-10-27T22:07:53+00:00\",\"dateModified\":\"2025-10-27T22:07:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/abifer.org.br\/renovacao-da-fca-antt-analisa-incluir-contorno-de-belo-horizonte-no-contrato\/#webpage\"},\"wordCount\":483,\"publisher\":{\"@id\":\"https:\/\/abifer.org.br\/en\/#organization\"},\"image\":{\"@id\":\"https:\/\/abifer.org.br\/renovacao-da-fca-antt-analisa-incluir-contorno-de-belo-horizonte-no-contrato\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/abifer.org.br\/wp-content\/uploads\/2025\/06\/mais-trilhos-brasil-logo-fundo-branco.jpeg\",\"articleSection\":[\"Not\u00edcias do Mercado\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/abifer.org.br\/en\/#\/schema\/person\/90c38c3286f60a11b363834930f79a1f\",\"name\":\"ABIFER\",\"url\":\"https:\/\/abifer.org.br\/author\/abifer\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Renova\u00e7\u00e3o da FCA: ANTT analisa incluir contorno de Belo Horizonte no contrato","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/abifer.org.br\/renovacao-da-fca-antt-analisa-incluir-contorno-de-belo-horizonte-no-contrato\/","og_locale":"pt_BR","og_type":"article","og_title":"Renova\u00e7\u00e3o da FCA: ANTT analisa incluir contorno de Belo Horizonte no contrato","og_description":"Fonte: A Gazeta Data: 24\/10\/2025 A Ag\u00eancia Nacional dos Transportes Terrestres (ANTT) est\u00e1 avaliando as propostas feitas pelos governos do Esp\u00edrito Santo e Minas Gerais para a constru\u00e7\u00e3o do contorno ferrovi\u00e1rio de Belo Horizonte em substitui\u00e7\u00e3o ao da Serra do Tigre. Essa alternativa \u00e9 um pedido dos Estados para ser realizada a renova\u00e7\u00e3o da concess\u00e3o [&hellip;]","og_url":"https:\/\/abifer.org.br\/renovacao-da-fca-antt-analisa-incluir-contorno-de-belo-horizonte-no-contrato\/","og_site_name":"ABIFER","article_publisher":"https:\/\/www.facebook.com\/abiferoficial\/","article_published_time":"2025-10-27T22:07:53+00:00","og_image":[{"width":1024,"height":1024,"url":"https:\/\/abifer.org.br\/wp-content\/uploads\/2025\/06\/mais-trilhos-brasil-logo-fundo-branco.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_creator":"@abiferoficial","twitter_site":"@abiferoficial","twitter_misc":{"Escrito por":"ABIFER","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Organization","@id":"https:\/\/abifer.org.br\/en\/#organization","name":"ABIFER","url":"https:\/\/abifer.org.br\/en\/","sameAs":["https:\/\/www.facebook.com\/abiferoficial\/","https:\/\/www.linkedin.com\/company\/abiferoficial\/","https:\/\/twitter.com\/abiferoficial"],"logo":{"@type":"ImageObject","@id":"https:\/\/abifer.org.br\/en\/#logo","inLanguage":"pt-BR","url":"https:\/\/abifer.org.br\/wp-content\/uploads\/2018\/05\/ABF_001_LogoSlogan.jpg","contentUrl":"https:\/\/abifer.org.br\/wp-content\/uploads\/2018\/05\/ABF_001_LogoSlogan.jpg","width":1182,"height":486,"caption":"ABIFER"},"image":{"@id":"https:\/\/abifer.org.br\/en\/#logo"}},{"@type":"WebSite","@id":"https:\/\/abifer.org.br\/en\/#website","url":"https:\/\/abifer.org.br\/en\/","name":"ABIFER","description":"Associa\u00e7\u00e3o Brasileira da Ind\u00fastria Ferrovi\u00e1ria","publisher":{"@id":"https:\/\/abifer.org.br\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/abifer.org.br\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"ImageObject","@id":"https:\/\/abifer.org.br\/renovacao-da-fca-antt-analisa-incluir-contorno-de-belo-horizonte-no-contrato\/#primaryimage","inLanguage":"pt-BR","url":"https:\/\/abifer.org.br\/wp-content\/uploads\/2025\/06\/mais-trilhos-brasil-logo-fundo-branco.jpeg","contentUrl":"https:\/\/abifer.org.br\/wp-content\/uploads\/2025\/06\/mais-trilhos-brasil-logo-fundo-branco.jpeg","width":1024,"height":1024},{"@type":"WebPage","@id":"https:\/\/abifer.org.br\/renovacao-da-fca-antt-analisa-incluir-contorno-de-belo-horizonte-no-contrato\/#webpage","url":"https:\/\/abifer.org.br\/renovacao-da-fca-antt-analisa-incluir-contorno-de-belo-horizonte-no-contrato\/","name":"Renova\u00e7\u00e3o da FCA: ANTT analisa incluir contorno de Belo Horizonte no contrato","isPartOf":{"@id":"https:\/\/abifer.org.br\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/abifer.org.br\/renovacao-da-fca-antt-analisa-incluir-contorno-de-belo-horizonte-no-contrato\/#primaryimage"},"datePublished":"2025-10-27T22:07:53+00:00","dateModified":"2025-10-27T22:07:53+00:00","breadcrumb":{"@id":"https:\/\/abifer.org.br\/renovacao-da-fca-antt-analisa-incluir-contorno-de-belo-horizonte-no-contrato\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/abifer.org.br\/renovacao-da-fca-antt-analisa-incluir-contorno-de-belo-horizonte-no-contrato\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/abifer.org.br\/renovacao-da-fca-antt-analisa-incluir-contorno-de-belo-horizonte-no-contrato\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/abifer.org.br\/en\/"},{"@type":"ListItem","position":2,"name":"Renova\u00e7\u00e3o da FCA: ANTT analisa incluir contorno de Belo Horizonte no contrato"}]},{"@type":"Article","@id":"https:\/\/abifer.org.br\/renovacao-da-fca-antt-analisa-incluir-contorno-de-belo-horizonte-no-contrato\/#article","isPartOf":{"@id":"https:\/\/abifer.org.br\/renovacao-da-fca-antt-analisa-incluir-contorno-de-belo-horizonte-no-contrato\/#webpage"},"author":{"@id":"https:\/\/abifer.org.br\/en\/#\/schema\/person\/90c38c3286f60a11b363834930f79a1f"},"headline":"Renova\u00e7\u00e3o da FCA: ANTT analisa incluir contorno de Belo Horizonte no contrato","datePublished":"2025-10-27T22:07:53+00:00","dateModified":"2025-10-27T22:07:53+00:00","mainEntityOfPage":{"@id":"https:\/\/abifer.org.br\/renovacao-da-fca-antt-analisa-incluir-contorno-de-belo-horizonte-no-contrato\/#webpage"},"wordCount":483,"publisher":{"@id":"https:\/\/abifer.org.br\/en\/#organization"},"image":{"@id":"https:\/\/abifer.org.br\/renovacao-da-fca-antt-analisa-incluir-contorno-de-belo-horizonte-no-contrato\/#primaryimage"},"thumbnailUrl":"https:\/\/abifer.org.br\/wp-content\/uploads\/2025\/06\/mais-trilhos-brasil-logo-fundo-branco.jpeg","articleSection":["Not\u00edcias do Mercado"],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/abifer.org.br\/en\/#\/schema\/person\/90c38c3286f60a11b363834930f79a1f","name":"ABIFER","url":"https:\/\/abifer.org.br\/author\/abifer\/"}]}},"_links":{"self":[{"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/posts\/90893\/"}],"collection":[{"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/posts\/"}],"about":[{"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/types\/post\/"}],"author":[{"embeddable":true,"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/users\/55\/"}],"replies":[{"embeddable":true,"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/comments\/?post=90893"}],"version-history":[{"count":1,"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/posts\/90893\/revisions\/"}],"predecessor-version":[{"id":90894,"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/posts\/90893\/revisions\/90894\/"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/media\/88837\/"}],"wp:attachment":[{"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/media\/?parent=90893"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/categories\/?post=90893"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/tags\/?post=90893"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}