{"id":91668,"date":"2025-12-11T18:31:41","date_gmt":"2025-12-11T21:31:41","guid":{"rendered":"https:\/\/abifer.org.br\/?p=91668"},"modified":"2025-12-11T18:31:41","modified_gmt":"2025-12-11T21:31:41","slug":"governo-federal-pretende-investir-r-288-bi-em-rodovias-e-ferrovias","status":"publish","type":"post","link":"https:\/\/abifer.org.br\/en\/governo-federal-pretende-investir-r-288-bi-em-rodovias-e-ferrovias\/","title":{"rendered":"Governo Federal pretende investir R$ 288 bi em rodovias e ferrovias"},"content":{"rendered":"<pre style=\"text-align: right;\"><a href=\"https:\/\/valor.globo.com\/conteudo-de-marca\/logistica-no-brasil\/noticia\/2025\/12\/08\/governo-federal-pretende-investir-r-288-bi-em-rodovias-e-ferrovias.ghtml\" target=\"_blank\" rel=\"noopener\"><strong><em>Fonte: Valor\r\nData: 08\/12\/2025<\/em><\/strong><\/a><\/pre>\n<p>Com o an\u00fancio de 21 leil\u00f5es ferrovi\u00e1rios e rodovi\u00e1rios, al\u00e9m da previs\u00e3o de investimentos de R$ 288 bilh\u00f5es em um novo modelo de capta\u00e7\u00e3o de recursos, o Governo Federal lan\u00e7ou, no fim de novembro, a Pol\u00edtica Nacional de Outorgas Ferrovi\u00e1rias e a carteira de rodovias para o pr\u00f3ximo ano. Durante o evento de lan\u00e7amento, o ministro dos Transportes, Renan Filho, ressaltou que, al\u00e9m da novidade na forma de capta\u00e7\u00e3o de recursos, a nova Pol\u00edtica Nacional vai implementar no setor ferrovi\u00e1rio as iniciativas bem- -sucedidas que t\u00eam sido empregadas nas rodovias:<\/p>\n<p>\u201c\u00c9 uma pol\u00edtica nacional in\u00e9dita, com alinhamento dos projetos a pr\u00e1ticas de estrutura\u00e7\u00e3o mais modernas, \u00e0 modelagem econ\u00f4mica e financeira tamb\u00e9m. Uma pol\u00edtica alinhada \u00e0 defini\u00e7\u00e3o de regras contratuais que n\u00f3s trouxemos do ambiente rodovi\u00e1rio para ferrovias. Isso foi uma decis\u00e3o de pa\u00eds e isso vai ser transformador\u201d, garantiu Renan Filho.<\/p>\n<p>A promessa \u00e9 de que a Pol\u00edtica Nacional de Outorgas Ferrovi\u00e1rias defina tamb\u00e9m diretrizes claras de planejamento, governan\u00e7a e sustentabilidade. Vale lembrar que o modal ferrovi\u00e1rio \u00e9 mais eficiente energeticamente, j\u00e1 que emite menos gases poluentes, o que reduz o impacto ambiental da log\u00edstica e do transporte de cargas no pa\u00eds e ajuda a cumprir compromissos ambientais internacionais.<\/p>\n<p>Para 2026, o Minist\u00e9rio dos Transportes prev\u00ea oito leil\u00f5es de ferrovias que abrangem mais de nove mil quil\u00f4metros de extens\u00e3o e devem atrair cerca de R$140 bilh\u00f5es em investimentos, com proje\u00e7\u00e3o de R$600 bilh\u00f5es injetados no sistema ferrovi\u00e1rio. O secret\u00e1rio nacional de Transporte Ferrovi\u00e1rio, Leonardo Ribeiro, acredita que as ferrovias reduzem os custos.<\/p>\n<p>\u201cFerrovia \u00e9 um fen\u00f4meno econ\u00f4mico, j\u00e1 que reduz custo marginal, barateia frete, integra cadeias de produ\u00e7\u00e3o. E n\u00f3s avan\u00e7amos muito nesses tr\u00eas anos, com uma estrat\u00e9gia sofisticada e s\u00f3lida, atentos \u00e0 complexidade do setor\u201d, disse ele.<\/p>\n<p>Com a amplia\u00e7\u00e3o dos trilhos, os custos log\u00edsticos v\u00e3o ser reduzidos, o que pode servir para aumentar a competitividade da produ\u00e7\u00e3o nacional, diminuindo a depend\u00eancia do transporte rodovi\u00e1rio, assegura o Minist\u00e9rio dos Transportes.<\/p>\n<p>\u201cEsse \u00e9 um passo importante, de concretizar uma vis\u00e3o, porque fazer ferrovia realmente demanda uma vis\u00e3o e uma pol\u00edtica de Estado. E o setor est\u00e1 muito animado com esses projetos, com essa vis\u00e3o de investimento no setor\u201d, disse Davi Barreto, diretor-presidente da Associa\u00e7\u00e3o Nacional dos Transportadores Ferrovi\u00e1rios (ANTF).<\/p>\n<p><strong>OS PROJETOS DESTACADOS<\/strong><\/p>\n<p>A Ferrogr\u00e3o \u00e9 um dos projetos que ser\u00e1 beneficiado com a nova pol\u00edtica. Com quase mil quil\u00f4metros entre Sinop (MT) e Itaituba (PA), a estrada de ferro est\u00e1 prevista no novo Plano de Acelera\u00e7\u00e3o do Crescimento (PAC) e ser\u00e1 constru\u00edda ao lado da Rodovia BR-163 (que liga o Par\u00e1 ao Rio Grande do Sul) j\u00e1 existente. A previs\u00e3o \u00e9 de que a obra crie mais de cem mil postos de trabalho durante sua implanta\u00e7\u00e3o.<\/p>\n<p>\u201cOs projetos feitos pelo modelo de concess\u00e3o, como os do Minist\u00e9rio dos Transportes mostram que a colabora\u00e7\u00e3o do governo com o setor privado alavanca e soma recursos. A agenda de concess\u00f5es n\u00e3o s\u00f3 foi retomada, como consolidada\u201d, disse Nelson Barbosa, diretor de Planejamento do BNDES, \u00f3rg\u00e3o que \u00e9 um dos principais financiadores dos projetos do Minist\u00e9rio dos Transportes.<\/p>\n<p>Outro projeto que tem merecido aten\u00e7\u00e3o \u00e9 o Anel Ferrovi\u00e1rio do Sudeste (EF-118), qu liga Santa Leopoldina (ES) a Nova Igua\u00e7u (RJ), passando pelo Porto de A\u00e7u (RJ), com 57 quil\u00f4metros, atravessando v\u00e1rios munic\u00edpios dos estados do Rio de Janeiro e Esp\u00edrito Santo. Quando as obras terminarem, a linha f\u00e9rrea promover\u00e1 a conex\u00e3o entre duas importantes ferrovias nacionais: ao norte com a Estrada de Ferro Vit\u00f3ria Minas (EFVM) e ao sul com a Malha Ferrovi\u00e1ria MRS.<\/p>\n<p>O Anel pode ainda potencializar projetos estrat\u00e9gicos, como complexos industriais (Comperj e A\u00e7u); a log\u00edstica para distribui\u00e7\u00e3o de combust\u00edveis; a remineraliza\u00e7\u00e3o do Oeste de Minas Gerais; e a log\u00edstica do agroneg\u00f3cio da regi\u00e3o Centro-Oeste.<\/p>\n<p><strong>Setor rodovi\u00e1rio tamb\u00e9m ser\u00e1 beneficiado<\/strong><\/p>\n<p>O setor rodovi\u00e1rio tamb\u00e9m vem sendo beneficiado pelo Governo Federal: em menos de tr\u00eas anos, o Minist\u00e9rio dos Transportes j\u00e1 realizou 21 leil\u00f5es para constru\u00e7\u00e3o e manuten\u00e7\u00e3o de rodovias no pa\u00eds, somando pouco mais de 10 mil quil\u00f4metros de estradas concedidas e R$ 232 bilh\u00f5es em investimentos. Os n\u00fameros de 2025 ainda ser\u00e3o ampliados com o leil\u00e3o da Fern\u00e3o Dias \u2014 conhecida como BR-381, que conecta as metr\u00f3poles de Belo Horizonte (MG) e S\u00e3o Paulo (SP) \u2014 marcado para o dia 11 de dezembro.<\/p>\n<p>Para o ano de 2026 est\u00e3o previstos 13 leil\u00f5es, que garantir\u00e3o R$ 149 bilh\u00f5es em investimentos. E o Governo Federal espera atingir a marca de 35 concess\u00f5es rodovi\u00e1rias. A secret\u00e1ria nacional de Transporte Rodovi\u00e1rio, Viviane Esse, estava na cerim\u00f4nia de lan\u00e7amento da Pol\u00edtica Nacional de Outorgas Ferrovi\u00e1rias e comemorou o lan\u00e7amento da carteira de ferrovias e rodovias:<\/p>\n<p>\u201cHoje foi um dia muito relevante para o setor de transportes como um todo, com o lan\u00e7amento da carteira de ferrovias e de rodovias. De rodovias s\u00e3o 13 novos leil\u00f5es e gente espera a mesma participa\u00e7\u00e3o dos investidores que tivemos ultimamente tamb\u00e9m na carteira de 2026\u201d, disse.<\/p>\n<p>A Rota dos Sert\u00f5es, cujo leil\u00e3o est\u00e1 previsto para mar\u00e7o de 2026 e deve atrair investimentos de R$ 6 bilh\u00f5es, \u00e9 um dos destaques dos processos rodovi\u00e1rios. Com 502 quil\u00f4metros de extens\u00e3o, ela conecta o anel rodovi\u00e1rio de Feira de Santana (BA) a Salgueiro (PE), e ser\u00e1 o primeiro leil\u00e3o de concess\u00e3o rodovi\u00e1ria do Nordeste. O projeto prev\u00ea melhorias como duplica\u00e7\u00f5es, passarelas e um ponto de parada e descanso. A expectativa \u00e9 de gerar cerca de 60 mil empregos.<\/p>\n<p>\u201cEstamos abertos para o investimento privado de longo prazo, pois existe um ingrediente fundamental que \u00e9 a credibilidade\u201d, disse o diretor-presidente da Associa\u00e7\u00e3o Brasileira de Concession\u00e1rias de Rodovias, Marco Aur\u00e9lio Barcelos.<\/p>\n<p>Entre os projetos tamb\u00e9m est\u00e3o seis otimiza\u00e7\u00f5es contratuais, mecanismo desenvolvido em parceria com o Tribunal de Contas da Uni\u00e3o (TCU), para modernizar e reequilibrar acordos de concess\u00e3o que j\u00e1 n\u00e3o atendiam como o previsto.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fonte: Valor Data: 08\/12\/2025 Com o an\u00fancio de 21 leil\u00f5es ferrovi\u00e1rios e rodovi\u00e1rios, al\u00e9m da previs\u00e3o de investimentos de R$ 288 bilh\u00f5es em um novo modelo de capta\u00e7\u00e3o de recursos, o Governo Federal lan\u00e7ou, no fim de novembro, a Pol\u00edtica Nacional de Outorgas Ferrovi\u00e1rias e a carteira de rodovias para o pr\u00f3ximo ano. Durante o [&hellip;]<\/p>\n","protected":false},"author":55,"featured_media":86710,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[875],"tags":[],"class_list":["post-91668","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-do-mercado"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Governo Federal pretende investir R$ 288 bi em rodovias e ferrovias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/abifer.org.br\/governo-federal-pretende-investir-r-288-bi-em-rodovias-e-ferrovias\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Governo Federal pretende investir R$ 288 bi em rodovias e ferrovias\" \/>\n<meta property=\"og:description\" content=\"Fonte: Valor Data: 08\/12\/2025 Com o an\u00fancio de 21 leil\u00f5es ferrovi\u00e1rios e rodovi\u00e1rios, al\u00e9m da previs\u00e3o de investimentos de R$ 288 bilh\u00f5es em um novo modelo de capta\u00e7\u00e3o de recursos, o Governo Federal lan\u00e7ou, no fim de novembro, a Pol\u00edtica Nacional de Outorgas Ferrovi\u00e1rias e a carteira de rodovias para o pr\u00f3ximo ano. Durante o [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/abifer.org.br\/governo-federal-pretende-investir-r-288-bi-em-rodovias-e-ferrovias\/\" \/>\n<meta property=\"og:site_name\" content=\"ABIFER\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/abiferoficial\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-12-11T21:31:41+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/abifer.org.br\/wp-content\/uploads\/2025\/02\/bandeira-brasil.webp\" \/>\n<meta name=\"twitter:creator\" content=\"@abiferoficial\" \/>\n<meta name=\"twitter:site\" content=\"@abiferoficial\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"ABIFER\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/abifer.org.br\/en\/#organization\",\"name\":\"ABIFER\",\"url\":\"https:\/\/abifer.org.br\/en\/\",\"sameAs\":[\"https:\/\/www.facebook.com\/abiferoficial\/\",\"https:\/\/www.linkedin.com\/company\/abiferoficial\/\",\"https:\/\/twitter.com\/abiferoficial\"],\"logo\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/abifer.org.br\/en\/#logo\",\"inLanguage\":\"pt-BR\",\"url\":\"https:\/\/abifer.org.br\/wp-content\/uploads\/2018\/05\/ABF_001_LogoSlogan.jpg\",\"contentUrl\":\"https:\/\/abifer.org.br\/wp-content\/uploads\/2018\/05\/ABF_001_LogoSlogan.jpg\",\"width\":1182,\"height\":486,\"caption\":\"ABIFER\"},\"image\":{\"@id\":\"https:\/\/abifer.org.br\/en\/#logo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/abifer.org.br\/en\/#website\",\"url\":\"https:\/\/abifer.org.br\/en\/\",\"name\":\"ABIFER\",\"description\":\"Associa\u00e7\u00e3o Brasileira da Ind\u00fastria Ferrovi\u00e1ria\",\"publisher\":{\"@id\":\"https:\/\/abifer.org.br\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/abifer.org.br\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/abifer.org.br\/governo-federal-pretende-investir-r-288-bi-em-rodovias-e-ferrovias\/#primaryimage\",\"inLanguage\":\"pt-BR\",\"url\":\"https:\/\/abifer.org.br\/wp-content\/uploads\/2025\/02\/bandeira-brasil.webp\",\"contentUrl\":\"https:\/\/abifer.org.br\/wp-content\/uploads\/2025\/02\/bandeira-brasil.webp\",\"width\":1024,\"height\":1024},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/abifer.org.br\/governo-federal-pretende-investir-r-288-bi-em-rodovias-e-ferrovias\/#webpage\",\"url\":\"https:\/\/abifer.org.br\/governo-federal-pretende-investir-r-288-bi-em-rodovias-e-ferrovias\/\",\"name\":\"Governo Federal pretende investir R$ 288 bi em rodovias e ferrovias\",\"isPartOf\":{\"@id\":\"https:\/\/abifer.org.br\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/abifer.org.br\/governo-federal-pretende-investir-r-288-bi-em-rodovias-e-ferrovias\/#primaryimage\"},\"datePublished\":\"2025-12-11T21:31:41+00:00\",\"dateModified\":\"2025-12-11T21:31:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/abifer.org.br\/governo-federal-pretende-investir-r-288-bi-em-rodovias-e-ferrovias\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/abifer.org.br\/governo-federal-pretende-investir-r-288-bi-em-rodovias-e-ferrovias\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/abifer.org.br\/governo-federal-pretende-investir-r-288-bi-em-rodovias-e-ferrovias\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/abifer.org.br\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Governo Federal pretende investir R$ 288 bi em rodovias e ferrovias\"}]},{\"@type\":\"Article\",\"@id\":\"https:\/\/abifer.org.br\/governo-federal-pretende-investir-r-288-bi-em-rodovias-e-ferrovias\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/abifer.org.br\/governo-federal-pretende-investir-r-288-bi-em-rodovias-e-ferrovias\/#webpage\"},\"author\":{\"@id\":\"https:\/\/abifer.org.br\/en\/#\/schema\/person\/90c38c3286f60a11b363834930f79a1f\"},\"headline\":\"Governo Federal pretende investir R$ 288 bi em rodovias e ferrovias\",\"datePublished\":\"2025-12-11T21:31:41+00:00\",\"dateModified\":\"2025-12-11T21:31:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/abifer.org.br\/governo-federal-pretende-investir-r-288-bi-em-rodovias-e-ferrovias\/#webpage\"},\"wordCount\":1086,\"publisher\":{\"@id\":\"https:\/\/abifer.org.br\/en\/#organization\"},\"image\":{\"@id\":\"https:\/\/abifer.org.br\/governo-federal-pretende-investir-r-288-bi-em-rodovias-e-ferrovias\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/abifer.org.br\/wp-content\/uploads\/2025\/02\/bandeira-brasil.webp\",\"articleSection\":[\"Not\u00edcias do Mercado\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/abifer.org.br\/en\/#\/schema\/person\/90c38c3286f60a11b363834930f79a1f\",\"name\":\"ABIFER\",\"url\":\"https:\/\/abifer.org.br\/author\/abifer\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Governo Federal pretende investir R$ 288 bi em rodovias e ferrovias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/abifer.org.br\/governo-federal-pretende-investir-r-288-bi-em-rodovias-e-ferrovias\/","og_locale":"pt_BR","og_type":"article","og_title":"Governo Federal pretende investir R$ 288 bi em rodovias e ferrovias","og_description":"Fonte: Valor Data: 08\/12\/2025 Com o an\u00fancio de 21 leil\u00f5es ferrovi\u00e1rios e rodovi\u00e1rios, al\u00e9m da previs\u00e3o de investimentos de R$ 288 bilh\u00f5es em um novo modelo de capta\u00e7\u00e3o de recursos, o Governo Federal lan\u00e7ou, no fim de novembro, a Pol\u00edtica Nacional de Outorgas Ferrovi\u00e1rias e a carteira de rodovias para o pr\u00f3ximo ano. Durante o [&hellip;]","og_url":"https:\/\/abifer.org.br\/governo-federal-pretende-investir-r-288-bi-em-rodovias-e-ferrovias\/","og_site_name":"ABIFER","article_publisher":"https:\/\/www.facebook.com\/abiferoficial\/","article_published_time":"2025-12-11T21:31:41+00:00","twitter_card":"summary_large_image","twitter_image":"https:\/\/abifer.org.br\/wp-content\/uploads\/2025\/02\/bandeira-brasil.webp","twitter_creator":"@abiferoficial","twitter_site":"@abiferoficial","twitter_misc":{"Escrito por":"ABIFER","Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Organization","@id":"https:\/\/abifer.org.br\/en\/#organization","name":"ABIFER","url":"https:\/\/abifer.org.br\/en\/","sameAs":["https:\/\/www.facebook.com\/abiferoficial\/","https:\/\/www.linkedin.com\/company\/abiferoficial\/","https:\/\/twitter.com\/abiferoficial"],"logo":{"@type":"ImageObject","@id":"https:\/\/abifer.org.br\/en\/#logo","inLanguage":"pt-BR","url":"https:\/\/abifer.org.br\/wp-content\/uploads\/2018\/05\/ABF_001_LogoSlogan.jpg","contentUrl":"https:\/\/abifer.org.br\/wp-content\/uploads\/2018\/05\/ABF_001_LogoSlogan.jpg","width":1182,"height":486,"caption":"ABIFER"},"image":{"@id":"https:\/\/abifer.org.br\/en\/#logo"}},{"@type":"WebSite","@id":"https:\/\/abifer.org.br\/en\/#website","url":"https:\/\/abifer.org.br\/en\/","name":"ABIFER","description":"Associa\u00e7\u00e3o Brasileira da Ind\u00fastria Ferrovi\u00e1ria","publisher":{"@id":"https:\/\/abifer.org.br\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/abifer.org.br\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"ImageObject","@id":"https:\/\/abifer.org.br\/governo-federal-pretende-investir-r-288-bi-em-rodovias-e-ferrovias\/#primaryimage","inLanguage":"pt-BR","url":"https:\/\/abifer.org.br\/wp-content\/uploads\/2025\/02\/bandeira-brasil.webp","contentUrl":"https:\/\/abifer.org.br\/wp-content\/uploads\/2025\/02\/bandeira-brasil.webp","width":1024,"height":1024},{"@type":"WebPage","@id":"https:\/\/abifer.org.br\/governo-federal-pretende-investir-r-288-bi-em-rodovias-e-ferrovias\/#webpage","url":"https:\/\/abifer.org.br\/governo-federal-pretende-investir-r-288-bi-em-rodovias-e-ferrovias\/","name":"Governo Federal pretende investir R$ 288 bi em rodovias e ferrovias","isPartOf":{"@id":"https:\/\/abifer.org.br\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/abifer.org.br\/governo-federal-pretende-investir-r-288-bi-em-rodovias-e-ferrovias\/#primaryimage"},"datePublished":"2025-12-11T21:31:41+00:00","dateModified":"2025-12-11T21:31:41+00:00","breadcrumb":{"@id":"https:\/\/abifer.org.br\/governo-federal-pretende-investir-r-288-bi-em-rodovias-e-ferrovias\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/abifer.org.br\/governo-federal-pretende-investir-r-288-bi-em-rodovias-e-ferrovias\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/abifer.org.br\/governo-federal-pretende-investir-r-288-bi-em-rodovias-e-ferrovias\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/abifer.org.br\/en\/"},{"@type":"ListItem","position":2,"name":"Governo Federal pretende investir R$ 288 bi em rodovias e ferrovias"}]},{"@type":"Article","@id":"https:\/\/abifer.org.br\/governo-federal-pretende-investir-r-288-bi-em-rodovias-e-ferrovias\/#article","isPartOf":{"@id":"https:\/\/abifer.org.br\/governo-federal-pretende-investir-r-288-bi-em-rodovias-e-ferrovias\/#webpage"},"author":{"@id":"https:\/\/abifer.org.br\/en\/#\/schema\/person\/90c38c3286f60a11b363834930f79a1f"},"headline":"Governo Federal pretende investir R$ 288 bi em rodovias e ferrovias","datePublished":"2025-12-11T21:31:41+00:00","dateModified":"2025-12-11T21:31:41+00:00","mainEntityOfPage":{"@id":"https:\/\/abifer.org.br\/governo-federal-pretende-investir-r-288-bi-em-rodovias-e-ferrovias\/#webpage"},"wordCount":1086,"publisher":{"@id":"https:\/\/abifer.org.br\/en\/#organization"},"image":{"@id":"https:\/\/abifer.org.br\/governo-federal-pretende-investir-r-288-bi-em-rodovias-e-ferrovias\/#primaryimage"},"thumbnailUrl":"https:\/\/abifer.org.br\/wp-content\/uploads\/2025\/02\/bandeira-brasil.webp","articleSection":["Not\u00edcias do Mercado"],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/abifer.org.br\/en\/#\/schema\/person\/90c38c3286f60a11b363834930f79a1f","name":"ABIFER","url":"https:\/\/abifer.org.br\/author\/abifer\/"}]}},"_links":{"self":[{"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/posts\/91668\/"}],"collection":[{"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/posts\/"}],"about":[{"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/types\/post\/"}],"author":[{"embeddable":true,"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/users\/55\/"}],"replies":[{"embeddable":true,"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/comments\/?post=91668"}],"version-history":[{"count":1,"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/posts\/91668\/revisions\/"}],"predecessor-version":[{"id":91669,"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/posts\/91668\/revisions\/91669\/"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/media\/86710\/"}],"wp:attachment":[{"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/media\/?parent=91668"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/categories\/?post=91668"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/tags\/?post=91668"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}