{"id":92271,"date":"2026-01-23T15:05:03","date_gmt":"2026-01-23T18:05:03","guid":{"rendered":"https:\/\/abifer.org.br\/?p=92271"},"modified":"2026-01-23T15:05:03","modified_gmt":"2026-01-23T18:05:03","slug":"corredor-minas-rio-abre-concessoes-ferrovias-2026","status":"publish","type":"post","link":"https:\/\/abifer.org.br\/en\/corredor-minas-rio-abre-concessoes-ferrovias-2026\/","title":{"rendered":"\u2018Corredor Minas-Rio\u2019 abre concess\u00f5es de ferrovias em 2026 com aposta de ser nova rota do caf\u00e9"},"content":{"rendered":"<pre style=\"text-align: right;\"><a href=\"https:\/\/www1.folha.uol.com.br\/mercado\/2026\/01\/corredor-minas-rio-abre-concessoes-de-ferrovias-em-2026-com-aposta-de-ser-nova-rota-do-cafe.shtml\" target=\"_blank\" rel=\"noopener\"><strong><em>Fonte: Folha S. Paulo\r\nData: 18\/01\/2026<\/em><\/strong><\/a><\/pre>\n<p>A concess\u00e3o de trechos ferrovi\u00e1rios para a iniciativa privada vai ter in\u00edcio em 2026 com a oferta do \u201ccorredor Minas-Rio\u201d, uma malha j\u00e1 existente \u2013mas subutilizada\u2013 de 740 km de extens\u00e3o e que conecta as cidades mineiras de Arcos, Lavras e Varginha at\u00e9 os munic\u00edpios fluminenses de Barra Mansa e Angra dos Reis.<\/p>\n<p>O tra\u00e7ado faz parte atualmente da malha da FCA (Ferrovia Centro-Atl\u00e2ntica), mas est\u00e1 quase inoperante e demanda investimentos para amplia\u00e7\u00f5es.<\/p>\n<p>O trecho ser\u00e1 retomado pelo governo Lula (PT) e oferecido por meio de um \u201cchamamento p\u00fablico\u201d, um\u00a0modelo in\u00e9dito\u00a0em que a administra\u00e7\u00e3o p\u00fablica oferece a malha ao mercado, condicionando essa opera\u00e7\u00e3o a investimentos, mas sem exigir pagamentos \u00e0 Uni\u00e3o (outorga).<\/p>\n<p>Com esse modelo de autoriza\u00e7\u00f5es, o governo federal pretende atrair investimentos privados para reaproveitar ferrovias existentes que foram abandonadas. O plano prev\u00ea um contrato de 99 anos de explora\u00e7\u00e3o ferrovi\u00e1ria. Se o chamamento p\u00fablico atrair mais de um interessado, o governo escolhe a proposta que seja mais atrativa ao interesse p\u00fablico.<\/p>\n<p>A concess\u00e3o total da FCA, feita 30 anos atr\u00e1s, acaba em setembro de 2026. Com a proximidade do fim do contrato, parte desses trechos de mais de 7 mil km da ferrovia ser\u00e1 devolvida \u00e0 Uni\u00e3o. Por isso, o governo tem pressa em dar um destino a tra\u00e7ados que ser\u00e3o retomados, al\u00e9m de viabilizar a prorroga\u00e7\u00e3o do contrato atual de parte da ferrovia com a VLI, que administra a FCA.<\/p>\n<p>O\u00a0corredor Minas-Rio\u00a0foi escolhido porque re\u00fane uma combina\u00e7\u00e3o de fatores que, na avalia\u00e7\u00e3o do Minist\u00e9rio dos Transportes, tem potencial de atrair diferentes operadores de ferrovia.<\/p>\n<p>O trecho aponta demanda real de carga, tem estudos t\u00e9cnicos prontos, inspe\u00e7\u00f5es realizadas e uma decis\u00e3o pol\u00edtica de priorizar o projeto. Passou tamb\u00e9m a fazer parte do PPI (Programa de Parcerias de Investimentos).<\/p>\n<p>Na pr\u00e1tica, isso significa que ele passa a ser tratado como prioridade pol\u00edtica e institucional, sendo acompanhado diretamente pela Casa Civil da Presid\u00eancia da Rep\u00fablica. Para o investidor, \u00e9 mais um sinal de seguran\u00e7a para o investimento.<\/p>\n<p>A diversifica\u00e7\u00e3o de cargas, al\u00e9m do poss\u00edvel interesse tur\u00edstico para transporte de passageiros, \u00e9 uma das principais apostas. Os estudos j\u00e1 realizados apontam que o trecho pode se converter em uma nova rota de exporta\u00e7\u00e3o para o caf\u00e9 nacional.<\/p>\n<p>O sul de Minas \u00e9 a principal regi\u00e3o produtora do pa\u00eds, respons\u00e1vel por mais de um ter\u00e7o do caf\u00e9 brasileiro. A ferrovia permitiria ligar essa produ\u00e7\u00e3o diretamente ao litoral fluminense, pelo porto de Angra dos Reis, uma alternativa log\u00edstica ao escoamento tradicional feito por rodovias e portos mais congestionados, como o de Santos.<\/p>\n<p>Al\u00e9m do caf\u00e9, o corredor pode viabilizar a importa\u00e7\u00e3o de fertilizantes e o transporte de cargas gerais. Atualmente, a malha inteira da FCA transporta 32 milh\u00f5es de toneladas por ano, sendo a maior parte dessa carga formada por min\u00e9rio de ferro e insumos da siderurgia.<\/p>\n<p>J\u00e1 no corredor Minas-Rio, a maior parte do volume envolve calc\u00e1rio, cl\u00ednquer, dolomita e insumos industriais, com movimenta\u00e7\u00e3o estimada em cerca de 1,7 milh\u00e3o de toneladas em 2025. Pelos c\u00e1lculos do governo, essa carga pode ultrapassar 2,5 milh\u00f5es de toneladas anuais nas pr\u00f3ximas d\u00e9cadas.<\/p>\n<p>O governo acredita que a oferta do corredor Minas-Rio como primeira autoriza\u00e7\u00e3o ferrovi\u00e1ria pode se tornar um marco para o setor. O projeto vai funcionar como um teste do modelo para outras ferrovias que enfrentam problemas de subutiliza\u00e7\u00e3o ou fim de contrato.<\/p>\n<p>Ao todo,\u00a0a carteira do setor ferrovi\u00e1rio\u00a0tem a expectativa de movimentar mais de R$ 139,7 bilh\u00f5es de investimentos em obras, al\u00e9m de R$ 516,5 bilh\u00f5es em opera\u00e7\u00f5es dos trechos.<\/p>\n<p>Al\u00e9m do chamamento p\u00fablico de trechos, o planejamento do governo federal est\u00e1 concentrado em oito tra\u00e7ados entre 2026 e 2027. A publica\u00e7\u00e3o de editais e as datas dos leil\u00f5es est\u00e3o distribu\u00eddas nos dois pr\u00f3ximos anos e incluem obras totalmente novas, al\u00e9m de revitaliza\u00e7\u00e3o de trechos degradados e integra\u00e7\u00e3o de corredores ferrovi\u00e1rios e portos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fonte: Folha S. Paulo Data: 18\/01\/2026 A concess\u00e3o de trechos ferrovi\u00e1rios para a iniciativa privada vai ter in\u00edcio em 2026 com a oferta do \u201ccorredor Minas-Rio\u201d, uma malha j\u00e1 existente \u2013mas subutilizada\u2013 de 740 km de extens\u00e3o e que conecta as cidades mineiras de Arcos, Lavras e Varginha at\u00e9 os munic\u00edpios fluminenses de Barra Mansa [&hellip;]<\/p>\n","protected":false},"author":55,"featured_media":88837,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[875],"tags":[],"class_list":["post-92271","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-do-mercado"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u2018Corredor Minas-Rio\u2019 abre concess\u00f5es de ferrovias em 2026 com aposta de ser nova rota do caf\u00e9<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/abifer.org.br\/corredor-minas-rio-abre-concessoes-ferrovias-2026\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u2018Corredor Minas-Rio\u2019 abre concess\u00f5es de ferrovias em 2026 com aposta de ser nova rota do caf\u00e9\" \/>\n<meta property=\"og:description\" content=\"Fonte: Folha S. Paulo Data: 18\/01\/2026 A concess\u00e3o de trechos ferrovi\u00e1rios para a iniciativa privada vai ter in\u00edcio em 2026 com a oferta do \u201ccorredor Minas-Rio\u201d, uma malha j\u00e1 existente \u2013mas subutilizada\u2013 de 740 km de extens\u00e3o e que conecta as cidades mineiras de Arcos, Lavras e Varginha at\u00e9 os munic\u00edpios fluminenses de Barra Mansa [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/abifer.org.br\/corredor-minas-rio-abre-concessoes-ferrovias-2026\/\" \/>\n<meta property=\"og:site_name\" content=\"ABIFER\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/abiferoficial\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-23T18:05:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/abifer.org.br\/wp-content\/uploads\/2025\/06\/mais-trilhos-brasil-logo-fundo-branco.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@abiferoficial\" \/>\n<meta name=\"twitter:site\" content=\"@abiferoficial\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"ABIFER\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/abifer.org.br\/en\/#organization\",\"name\":\"ABIFER\",\"url\":\"https:\/\/abifer.org.br\/en\/\",\"sameAs\":[\"https:\/\/www.facebook.com\/abiferoficial\/\",\"https:\/\/www.linkedin.com\/company\/abiferoficial\/\",\"https:\/\/twitter.com\/abiferoficial\"],\"logo\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/abifer.org.br\/en\/#logo\",\"inLanguage\":\"pt-BR\",\"url\":\"https:\/\/abifer.org.br\/wp-content\/uploads\/2018\/05\/ABF_001_LogoSlogan.jpg\",\"contentUrl\":\"https:\/\/abifer.org.br\/wp-content\/uploads\/2018\/05\/ABF_001_LogoSlogan.jpg\",\"width\":1182,\"height\":486,\"caption\":\"ABIFER\"},\"image\":{\"@id\":\"https:\/\/abifer.org.br\/en\/#logo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/abifer.org.br\/en\/#website\",\"url\":\"https:\/\/abifer.org.br\/en\/\",\"name\":\"ABIFER\",\"description\":\"Associa\u00e7\u00e3o Brasileira da Ind\u00fastria Ferrovi\u00e1ria\",\"publisher\":{\"@id\":\"https:\/\/abifer.org.br\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/abifer.org.br\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/abifer.org.br\/corredor-minas-rio-abre-concessoes-ferrovias-2026\/#primaryimage\",\"inLanguage\":\"pt-BR\",\"url\":\"https:\/\/abifer.org.br\/wp-content\/uploads\/2025\/06\/mais-trilhos-brasil-logo-fundo-branco.jpeg\",\"contentUrl\":\"https:\/\/abifer.org.br\/wp-content\/uploads\/2025\/06\/mais-trilhos-brasil-logo-fundo-branco.jpeg\",\"width\":1024,\"height\":1024},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/abifer.org.br\/corredor-minas-rio-abre-concessoes-ferrovias-2026\/#webpage\",\"url\":\"https:\/\/abifer.org.br\/corredor-minas-rio-abre-concessoes-ferrovias-2026\/\",\"name\":\"\u2018Corredor Minas-Rio\u2019 abre concess\u00f5es de ferrovias em 2026 com aposta de ser nova rota do caf\u00e9\",\"isPartOf\":{\"@id\":\"https:\/\/abifer.org.br\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/abifer.org.br\/corredor-minas-rio-abre-concessoes-ferrovias-2026\/#primaryimage\"},\"datePublished\":\"2026-01-23T18:05:03+00:00\",\"dateModified\":\"2026-01-23T18:05:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/abifer.org.br\/corredor-minas-rio-abre-concessoes-ferrovias-2026\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/abifer.org.br\/corredor-minas-rio-abre-concessoes-ferrovias-2026\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/abifer.org.br\/corredor-minas-rio-abre-concessoes-ferrovias-2026\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/abifer.org.br\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u2018Corredor Minas-Rio\u2019 abre concess\u00f5es de ferrovias em 2026 com aposta de ser nova rota do caf\u00e9\"}]},{\"@type\":\"Article\",\"@id\":\"https:\/\/abifer.org.br\/corredor-minas-rio-abre-concessoes-ferrovias-2026\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/abifer.org.br\/corredor-minas-rio-abre-concessoes-ferrovias-2026\/#webpage\"},\"author\":{\"@id\":\"https:\/\/abifer.org.br\/en\/#\/schema\/person\/90c38c3286f60a11b363834930f79a1f\"},\"headline\":\"\u2018Corredor Minas-Rio\u2019 abre concess\u00f5es de ferrovias em 2026 com aposta de ser nova rota do caf\u00e9\",\"datePublished\":\"2026-01-23T18:05:03+00:00\",\"dateModified\":\"2026-01-23T18:05:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/abifer.org.br\/corredor-minas-rio-abre-concessoes-ferrovias-2026\/#webpage\"},\"wordCount\":717,\"publisher\":{\"@id\":\"https:\/\/abifer.org.br\/en\/#organization\"},\"image\":{\"@id\":\"https:\/\/abifer.org.br\/corredor-minas-rio-abre-concessoes-ferrovias-2026\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/abifer.org.br\/wp-content\/uploads\/2025\/06\/mais-trilhos-brasil-logo-fundo-branco.jpeg\",\"articleSection\":[\"Not\u00edcias do Mercado\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/abifer.org.br\/en\/#\/schema\/person\/90c38c3286f60a11b363834930f79a1f\",\"name\":\"ABIFER\",\"url\":\"https:\/\/abifer.org.br\/author\/abifer\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u2018Corredor Minas-Rio\u2019 abre concess\u00f5es de ferrovias em 2026 com aposta de ser nova rota do caf\u00e9","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/abifer.org.br\/corredor-minas-rio-abre-concessoes-ferrovias-2026\/","og_locale":"pt_BR","og_type":"article","og_title":"\u2018Corredor Minas-Rio\u2019 abre concess\u00f5es de ferrovias em 2026 com aposta de ser nova rota do caf\u00e9","og_description":"Fonte: Folha S. Paulo Data: 18\/01\/2026 A concess\u00e3o de trechos ferrovi\u00e1rios para a iniciativa privada vai ter in\u00edcio em 2026 com a oferta do \u201ccorredor Minas-Rio\u201d, uma malha j\u00e1 existente \u2013mas subutilizada\u2013 de 740 km de extens\u00e3o e que conecta as cidades mineiras de Arcos, Lavras e Varginha at\u00e9 os munic\u00edpios fluminenses de Barra Mansa [&hellip;]","og_url":"https:\/\/abifer.org.br\/corredor-minas-rio-abre-concessoes-ferrovias-2026\/","og_site_name":"ABIFER","article_publisher":"https:\/\/www.facebook.com\/abiferoficial\/","article_published_time":"2026-01-23T18:05:03+00:00","og_image":[{"width":1024,"height":1024,"url":"https:\/\/abifer.org.br\/wp-content\/uploads\/2025\/06\/mais-trilhos-brasil-logo-fundo-branco.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_creator":"@abiferoficial","twitter_site":"@abiferoficial","twitter_misc":{"Escrito por":"ABIFER","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Organization","@id":"https:\/\/abifer.org.br\/en\/#organization","name":"ABIFER","url":"https:\/\/abifer.org.br\/en\/","sameAs":["https:\/\/www.facebook.com\/abiferoficial\/","https:\/\/www.linkedin.com\/company\/abiferoficial\/","https:\/\/twitter.com\/abiferoficial"],"logo":{"@type":"ImageObject","@id":"https:\/\/abifer.org.br\/en\/#logo","inLanguage":"pt-BR","url":"https:\/\/abifer.org.br\/wp-content\/uploads\/2018\/05\/ABF_001_LogoSlogan.jpg","contentUrl":"https:\/\/abifer.org.br\/wp-content\/uploads\/2018\/05\/ABF_001_LogoSlogan.jpg","width":1182,"height":486,"caption":"ABIFER"},"image":{"@id":"https:\/\/abifer.org.br\/en\/#logo"}},{"@type":"WebSite","@id":"https:\/\/abifer.org.br\/en\/#website","url":"https:\/\/abifer.org.br\/en\/","name":"ABIFER","description":"Associa\u00e7\u00e3o Brasileira da Ind\u00fastria Ferrovi\u00e1ria","publisher":{"@id":"https:\/\/abifer.org.br\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/abifer.org.br\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"ImageObject","@id":"https:\/\/abifer.org.br\/corredor-minas-rio-abre-concessoes-ferrovias-2026\/#primaryimage","inLanguage":"pt-BR","url":"https:\/\/abifer.org.br\/wp-content\/uploads\/2025\/06\/mais-trilhos-brasil-logo-fundo-branco.jpeg","contentUrl":"https:\/\/abifer.org.br\/wp-content\/uploads\/2025\/06\/mais-trilhos-brasil-logo-fundo-branco.jpeg","width":1024,"height":1024},{"@type":"WebPage","@id":"https:\/\/abifer.org.br\/corredor-minas-rio-abre-concessoes-ferrovias-2026\/#webpage","url":"https:\/\/abifer.org.br\/corredor-minas-rio-abre-concessoes-ferrovias-2026\/","name":"\u2018Corredor Minas-Rio\u2019 abre concess\u00f5es de ferrovias em 2026 com aposta de ser nova rota do caf\u00e9","isPartOf":{"@id":"https:\/\/abifer.org.br\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/abifer.org.br\/corredor-minas-rio-abre-concessoes-ferrovias-2026\/#primaryimage"},"datePublished":"2026-01-23T18:05:03+00:00","dateModified":"2026-01-23T18:05:03+00:00","breadcrumb":{"@id":"https:\/\/abifer.org.br\/corredor-minas-rio-abre-concessoes-ferrovias-2026\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/abifer.org.br\/corredor-minas-rio-abre-concessoes-ferrovias-2026\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/abifer.org.br\/corredor-minas-rio-abre-concessoes-ferrovias-2026\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/abifer.org.br\/en\/"},{"@type":"ListItem","position":2,"name":"\u2018Corredor Minas-Rio\u2019 abre concess\u00f5es de ferrovias em 2026 com aposta de ser nova rota do caf\u00e9"}]},{"@type":"Article","@id":"https:\/\/abifer.org.br\/corredor-minas-rio-abre-concessoes-ferrovias-2026\/#article","isPartOf":{"@id":"https:\/\/abifer.org.br\/corredor-minas-rio-abre-concessoes-ferrovias-2026\/#webpage"},"author":{"@id":"https:\/\/abifer.org.br\/en\/#\/schema\/person\/90c38c3286f60a11b363834930f79a1f"},"headline":"\u2018Corredor Minas-Rio\u2019 abre concess\u00f5es de ferrovias em 2026 com aposta de ser nova rota do caf\u00e9","datePublished":"2026-01-23T18:05:03+00:00","dateModified":"2026-01-23T18:05:03+00:00","mainEntityOfPage":{"@id":"https:\/\/abifer.org.br\/corredor-minas-rio-abre-concessoes-ferrovias-2026\/#webpage"},"wordCount":717,"publisher":{"@id":"https:\/\/abifer.org.br\/en\/#organization"},"image":{"@id":"https:\/\/abifer.org.br\/corredor-minas-rio-abre-concessoes-ferrovias-2026\/#primaryimage"},"thumbnailUrl":"https:\/\/abifer.org.br\/wp-content\/uploads\/2025\/06\/mais-trilhos-brasil-logo-fundo-branco.jpeg","articleSection":["Not\u00edcias do Mercado"],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/abifer.org.br\/en\/#\/schema\/person\/90c38c3286f60a11b363834930f79a1f","name":"ABIFER","url":"https:\/\/abifer.org.br\/author\/abifer\/"}]}},"_links":{"self":[{"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/posts\/92271\/"}],"collection":[{"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/posts\/"}],"about":[{"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/types\/post\/"}],"author":[{"embeddable":true,"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/users\/55\/"}],"replies":[{"embeddable":true,"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/comments\/?post=92271"}],"version-history":[{"count":1,"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/posts\/92271\/revisions\/"}],"predecessor-version":[{"id":92273,"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/posts\/92271\/revisions\/92273\/"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/media\/88837\/"}],"wp:attachment":[{"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/media\/?parent=92271"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/categories\/?post=92271"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/tags\/?post=92271"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}