{"id":92282,"date":"2026-01-23T15:26:38","date_gmt":"2026-01-23T18:26:38","guid":{"rendered":"https:\/\/abifer.org.br\/?p=92282"},"modified":"2026-01-23T15:26:38","modified_gmt":"2026-01-23T18:26:38","slug":"dinheiro-privado-em-ferrovias-governo-federal-endurece-fiscalizacao","status":"publish","type":"post","link":"https:\/\/abifer.org.br\/en\/dinheiro-privado-em-ferrovias-governo-federal-endurece-fiscalizacao\/","title":{"rendered":"Dinheiro privado em ferrovias: governo federal endurece fiscaliza\u00e7\u00e3o"},"content":{"rendered":"<pre style=\"text-align: right;\"><a href=\"https:\/\/noticias.r7.com\/prisma\/r7-planalto\/dinheiro-privado-em-ferrovias-ministerio-dos-transportes-endurece-fiscalizacao-23012026\/\" target=\"_blank\" rel=\"noopener\"><strong><em>Fonte: R7\r\nData: 23\/01\/2026<\/em><\/strong><\/a><\/pre>\n<p><em>Pasta quer produ\u00e7\u00e3o de relat\u00f3rios e acompanhamento dos recursos investidos<\/em><\/p>\n<p>O Minist\u00e9rio dos Transportes vai acompanhar de perto os recursos privados investidos em ferrovias brasileiras. Em portaria publicada nesta sexta-feira (23), a pasta endureceu as regras de controle e fiscaliza\u00e7\u00e3o dessas verbas.<\/p>\n<p>Agora, os valores com origem em acordos firmados entre\u00a0governo\u00a0e concession\u00e1rias ferrovi\u00e1rias, assinados muitas vezes para encerrar disputas administrativas ou judiciais, ser\u00e3o monitorados.<\/p>\n<p>Na pr\u00e1tica, a\u00a0medida\u00a0pode levar \u00e0 redu\u00e7\u00e3o dos custos de produtos e do transporte de cargas, bem como \u00e0 diminui\u00e7\u00e3o da emiss\u00e3o de poluentes.<\/p>\n<p>As novas regras estipulam, por exemplo, que bilh\u00f5es de reais parados ou sem destina\u00e7\u00e3o clara, que acabam na mira de \u00f3rg\u00e3os de controle, s\u00f3 poder\u00e3o ser usados em projetos estrat\u00e9gicos para o pa\u00eds.<\/p>\n<p>A ANTT (Ag\u00eancia Nacional de Transportes Terrestres) ficar\u00e1 respons\u00e1vel pelo monitoramento dos recursos e ter\u00e1 de publicar relat\u00f3rios trimestrais com detalhes dos valores, dos rendimentos financeiros e do andamento dos projetos.<\/p>\n<p>Caso as quantias n\u00e3o sejam aplicadas conforme as regras ou dentro dos prazos definidos, o dinheiro poder\u00e1 ser recolhido ao Tesouro Nacional.<\/p>\n<p><strong>Entenda<\/strong><\/p>\n<p>Embora os recursos em quest\u00e3o sejam privados, eles s\u00e3o usados para melhorar a malha ferrovi\u00e1ria de interesse da Uni\u00e3o, em obras de amplia\u00e7\u00e3o, recupera\u00e7\u00e3o de trechos ou aumento da capacidade log\u00edstica.<\/p>\n<p>Com as altera\u00e7\u00f5es, esses recursos dever\u00e3o ser destinados apenas para projetos oficiais de planejamento, como o PNL (Plano Nacional de Log\u00edstica) e o PAC (Programa de Acelera\u00e7\u00e3o do Crescimento).<\/p>\n<p>A Portaria tamb\u00e9m cria um Comit\u00ea de Governan\u00e7a de Recursos Ferrovi\u00e1rios, formado por representantes do Minist\u00e9rio dos Transportes, da ANTT e da Infra S.A.<\/p>\n<p>O grupo ser\u00e1 respons\u00e1vel por aprovar quais projetos poder\u00e3o receber valores e por resolver conflitos relacionados \u00e0 gest\u00e3o dos investimentos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fonte: R7 Data: 23\/01\/2026 Pasta quer produ\u00e7\u00e3o de relat\u00f3rios e acompanhamento dos recursos investidos O Minist\u00e9rio dos Transportes vai acompanhar de perto os recursos privados investidos em ferrovias brasileiras. Em portaria publicada nesta sexta-feira (23), a pasta endureceu as regras de controle e fiscaliza\u00e7\u00e3o dessas verbas. Agora, os valores com origem em acordos firmados entre\u00a0governo\u00a0e [&hellip;]<\/p>\n","protected":false},"author":55,"featured_media":86710,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[875],"tags":[],"class_list":["post-92282","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-do-mercado"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Dinheiro privado em ferrovias: governo federal endurece fiscaliza\u00e7\u00e3o<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/abifer.org.br\/dinheiro-privado-em-ferrovias-governo-federal-endurece-fiscalizacao\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dinheiro privado em ferrovias: governo federal endurece fiscaliza\u00e7\u00e3o\" \/>\n<meta property=\"og:description\" content=\"Fonte: R7 Data: 23\/01\/2026 Pasta quer produ\u00e7\u00e3o de relat\u00f3rios e acompanhamento dos recursos investidos O Minist\u00e9rio dos Transportes vai acompanhar de perto os recursos privados investidos em ferrovias brasileiras. Em portaria publicada nesta sexta-feira (23), a pasta endureceu as regras de controle e fiscaliza\u00e7\u00e3o dessas verbas. Agora, os valores com origem em acordos firmados entre\u00a0governo\u00a0e [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/abifer.org.br\/dinheiro-privado-em-ferrovias-governo-federal-endurece-fiscalizacao\/\" \/>\n<meta property=\"og:site_name\" content=\"ABIFER\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/abiferoficial\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-23T18:26:38+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/abifer.org.br\/wp-content\/uploads\/2025\/02\/bandeira-brasil.webp\" \/>\n<meta name=\"twitter:creator\" content=\"@abiferoficial\" \/>\n<meta name=\"twitter:site\" content=\"@abiferoficial\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"ABIFER\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/abifer.org.br\/en\/#organization\",\"name\":\"ABIFER\",\"url\":\"https:\/\/abifer.org.br\/en\/\",\"sameAs\":[\"https:\/\/www.facebook.com\/abiferoficial\/\",\"https:\/\/www.linkedin.com\/company\/abiferoficial\/\",\"https:\/\/twitter.com\/abiferoficial\"],\"logo\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/abifer.org.br\/en\/#logo\",\"inLanguage\":\"pt-BR\",\"url\":\"https:\/\/abifer.org.br\/wp-content\/uploads\/2018\/05\/ABF_001_LogoSlogan.jpg\",\"contentUrl\":\"https:\/\/abifer.org.br\/wp-content\/uploads\/2018\/05\/ABF_001_LogoSlogan.jpg\",\"width\":1182,\"height\":486,\"caption\":\"ABIFER\"},\"image\":{\"@id\":\"https:\/\/abifer.org.br\/en\/#logo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/abifer.org.br\/en\/#website\",\"url\":\"https:\/\/abifer.org.br\/en\/\",\"name\":\"ABIFER\",\"description\":\"Associa\u00e7\u00e3o Brasileira da Ind\u00fastria Ferrovi\u00e1ria\",\"publisher\":{\"@id\":\"https:\/\/abifer.org.br\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/abifer.org.br\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/abifer.org.br\/dinheiro-privado-em-ferrovias-governo-federal-endurece-fiscalizacao\/#primaryimage\",\"inLanguage\":\"pt-BR\",\"url\":\"https:\/\/abifer.org.br\/wp-content\/uploads\/2025\/02\/bandeira-brasil.webp\",\"contentUrl\":\"https:\/\/abifer.org.br\/wp-content\/uploads\/2025\/02\/bandeira-brasil.webp\",\"width\":1024,\"height\":1024},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/abifer.org.br\/dinheiro-privado-em-ferrovias-governo-federal-endurece-fiscalizacao\/#webpage\",\"url\":\"https:\/\/abifer.org.br\/dinheiro-privado-em-ferrovias-governo-federal-endurece-fiscalizacao\/\",\"name\":\"Dinheiro privado em ferrovias: governo federal endurece fiscaliza\u00e7\u00e3o\",\"isPartOf\":{\"@id\":\"https:\/\/abifer.org.br\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/abifer.org.br\/dinheiro-privado-em-ferrovias-governo-federal-endurece-fiscalizacao\/#primaryimage\"},\"datePublished\":\"2026-01-23T18:26:38+00:00\",\"dateModified\":\"2026-01-23T18:26:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/abifer.org.br\/dinheiro-privado-em-ferrovias-governo-federal-endurece-fiscalizacao\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/abifer.org.br\/dinheiro-privado-em-ferrovias-governo-federal-endurece-fiscalizacao\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/abifer.org.br\/dinheiro-privado-em-ferrovias-governo-federal-endurece-fiscalizacao\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/abifer.org.br\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dinheiro privado em ferrovias: governo federal endurece fiscaliza\u00e7\u00e3o\"}]},{\"@type\":\"Article\",\"@id\":\"https:\/\/abifer.org.br\/dinheiro-privado-em-ferrovias-governo-federal-endurece-fiscalizacao\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/abifer.org.br\/dinheiro-privado-em-ferrovias-governo-federal-endurece-fiscalizacao\/#webpage\"},\"author\":{\"@id\":\"https:\/\/abifer.org.br\/en\/#\/schema\/person\/90c38c3286f60a11b363834930f79a1f\"},\"headline\":\"Dinheiro privado em ferrovias: governo federal endurece fiscaliza\u00e7\u00e3o\",\"datePublished\":\"2026-01-23T18:26:38+00:00\",\"dateModified\":\"2026-01-23T18:26:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/abifer.org.br\/dinheiro-privado-em-ferrovias-governo-federal-endurece-fiscalizacao\/#webpage\"},\"wordCount\":327,\"publisher\":{\"@id\":\"https:\/\/abifer.org.br\/en\/#organization\"},\"image\":{\"@id\":\"https:\/\/abifer.org.br\/dinheiro-privado-em-ferrovias-governo-federal-endurece-fiscalizacao\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/abifer.org.br\/wp-content\/uploads\/2025\/02\/bandeira-brasil.webp\",\"articleSection\":[\"Not\u00edcias do Mercado\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/abifer.org.br\/en\/#\/schema\/person\/90c38c3286f60a11b363834930f79a1f\",\"name\":\"ABIFER\",\"url\":\"https:\/\/abifer.org.br\/author\/abifer\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dinheiro privado em ferrovias: governo federal endurece fiscaliza\u00e7\u00e3o","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/abifer.org.br\/dinheiro-privado-em-ferrovias-governo-federal-endurece-fiscalizacao\/","og_locale":"pt_BR","og_type":"article","og_title":"Dinheiro privado em ferrovias: governo federal endurece fiscaliza\u00e7\u00e3o","og_description":"Fonte: R7 Data: 23\/01\/2026 Pasta quer produ\u00e7\u00e3o de relat\u00f3rios e acompanhamento dos recursos investidos O Minist\u00e9rio dos Transportes vai acompanhar de perto os recursos privados investidos em ferrovias brasileiras. Em portaria publicada nesta sexta-feira (23), a pasta endureceu as regras de controle e fiscaliza\u00e7\u00e3o dessas verbas. Agora, os valores com origem em acordos firmados entre\u00a0governo\u00a0e [&hellip;]","og_url":"https:\/\/abifer.org.br\/dinheiro-privado-em-ferrovias-governo-federal-endurece-fiscalizacao\/","og_site_name":"ABIFER","article_publisher":"https:\/\/www.facebook.com\/abiferoficial\/","article_published_time":"2026-01-23T18:26:38+00:00","twitter_card":"summary_large_image","twitter_image":"https:\/\/abifer.org.br\/wp-content\/uploads\/2025\/02\/bandeira-brasil.webp","twitter_creator":"@abiferoficial","twitter_site":"@abiferoficial","twitter_misc":{"Escrito por":"ABIFER","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Organization","@id":"https:\/\/abifer.org.br\/en\/#organization","name":"ABIFER","url":"https:\/\/abifer.org.br\/en\/","sameAs":["https:\/\/www.facebook.com\/abiferoficial\/","https:\/\/www.linkedin.com\/company\/abiferoficial\/","https:\/\/twitter.com\/abiferoficial"],"logo":{"@type":"ImageObject","@id":"https:\/\/abifer.org.br\/en\/#logo","inLanguage":"pt-BR","url":"https:\/\/abifer.org.br\/wp-content\/uploads\/2018\/05\/ABF_001_LogoSlogan.jpg","contentUrl":"https:\/\/abifer.org.br\/wp-content\/uploads\/2018\/05\/ABF_001_LogoSlogan.jpg","width":1182,"height":486,"caption":"ABIFER"},"image":{"@id":"https:\/\/abifer.org.br\/en\/#logo"}},{"@type":"WebSite","@id":"https:\/\/abifer.org.br\/en\/#website","url":"https:\/\/abifer.org.br\/en\/","name":"ABIFER","description":"Associa\u00e7\u00e3o Brasileira da Ind\u00fastria Ferrovi\u00e1ria","publisher":{"@id":"https:\/\/abifer.org.br\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/abifer.org.br\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"ImageObject","@id":"https:\/\/abifer.org.br\/dinheiro-privado-em-ferrovias-governo-federal-endurece-fiscalizacao\/#primaryimage","inLanguage":"pt-BR","url":"https:\/\/abifer.org.br\/wp-content\/uploads\/2025\/02\/bandeira-brasil.webp","contentUrl":"https:\/\/abifer.org.br\/wp-content\/uploads\/2025\/02\/bandeira-brasil.webp","width":1024,"height":1024},{"@type":"WebPage","@id":"https:\/\/abifer.org.br\/dinheiro-privado-em-ferrovias-governo-federal-endurece-fiscalizacao\/#webpage","url":"https:\/\/abifer.org.br\/dinheiro-privado-em-ferrovias-governo-federal-endurece-fiscalizacao\/","name":"Dinheiro privado em ferrovias: governo federal endurece fiscaliza\u00e7\u00e3o","isPartOf":{"@id":"https:\/\/abifer.org.br\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/abifer.org.br\/dinheiro-privado-em-ferrovias-governo-federal-endurece-fiscalizacao\/#primaryimage"},"datePublished":"2026-01-23T18:26:38+00:00","dateModified":"2026-01-23T18:26:38+00:00","breadcrumb":{"@id":"https:\/\/abifer.org.br\/dinheiro-privado-em-ferrovias-governo-federal-endurece-fiscalizacao\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/abifer.org.br\/dinheiro-privado-em-ferrovias-governo-federal-endurece-fiscalizacao\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/abifer.org.br\/dinheiro-privado-em-ferrovias-governo-federal-endurece-fiscalizacao\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/abifer.org.br\/en\/"},{"@type":"ListItem","position":2,"name":"Dinheiro privado em ferrovias: governo federal endurece fiscaliza\u00e7\u00e3o"}]},{"@type":"Article","@id":"https:\/\/abifer.org.br\/dinheiro-privado-em-ferrovias-governo-federal-endurece-fiscalizacao\/#article","isPartOf":{"@id":"https:\/\/abifer.org.br\/dinheiro-privado-em-ferrovias-governo-federal-endurece-fiscalizacao\/#webpage"},"author":{"@id":"https:\/\/abifer.org.br\/en\/#\/schema\/person\/90c38c3286f60a11b363834930f79a1f"},"headline":"Dinheiro privado em ferrovias: governo federal endurece fiscaliza\u00e7\u00e3o","datePublished":"2026-01-23T18:26:38+00:00","dateModified":"2026-01-23T18:26:38+00:00","mainEntityOfPage":{"@id":"https:\/\/abifer.org.br\/dinheiro-privado-em-ferrovias-governo-federal-endurece-fiscalizacao\/#webpage"},"wordCount":327,"publisher":{"@id":"https:\/\/abifer.org.br\/en\/#organization"},"image":{"@id":"https:\/\/abifer.org.br\/dinheiro-privado-em-ferrovias-governo-federal-endurece-fiscalizacao\/#primaryimage"},"thumbnailUrl":"https:\/\/abifer.org.br\/wp-content\/uploads\/2025\/02\/bandeira-brasil.webp","articleSection":["Not\u00edcias do Mercado"],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/abifer.org.br\/en\/#\/schema\/person\/90c38c3286f60a11b363834930f79a1f","name":"ABIFER","url":"https:\/\/abifer.org.br\/author\/abifer\/"}]}},"_links":{"self":[{"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/posts\/92282\/"}],"collection":[{"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/posts\/"}],"about":[{"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/types\/post\/"}],"author":[{"embeddable":true,"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/users\/55\/"}],"replies":[{"embeddable":true,"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/comments\/?post=92282"}],"version-history":[{"count":1,"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/posts\/92282\/revisions\/"}],"predecessor-version":[{"id":92283,"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/posts\/92282\/revisions\/92283\/"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/media\/86710\/"}],"wp:attachment":[{"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/media\/?parent=92282"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/categories\/?post=92282"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/tags\/?post=92282"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}