{"id":92375,"date":"2026-02-02T16:28:16","date_gmt":"2026-02-02T19:28:16","guid":{"rendered":"https:\/\/abifer.org.br\/?p=92375"},"modified":"2026-02-02T16:28:16","modified_gmt":"2026-02-02T19:28:16","slug":"hidremec-celebra-25-anos-de-excelencia-na-producao-de-dormentes-de-aco","status":"publish","type":"post","link":"https:\/\/abifer.org.br\/en\/hidremec-celebra-25-anos-de-excelencia-na-producao-de-dormentes-de-aco\/","title":{"rendered":"Hidremec celebra 25 anos de excel\u00eancia na produ\u00e7\u00e3o de dormentes de a\u00e7o"},"content":{"rendered":"<pre style=\"text-align: right;\"><strong><em>Fonte: Assessoria Hidremec\r\nData: 02\/02\/2026<\/em><\/strong><\/pre>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-92376 alignleft\" src=\"http:\/\/abifer.org.br\/wp-content\/uploads\/2026\/02\/hidremec-dormentes-aco-300x169.jpeg\" alt=\"\" width=\"300\" height=\"169\" srcset=\"https:\/\/abifer.org.br\/wp-content\/uploads\/2026\/02\/hidremec-dormentes-aco-300x169.jpeg 300w, https:\/\/abifer.org.br\/wp-content\/uploads\/2026\/02\/hidremec-dormentes-aco-1024x578.jpeg 1024w, https:\/\/abifer.org.br\/wp-content\/uploads\/2026\/02\/hidremec-dormentes-aco-768x434.jpeg 768w, https:\/\/abifer.org.br\/wp-content\/uploads\/2026\/02\/hidremec-dormentes-aco.jpeg 1280w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>A Hidremec celebra 25 anos de uma trajet\u00f3ria marcada por crescimento, inova\u00e7\u00e3o e contribui\u00e7\u00e3o relevante para o desenvolvimento da infraestrutura ferrovi\u00e1ria brasileira. Fundada em 2 de fevereiro de 2001, em S\u00e3o Paulo, a empresa iniciou suas atividades com uma discreta produ\u00e7\u00e3o e, ao longo dos anos, consolidou-se como refer\u00eancia no segmento.<\/p>\n<p>Visando \u00e0 expans\u00e3o de sua capacidade produtiva e ao aprimoramento da log\u00edstica, a Hidremec transferiu sua opera\u00e7\u00e3o para Cariacica, no Esp\u00edrito Santo. O que come\u00e7ou em um galp\u00e3o simples transformou-se em uma moderna e robusta planta industrial, que hoje emprega mais de 100 colaboradores e opera com produ\u00e7\u00e3o cont\u00ednua de dormentes de a\u00e7o.<\/p>\n<p>Os dormentes produzidos pela Hidremec destacam-se pela alta durabilidade, qualidade e confiabilidade, sendo certificados pelo Laborat\u00f3rio de Ensaios Din\u00e2micos da Unicamp (LABEDIN) e desenvolvidos em conformidade com normas internacionais. Ao longo de sua hist\u00f3ria, a empresa promoveu uma evolu\u00e7\u00e3o consistente de seus processos produtivos, aprimorando a fabrica\u00e7\u00e3o manual para etapas mecanizadas e, posteriormente, para um ambiente altamente tecnol\u00f3gico, com o uso de rob\u00f4s auxiliando a soldagem e equipamentos de \u00faltima gera\u00e7\u00e3o. Esse investimento cont\u00ednuo em tecnologia resulta em produtos cada vez mais resistentes, eficientes e sustent\u00e1veis.<\/p>\n<p>Estrat\u00e9gicamente localizada, a unidade capixaba conta com um ramal da Estrada de Ferro Vit\u00f3ria a Minas em sua pr\u00f3pria \u00e1rea, al\u00e9m de f\u00e1cil acesso aos modais rodovi\u00e1rio e aquavi\u00e1rio, o que assegura efici\u00eancia no escoamento da produ\u00e7\u00e3o e no recebimento de mat\u00e9rias-primas.<\/p>\n<p>Com capacidade instalada para produzir at\u00e9 60 mil dormentes por m\u00eas, a Hidremec j\u00e1 fabricou, ao longo de sua hist\u00f3ria, aproximadamente 6 milh\u00f5es de dormentes, permitindo vias ferrovi\u00e1rias equipadas com dormentes de a\u00e7o, contribuindo de forma expressiva para a expans\u00e3o e moderniza\u00e7\u00e3o da malha ferrovi\u00e1ria nacional.<\/p>\n<p>Como resultado de um processo estruturado de crescimento, a Hidremec tamb\u00e9m ampliou seu portf\u00f3lio e diversificou sua atua\u00e7\u00e3o no mercado ferrovi\u00e1rio, passando a fornecer chaparias para Aparelhos de Mudan\u00e7a de Via (AMV), contratrilhos de ponte e outros materiais ferrovi\u00e1rios. Essa amplia\u00e7\u00e3o foi impulsionada pela associa\u00e7\u00e3o com a BR Rail Equipamentos, da qual a Hidremec det\u00e9m participa\u00e7\u00e3o acion\u00e1ria, refor\u00e7ando sua posi\u00e7\u00e3o estrat\u00e9gica e seu compromisso com solu\u00e7\u00f5es completas para o setor.<\/p>\n<p>Ao celebrar seus 25 anos, a Hidremec reafirma seu compromisso com a qualidade, a inova\u00e7\u00e3o e o desenvolvimento sustent\u00e1vel das ferrovias, projetando o futuro com a solidez de quem construiu uma hist\u00f3ria de confian\u00e7a e excel\u00eancia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fonte: Assessoria Hidremec Data: 02\/02\/2026 A Hidremec celebra 25 anos de uma trajet\u00f3ria marcada por crescimento, inova\u00e7\u00e3o e contribui\u00e7\u00e3o relevante para o desenvolvimento da infraestrutura ferrovi\u00e1ria brasileira. Fundada em 2 de fevereiro de 2001, em S\u00e3o Paulo, a empresa iniciou suas atividades com uma discreta produ\u00e7\u00e3o e, ao longo dos anos, consolidou-se como refer\u00eancia no [&hellip;]<\/p>\n","protected":false},"author":55,"featured_media":92376,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[875],"tags":[],"class_list":["post-92375","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-do-mercado"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Hidremec celebra 25 anos de excel\u00eancia na produ\u00e7\u00e3o de dormentes de a\u00e7o<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/abifer.org.br\/hidremec-celebra-25-anos-de-excelencia-na-producao-de-dormentes-de-aco\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hidremec celebra 25 anos de excel\u00eancia na produ\u00e7\u00e3o de dormentes de a\u00e7o\" \/>\n<meta property=\"og:description\" content=\"Fonte: Assessoria Hidremec Data: 02\/02\/2026 A Hidremec celebra 25 anos de uma trajet\u00f3ria marcada por crescimento, inova\u00e7\u00e3o e contribui\u00e7\u00e3o relevante para o desenvolvimento da infraestrutura ferrovi\u00e1ria brasileira. Fundada em 2 de fevereiro de 2001, em S\u00e3o Paulo, a empresa iniciou suas atividades com uma discreta produ\u00e7\u00e3o e, ao longo dos anos, consolidou-se como refer\u00eancia no [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"http:\/\/abifer.org.br\/hidremec-celebra-25-anos-de-excelencia-na-producao-de-dormentes-de-aco\/\" \/>\n<meta property=\"og:site_name\" content=\"ABIFER\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/abiferoficial\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-02T19:28:16+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/abifer.org.br\/wp-content\/uploads\/2026\/02\/hidremec-dormentes-aco.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"723\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@abiferoficial\" \/>\n<meta name=\"twitter:site\" content=\"@abiferoficial\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"ABIFER\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/abifer.org.br\/en\/#organization\",\"name\":\"ABIFER\",\"url\":\"https:\/\/abifer.org.br\/en\/\",\"sameAs\":[\"https:\/\/www.facebook.com\/abiferoficial\/\",\"https:\/\/www.linkedin.com\/company\/abiferoficial\/\",\"https:\/\/twitter.com\/abiferoficial\"],\"logo\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/abifer.org.br\/en\/#logo\",\"inLanguage\":\"pt-BR\",\"url\":\"https:\/\/abifer.org.br\/wp-content\/uploads\/2018\/05\/ABF_001_LogoSlogan.jpg\",\"contentUrl\":\"https:\/\/abifer.org.br\/wp-content\/uploads\/2018\/05\/ABF_001_LogoSlogan.jpg\",\"width\":1182,\"height\":486,\"caption\":\"ABIFER\"},\"image\":{\"@id\":\"https:\/\/abifer.org.br\/en\/#logo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/abifer.org.br\/en\/#website\",\"url\":\"https:\/\/abifer.org.br\/en\/\",\"name\":\"ABIFER\",\"description\":\"Associa\u00e7\u00e3o Brasileira da Ind\u00fastria Ferrovi\u00e1ria\",\"publisher\":{\"@id\":\"https:\/\/abifer.org.br\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/abifer.org.br\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"ImageObject\",\"@id\":\"http:\/\/abifer.org.br\/hidremec-celebra-25-anos-de-excelencia-na-producao-de-dormentes-de-aco\/#primaryimage\",\"inLanguage\":\"pt-BR\",\"url\":\"https:\/\/abifer.org.br\/wp-content\/uploads\/2026\/02\/hidremec-dormentes-aco.jpeg\",\"contentUrl\":\"https:\/\/abifer.org.br\/wp-content\/uploads\/2026\/02\/hidremec-dormentes-aco.jpeg\",\"width\":1280,\"height\":723},{\"@type\":\"WebPage\",\"@id\":\"http:\/\/abifer.org.br\/hidremec-celebra-25-anos-de-excelencia-na-producao-de-dormentes-de-aco\/#webpage\",\"url\":\"http:\/\/abifer.org.br\/hidremec-celebra-25-anos-de-excelencia-na-producao-de-dormentes-de-aco\/\",\"name\":\"Hidremec celebra 25 anos de excel\u00eancia na produ\u00e7\u00e3o de dormentes de a\u00e7o\",\"isPartOf\":{\"@id\":\"https:\/\/abifer.org.br\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\/\/abifer.org.br\/hidremec-celebra-25-anos-de-excelencia-na-producao-de-dormentes-de-aco\/#primaryimage\"},\"datePublished\":\"2026-02-02T19:28:16+00:00\",\"dateModified\":\"2026-02-02T19:28:16+00:00\",\"breadcrumb\":{\"@id\":\"http:\/\/abifer.org.br\/hidremec-celebra-25-anos-de-excelencia-na-producao-de-dormentes-de-aco\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/abifer.org.br\/hidremec-celebra-25-anos-de-excelencia-na-producao-de-dormentes-de-aco\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/abifer.org.br\/hidremec-celebra-25-anos-de-excelencia-na-producao-de-dormentes-de-aco\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/abifer.org.br\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Hidremec celebra 25 anos de excel\u00eancia na produ\u00e7\u00e3o de dormentes de a\u00e7o\"}]},{\"@type\":\"Article\",\"@id\":\"http:\/\/abifer.org.br\/hidremec-celebra-25-anos-de-excelencia-na-producao-de-dormentes-de-aco\/#article\",\"isPartOf\":{\"@id\":\"http:\/\/abifer.org.br\/hidremec-celebra-25-anos-de-excelencia-na-producao-de-dormentes-de-aco\/#webpage\"},\"author\":{\"@id\":\"https:\/\/abifer.org.br\/en\/#\/schema\/person\/90c38c3286f60a11b363834930f79a1f\"},\"headline\":\"Hidremec celebra 25 anos de excel\u00eancia na produ\u00e7\u00e3o de dormentes de a\u00e7o\",\"datePublished\":\"2026-02-02T19:28:16+00:00\",\"dateModified\":\"2026-02-02T19:28:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\/\/abifer.org.br\/hidremec-celebra-25-anos-de-excelencia-na-producao-de-dormentes-de-aco\/#webpage\"},\"wordCount\":454,\"publisher\":{\"@id\":\"https:\/\/abifer.org.br\/en\/#organization\"},\"image\":{\"@id\":\"http:\/\/abifer.org.br\/hidremec-celebra-25-anos-de-excelencia-na-producao-de-dormentes-de-aco\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/abifer.org.br\/wp-content\/uploads\/2026\/02\/hidremec-dormentes-aco.jpeg\",\"articleSection\":[\"Not\u00edcias do Mercado\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/abifer.org.br\/en\/#\/schema\/person\/90c38c3286f60a11b363834930f79a1f\",\"name\":\"ABIFER\",\"url\":\"https:\/\/abifer.org.br\/author\/abifer\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hidremec celebra 25 anos de excel\u00eancia na produ\u00e7\u00e3o de dormentes de a\u00e7o","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/abifer.org.br\/hidremec-celebra-25-anos-de-excelencia-na-producao-de-dormentes-de-aco\/","og_locale":"pt_BR","og_type":"article","og_title":"Hidremec celebra 25 anos de excel\u00eancia na produ\u00e7\u00e3o de dormentes de a\u00e7o","og_description":"Fonte: Assessoria Hidremec Data: 02\/02\/2026 A Hidremec celebra 25 anos de uma trajet\u00f3ria marcada por crescimento, inova\u00e7\u00e3o e contribui\u00e7\u00e3o relevante para o desenvolvimento da infraestrutura ferrovi\u00e1ria brasileira. Fundada em 2 de fevereiro de 2001, em S\u00e3o Paulo, a empresa iniciou suas atividades com uma discreta produ\u00e7\u00e3o e, ao longo dos anos, consolidou-se como refer\u00eancia no [&hellip;]","og_url":"http:\/\/abifer.org.br\/hidremec-celebra-25-anos-de-excelencia-na-producao-de-dormentes-de-aco\/","og_site_name":"ABIFER","article_publisher":"https:\/\/www.facebook.com\/abiferoficial\/","article_published_time":"2026-02-02T19:28:16+00:00","og_image":[{"width":1280,"height":723,"url":"http:\/\/abifer.org.br\/wp-content\/uploads\/2026\/02\/hidremec-dormentes-aco.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_creator":"@abiferoficial","twitter_site":"@abiferoficial","twitter_misc":{"Escrito por":"ABIFER","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Organization","@id":"https:\/\/abifer.org.br\/en\/#organization","name":"ABIFER","url":"https:\/\/abifer.org.br\/en\/","sameAs":["https:\/\/www.facebook.com\/abiferoficial\/","https:\/\/www.linkedin.com\/company\/abiferoficial\/","https:\/\/twitter.com\/abiferoficial"],"logo":{"@type":"ImageObject","@id":"https:\/\/abifer.org.br\/en\/#logo","inLanguage":"pt-BR","url":"https:\/\/abifer.org.br\/wp-content\/uploads\/2018\/05\/ABF_001_LogoSlogan.jpg","contentUrl":"https:\/\/abifer.org.br\/wp-content\/uploads\/2018\/05\/ABF_001_LogoSlogan.jpg","width":1182,"height":486,"caption":"ABIFER"},"image":{"@id":"https:\/\/abifer.org.br\/en\/#logo"}},{"@type":"WebSite","@id":"https:\/\/abifer.org.br\/en\/#website","url":"https:\/\/abifer.org.br\/en\/","name":"ABIFER","description":"Associa\u00e7\u00e3o Brasileira da Ind\u00fastria Ferrovi\u00e1ria","publisher":{"@id":"https:\/\/abifer.org.br\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/abifer.org.br\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"ImageObject","@id":"http:\/\/abifer.org.br\/hidremec-celebra-25-anos-de-excelencia-na-producao-de-dormentes-de-aco\/#primaryimage","inLanguage":"pt-BR","url":"https:\/\/abifer.org.br\/wp-content\/uploads\/2026\/02\/hidremec-dormentes-aco.jpeg","contentUrl":"https:\/\/abifer.org.br\/wp-content\/uploads\/2026\/02\/hidremec-dormentes-aco.jpeg","width":1280,"height":723},{"@type":"WebPage","@id":"http:\/\/abifer.org.br\/hidremec-celebra-25-anos-de-excelencia-na-producao-de-dormentes-de-aco\/#webpage","url":"http:\/\/abifer.org.br\/hidremec-celebra-25-anos-de-excelencia-na-producao-de-dormentes-de-aco\/","name":"Hidremec celebra 25 anos de excel\u00eancia na produ\u00e7\u00e3o de dormentes de a\u00e7o","isPartOf":{"@id":"https:\/\/abifer.org.br\/en\/#website"},"primaryImageOfPage":{"@id":"http:\/\/abifer.org.br\/hidremec-celebra-25-anos-de-excelencia-na-producao-de-dormentes-de-aco\/#primaryimage"},"datePublished":"2026-02-02T19:28:16+00:00","dateModified":"2026-02-02T19:28:16+00:00","breadcrumb":{"@id":"http:\/\/abifer.org.br\/hidremec-celebra-25-anos-de-excelencia-na-producao-de-dormentes-de-aco\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["http:\/\/abifer.org.br\/hidremec-celebra-25-anos-de-excelencia-na-producao-de-dormentes-de-aco\/"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/abifer.org.br\/hidremec-celebra-25-anos-de-excelencia-na-producao-de-dormentes-de-aco\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/abifer.org.br\/en\/"},{"@type":"ListItem","position":2,"name":"Hidremec celebra 25 anos de excel\u00eancia na produ\u00e7\u00e3o de dormentes de a\u00e7o"}]},{"@type":"Article","@id":"http:\/\/abifer.org.br\/hidremec-celebra-25-anos-de-excelencia-na-producao-de-dormentes-de-aco\/#article","isPartOf":{"@id":"http:\/\/abifer.org.br\/hidremec-celebra-25-anos-de-excelencia-na-producao-de-dormentes-de-aco\/#webpage"},"author":{"@id":"https:\/\/abifer.org.br\/en\/#\/schema\/person\/90c38c3286f60a11b363834930f79a1f"},"headline":"Hidremec celebra 25 anos de excel\u00eancia na produ\u00e7\u00e3o de dormentes de a\u00e7o","datePublished":"2026-02-02T19:28:16+00:00","dateModified":"2026-02-02T19:28:16+00:00","mainEntityOfPage":{"@id":"http:\/\/abifer.org.br\/hidremec-celebra-25-anos-de-excelencia-na-producao-de-dormentes-de-aco\/#webpage"},"wordCount":454,"publisher":{"@id":"https:\/\/abifer.org.br\/en\/#organization"},"image":{"@id":"http:\/\/abifer.org.br\/hidremec-celebra-25-anos-de-excelencia-na-producao-de-dormentes-de-aco\/#primaryimage"},"thumbnailUrl":"https:\/\/abifer.org.br\/wp-content\/uploads\/2026\/02\/hidremec-dormentes-aco.jpeg","articleSection":["Not\u00edcias do Mercado"],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/abifer.org.br\/en\/#\/schema\/person\/90c38c3286f60a11b363834930f79a1f","name":"ABIFER","url":"https:\/\/abifer.org.br\/author\/abifer\/"}]}},"_links":{"self":[{"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/posts\/92375\/"}],"collection":[{"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/posts\/"}],"about":[{"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/types\/post\/"}],"author":[{"embeddable":true,"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/users\/55\/"}],"replies":[{"embeddable":true,"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/comments\/?post=92375"}],"version-history":[{"count":1,"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/posts\/92375\/revisions\/"}],"predecessor-version":[{"id":92378,"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/posts\/92375\/revisions\/92378\/"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/media\/92376\/"}],"wp:attachment":[{"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/media\/?parent=92375"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/categories\/?post=92375"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/tags\/?post=92375"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}