{"id":92506,"date":"2026-02-09T18:31:54","date_gmt":"2026-02-09T21:31:54","guid":{"rendered":"https:\/\/abifer.org.br\/?p=92506"},"modified":"2026-02-09T18:31:54","modified_gmt":"2026-02-09T21:31:54","slug":"transnordestina-tera-10-terminais-ao-longo-da-ferrovia","status":"publish","type":"post","link":"https:\/\/abifer.org.br\/en\/transnordestina-tera-10-terminais-ao-longo-da-ferrovia\/","title":{"rendered":"Transnordestina ter\u00e1 10 terminais ao longo da ferrovia"},"content":{"rendered":"<pre style=\"text-align: right;\"><a href=\"https:\/\/agenciainfra.com\/blog\/transnordestina-tera-10-terminais-ao-longo-da-ferrovia\/\" target=\"_blank\" rel=\"noopener\"><strong><em>Fonte: Ag\u00eancia iNFRA\r\nData: 05\/02\/2026<\/em><\/strong><\/a><\/pre>\n<p>A Ferrovia Transnordestina contar\u00e1 com dez terminais log\u00edsticos ao longo do tra\u00e7ado para ampliar a movimenta\u00e7\u00e3o de cargas e integrar o transporte ferrovi\u00e1rio \u00e0 distribui\u00e7\u00e3o rodovi\u00e1ria no Nordeste. A estrutura incluir\u00e1 nove terminais intermodais e um porto seco, com unidades previstas no Piau\u00ed, Pernambuco e Cear\u00e1, parte operada pela TLSA (Transnordestina Log\u00edstica) e parte por investidores privados.<\/p>\n<p>O primeiro terminal privado em constru\u00e7\u00e3o \u00e9 o de Iguatu (CE), com in\u00edcio de opera\u00e7\u00e3o previsto para maio. O empreendimento dever\u00e1 movimentar cerca de 20 mil toneladas mensais de gr\u00e3os e farelo e oferecer servi\u00e7os como transbordo, armazenagem e entrega final por caminh\u00e3o, permitindo atender desde grandes embarcadores at\u00e9 pequenas empresas.<\/p>\n<p>A operadora estima que a integra\u00e7\u00e3o entre ferrovia e terminais reduza custos de frete e amplie o acesso ao transporte de carga. Al\u00e9m de Iguatu, est\u00e3o previstos terminais em Eliseu Martins e Bela Vista do Piau\u00ed (PI), Trindade e Salgueiro (PE), Miss\u00e3o Velha, Quixad\u00e1 e Maranguape (CE), al\u00e9m de um porto seco em Quixeramobim (CE) e conex\u00e3o com o Porto do Pec\u00e9m.<\/p>\n<p>A ferrovia \u00e9 voltada principalmente ao escoamento de gr\u00e3os, fertilizantes, combust\u00edveis e outras cargas industriais, ligando \u00e1reas produtoras do interior ao litoral e aos portos da regi\u00e3o.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fonte: Ag\u00eancia iNFRA Data: 05\/02\/2026 A Ferrovia Transnordestina contar\u00e1 com dez terminais log\u00edsticos ao longo do tra\u00e7ado para ampliar a movimenta\u00e7\u00e3o de cargas e integrar o transporte ferrovi\u00e1rio \u00e0 distribui\u00e7\u00e3o rodovi\u00e1ria no Nordeste. A estrutura incluir\u00e1 nove terminais intermodais e um porto seco, com unidades previstas no Piau\u00ed, Pernambuco e Cear\u00e1, parte operada pela TLSA [&hellip;]<\/p>\n","protected":false},"author":55,"featured_media":86710,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[875],"tags":[],"class_list":["post-92506","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-do-mercado"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Transnordestina ter\u00e1 10 terminais ao longo da ferrovia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/abifer.org.br\/transnordestina-tera-10-terminais-ao-longo-da-ferrovia\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Transnordestina ter\u00e1 10 terminais ao longo da ferrovia\" \/>\n<meta property=\"og:description\" content=\"Fonte: Ag\u00eancia iNFRA Data: 05\/02\/2026 A Ferrovia Transnordestina contar\u00e1 com dez terminais log\u00edsticos ao longo do tra\u00e7ado para ampliar a movimenta\u00e7\u00e3o de cargas e integrar o transporte ferrovi\u00e1rio \u00e0 distribui\u00e7\u00e3o rodovi\u00e1ria no Nordeste. A estrutura incluir\u00e1 nove terminais intermodais e um porto seco, com unidades previstas no Piau\u00ed, Pernambuco e Cear\u00e1, parte operada pela TLSA [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/abifer.org.br\/en\/transnordestina-tera-10-terminais-ao-longo-da-ferrovia\/\" \/>\n<meta property=\"og:site_name\" content=\"ABIFER\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/abiferoficial\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-09T21:31:54+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/abifer.org.br\/wp-content\/uploads\/2025\/02\/bandeira-brasil.webp\" \/>\n<meta name=\"twitter:creator\" content=\"@abiferoficial\" \/>\n<meta name=\"twitter:site\" content=\"@abiferoficial\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"ABIFER\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/abifer.org.br\/en\/#organization\",\"name\":\"ABIFER\",\"url\":\"https:\/\/abifer.org.br\/en\/\",\"sameAs\":[\"https:\/\/www.facebook.com\/abiferoficial\/\",\"https:\/\/www.linkedin.com\/company\/abiferoficial\/\",\"https:\/\/twitter.com\/abiferoficial\"],\"logo\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/abifer.org.br\/en\/#logo\",\"inLanguage\":\"pt-BR\",\"url\":\"https:\/\/abifer.org.br\/wp-content\/uploads\/2018\/05\/ABF_001_LogoSlogan.jpg\",\"contentUrl\":\"https:\/\/abifer.org.br\/wp-content\/uploads\/2018\/05\/ABF_001_LogoSlogan.jpg\",\"width\":1182,\"height\":486,\"caption\":\"ABIFER\"},\"image\":{\"@id\":\"https:\/\/abifer.org.br\/en\/#logo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/abifer.org.br\/en\/#website\",\"url\":\"https:\/\/abifer.org.br\/en\/\",\"name\":\"ABIFER\",\"description\":\"Associa\u00e7\u00e3o Brasileira da Ind\u00fastria Ferrovi\u00e1ria\",\"publisher\":{\"@id\":\"https:\/\/abifer.org.br\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/abifer.org.br\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/abifer.org.br\/en\/transnordestina-tera-10-terminais-ao-longo-da-ferrovia\/#primaryimage\",\"inLanguage\":\"pt-BR\",\"url\":\"https:\/\/abifer.org.br\/wp-content\/uploads\/2025\/02\/bandeira-brasil.webp\",\"contentUrl\":\"https:\/\/abifer.org.br\/wp-content\/uploads\/2025\/02\/bandeira-brasil.webp\",\"width\":1024,\"height\":1024},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/abifer.org.br\/en\/transnordestina-tera-10-terminais-ao-longo-da-ferrovia\/#webpage\",\"url\":\"https:\/\/abifer.org.br\/en\/transnordestina-tera-10-terminais-ao-longo-da-ferrovia\/\",\"name\":\"Transnordestina ter\u00e1 10 terminais ao longo da ferrovia\",\"isPartOf\":{\"@id\":\"https:\/\/abifer.org.br\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/abifer.org.br\/en\/transnordestina-tera-10-terminais-ao-longo-da-ferrovia\/#primaryimage\"},\"datePublished\":\"2026-02-09T21:31:54+00:00\",\"dateModified\":\"2026-02-09T21:31:54+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/abifer.org.br\/en\/transnordestina-tera-10-terminais-ao-longo-da-ferrovia\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/abifer.org.br\/en\/transnordestina-tera-10-terminais-ao-longo-da-ferrovia\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/abifer.org.br\/en\/transnordestina-tera-10-terminais-ao-longo-da-ferrovia\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/abifer.org.br\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Transnordestina ter\u00e1 10 terminais ao longo da ferrovia\"}]},{\"@type\":\"Article\",\"@id\":\"https:\/\/abifer.org.br\/en\/transnordestina-tera-10-terminais-ao-longo-da-ferrovia\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/abifer.org.br\/en\/transnordestina-tera-10-terminais-ao-longo-da-ferrovia\/#webpage\"},\"author\":{\"@id\":\"https:\/\/abifer.org.br\/en\/#\/schema\/person\/90c38c3286f60a11b363834930f79a1f\"},\"headline\":\"Transnordestina ter\u00e1 10 terminais ao longo da ferrovia\",\"datePublished\":\"2026-02-09T21:31:54+00:00\",\"dateModified\":\"2026-02-09T21:31:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/abifer.org.br\/en\/transnordestina-tera-10-terminais-ao-longo-da-ferrovia\/#webpage\"},\"wordCount\":223,\"publisher\":{\"@id\":\"https:\/\/abifer.org.br\/en\/#organization\"},\"image\":{\"@id\":\"https:\/\/abifer.org.br\/en\/transnordestina-tera-10-terminais-ao-longo-da-ferrovia\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/abifer.org.br\/wp-content\/uploads\/2025\/02\/bandeira-brasil.webp\",\"articleSection\":[\"Not\u00edcias do Mercado\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/abifer.org.br\/en\/#\/schema\/person\/90c38c3286f60a11b363834930f79a1f\",\"name\":\"ABIFER\",\"url\":\"https:\/\/abifer.org.br\/author\/abifer\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Transnordestina ter\u00e1 10 terminais ao longo da ferrovia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/abifer.org.br\/transnordestina-tera-10-terminais-ao-longo-da-ferrovia\/","og_locale":"pt_BR","og_type":"article","og_title":"Transnordestina ter\u00e1 10 terminais ao longo da ferrovia","og_description":"Fonte: Ag\u00eancia iNFRA Data: 05\/02\/2026 A Ferrovia Transnordestina contar\u00e1 com dez terminais log\u00edsticos ao longo do tra\u00e7ado para ampliar a movimenta\u00e7\u00e3o de cargas e integrar o transporte ferrovi\u00e1rio \u00e0 distribui\u00e7\u00e3o rodovi\u00e1ria no Nordeste. A estrutura incluir\u00e1 nove terminais intermodais e um porto seco, com unidades previstas no Piau\u00ed, Pernambuco e Cear\u00e1, parte operada pela TLSA [&hellip;]","og_url":"https:\/\/abifer.org.br\/en\/transnordestina-tera-10-terminais-ao-longo-da-ferrovia\/","og_site_name":"ABIFER","article_publisher":"https:\/\/www.facebook.com\/abiferoficial\/","article_published_time":"2026-02-09T21:31:54+00:00","twitter_card":"summary_large_image","twitter_image":"https:\/\/abifer.org.br\/wp-content\/uploads\/2025\/02\/bandeira-brasil.webp","twitter_creator":"@abiferoficial","twitter_site":"@abiferoficial","twitter_misc":{"Escrito por":"ABIFER","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Organization","@id":"https:\/\/abifer.org.br\/en\/#organization","name":"ABIFER","url":"https:\/\/abifer.org.br\/en\/","sameAs":["https:\/\/www.facebook.com\/abiferoficial\/","https:\/\/www.linkedin.com\/company\/abiferoficial\/","https:\/\/twitter.com\/abiferoficial"],"logo":{"@type":"ImageObject","@id":"https:\/\/abifer.org.br\/en\/#logo","inLanguage":"pt-BR","url":"https:\/\/abifer.org.br\/wp-content\/uploads\/2018\/05\/ABF_001_LogoSlogan.jpg","contentUrl":"https:\/\/abifer.org.br\/wp-content\/uploads\/2018\/05\/ABF_001_LogoSlogan.jpg","width":1182,"height":486,"caption":"ABIFER"},"image":{"@id":"https:\/\/abifer.org.br\/en\/#logo"}},{"@type":"WebSite","@id":"https:\/\/abifer.org.br\/en\/#website","url":"https:\/\/abifer.org.br\/en\/","name":"ABIFER","description":"Associa\u00e7\u00e3o Brasileira da Ind\u00fastria Ferrovi\u00e1ria","publisher":{"@id":"https:\/\/abifer.org.br\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/abifer.org.br\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"ImageObject","@id":"https:\/\/abifer.org.br\/en\/transnordestina-tera-10-terminais-ao-longo-da-ferrovia\/#primaryimage","inLanguage":"pt-BR","url":"https:\/\/abifer.org.br\/wp-content\/uploads\/2025\/02\/bandeira-brasil.webp","contentUrl":"https:\/\/abifer.org.br\/wp-content\/uploads\/2025\/02\/bandeira-brasil.webp","width":1024,"height":1024},{"@type":"WebPage","@id":"https:\/\/abifer.org.br\/en\/transnordestina-tera-10-terminais-ao-longo-da-ferrovia\/#webpage","url":"https:\/\/abifer.org.br\/en\/transnordestina-tera-10-terminais-ao-longo-da-ferrovia\/","name":"Transnordestina ter\u00e1 10 terminais ao longo da ferrovia","isPartOf":{"@id":"https:\/\/abifer.org.br\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/abifer.org.br\/en\/transnordestina-tera-10-terminais-ao-longo-da-ferrovia\/#primaryimage"},"datePublished":"2026-02-09T21:31:54+00:00","dateModified":"2026-02-09T21:31:54+00:00","breadcrumb":{"@id":"https:\/\/abifer.org.br\/en\/transnordestina-tera-10-terminais-ao-longo-da-ferrovia\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/abifer.org.br\/en\/transnordestina-tera-10-terminais-ao-longo-da-ferrovia\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/abifer.org.br\/en\/transnordestina-tera-10-terminais-ao-longo-da-ferrovia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/abifer.org.br\/en\/"},{"@type":"ListItem","position":2,"name":"Transnordestina ter\u00e1 10 terminais ao longo da ferrovia"}]},{"@type":"Article","@id":"https:\/\/abifer.org.br\/en\/transnordestina-tera-10-terminais-ao-longo-da-ferrovia\/#article","isPartOf":{"@id":"https:\/\/abifer.org.br\/en\/transnordestina-tera-10-terminais-ao-longo-da-ferrovia\/#webpage"},"author":{"@id":"https:\/\/abifer.org.br\/en\/#\/schema\/person\/90c38c3286f60a11b363834930f79a1f"},"headline":"Transnordestina ter\u00e1 10 terminais ao longo da ferrovia","datePublished":"2026-02-09T21:31:54+00:00","dateModified":"2026-02-09T21:31:54+00:00","mainEntityOfPage":{"@id":"https:\/\/abifer.org.br\/en\/transnordestina-tera-10-terminais-ao-longo-da-ferrovia\/#webpage"},"wordCount":223,"publisher":{"@id":"https:\/\/abifer.org.br\/en\/#organization"},"image":{"@id":"https:\/\/abifer.org.br\/en\/transnordestina-tera-10-terminais-ao-longo-da-ferrovia\/#primaryimage"},"thumbnailUrl":"https:\/\/abifer.org.br\/wp-content\/uploads\/2025\/02\/bandeira-brasil.webp","articleSection":["Not\u00edcias do Mercado"],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/abifer.org.br\/en\/#\/schema\/person\/90c38c3286f60a11b363834930f79a1f","name":"ABIFER","url":"https:\/\/abifer.org.br\/author\/abifer\/"}]}},"_links":{"self":[{"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/posts\/92506\/"}],"collection":[{"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/posts\/"}],"about":[{"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/types\/post\/"}],"author":[{"embeddable":true,"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/users\/55\/"}],"replies":[{"embeddable":true,"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/comments\/?post=92506"}],"version-history":[{"count":1,"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/posts\/92506\/revisions\/"}],"predecessor-version":[{"id":92507,"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/posts\/92506\/revisions\/92507\/"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/media\/86710\/"}],"wp:attachment":[{"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/media\/?parent=92506"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/categories\/?post=92506"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/tags\/?post=92506"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}