{"id":92835,"date":"2026-02-26T17:22:33","date_gmt":"2026-02-26T20:22:33","guid":{"rendered":"https:\/\/abifer.org.br\/?p=92835"},"modified":"2026-02-26T17:22:33","modified_gmt":"2026-02-26T20:22:33","slug":"ferrovia-na-ba-viabiliza-ate-60-mt-de-minerio-de-ferro-diz-ibram","status":"publish","type":"post","link":"https:\/\/abifer.org.br\/en\/ferrovia-na-ba-viabiliza-ate-60-mt-de-minerio-de-ferro-diz-ibram\/","title":{"rendered":"Ferrovia na BA viabiliza at\u00e9 60 Mt de min\u00e9rio de ferro, diz Ibram"},"content":{"rendered":"<pre style=\"text-align: right;\"><a href=\"https:\/\/agenciainfra.com\/blog\/ferrovia-na-ba-viabiliza-ate-60-mt-de-minerio-de-ferro-diz-ibram\/\" target=\"_blank\" rel=\"noopener\"><strong><em>Fonte: Ag\u00eancia iNFRA\r\nData: 24\/02\/2026<\/em><\/strong><\/a><\/pre>\n<p>A conclus\u00e3o de trechos da Fiol (Ferrovia de Integra\u00e7\u00e3o Oeste-Leste), ligando o interior baiano ao Porto Sul, em Ilh\u00e9us (BA), pode viabilizar produ\u00e7\u00e3o de 50 a 60 Mt (milh\u00f5es de toneladas) de min\u00e9rio de ferro no sul do estado, prev\u00ea o Ibram (Instituto Brasileiro de Minera\u00e7\u00e3o). O segmento corresponde aos trechos Fiol 1 e 2 \u2013 o primeiro paralisado ap\u00f3s o abandono das obras pela Bamin (Bahia Minera\u00e7\u00e3o) e o segundo em execu\u00e7\u00e3o pelo governo federal.<\/p>\n<p>\u201cQuando terminar a constru\u00e7\u00e3o da ferrovia, que j\u00e1 est\u00e1 70% pronta, at\u00e9 o porto de Ilh\u00e9us para exporta\u00e7\u00e3o de min\u00e9rio, a regi\u00e3o n\u00e3o alcan\u00e7ar\u00e1 a produ\u00e7\u00e3o de Minas Gerais e do Par\u00e1, com 180 Mt, mas vai passar de 50 Mt. V\u00e3o produzir de 50 a 60 Mt de min\u00e9rio de boa qualidade por ano\u201d, disse o diretor de assuntos miner\u00e1rios do instituto, Julio Nery, em encontro da diretoria da entidade com jornalistas na segunda-feira (23).<\/p>\n<p>O governo federal est\u00e1 tentando viabilizar o corredor que vai integrar a Fiol \u00e0 Fico (Ferrovia de Integra\u00e7\u00e3o Centro-Oeste) por meio de uma concess\u00e3o. Mas antes precisa resolver a situa\u00e7\u00e3o da Fiol 1, que vai de Ilh\u00e9us a Caetit\u00e9 (BA) e j\u00e1 foi concedida em 2021. Como mostrou a Ag\u00eancia iNFRA, quem avalia comprar o neg\u00f3cio da Bamin, que inclui porto e mina de ferro, \u00e9 a Mota-Engil, construtora portuguesa que tem como acionista a chinesa CCCC (China Communications Construction Company).<\/p>\n<p>A Fiol 2, de Caetit\u00e9 at\u00e9 Correntina (BA), tamb\u00e9m inacabada, \u00e9 mantida pela estatal Infra S.A. O governo ainda discute modelos de contrata\u00e7\u00e3o para viabilizar o terceiro trecho, a Fiol 3, que futuramente deve compor o corredor Fico-Fiol, com longo trajeto do litoral baiano podendo chegar at\u00e9 Lucas do Rio Verde, no interior do Mato Grosso.<\/p>\n<p>Ao tratar da potencialidade da Fiol, a diretoria do Ibram ressaltou a import\u00e2ncia da infraestrutura de log\u00edstica para viabilizar projetos de minera\u00e7\u00e3o no Brasil. Os diretores destacaram que o investimento em ferrovias e portos, por exemplo, representam dois ter\u00e7os do valor dos projetos de minera\u00e7\u00e3o no pa\u00eds. Tal realidade, destacaram, n\u00e3o ocorre em outros pa\u00edses mineradores, como Austr\u00e1lia e Canad\u00e1, onde agentes do setor de transportes se encarregam de fazer os investimentos em ramais ferrovi\u00e1rios ou terminais portu\u00e1rios para escoar a produ\u00e7\u00e3o do min\u00e9rio.<\/p>\n<p><strong>\u2018Nova fronteira\u2019<\/strong><\/p>\n<p>Entre 2026 e 2030, o setor mineral planeja investir US$ 11,2 bilh\u00f5es (ou R$ 58,2 bilh\u00f5es) em infraestrutura log\u00edstica, segundo proje\u00e7\u00e3o do Ibram anunciada no in\u00edcio do m\u00eas. Isso representa 14,6% do total de US$ 76,9 bilh\u00f5es programados pelo setor de minera\u00e7\u00e3o no Brasil no mesmo per\u00edodo.<\/p>\n<p>De acordo com a proje\u00e7\u00e3o, o estado da Bahia receber\u00e1 o terceiro maior volume de investimento do setor, o total de US$ 11,7 bilh\u00f5es (R$ 60,7 bilh\u00f5es) at\u00e9 2030. Minas Gerais e Par\u00e1 receber\u00e3o valores maiores de US$ 19,7 bilh\u00f5es e US$ 14,7 bilh\u00f5es, respectivamente.<\/p>\n<p>Na avalia\u00e7\u00e3o dos diretores do Ibram, a Bahia representa uma \u201cnova fronteira\u201d de explora\u00e7\u00e3o mineral no Brasil, em raz\u00e3o da diversidade de reservas e volume de investimento em mapeamento geol\u00f3gico.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fonte: Ag\u00eancia iNFRA Data: 24\/02\/2026 A conclus\u00e3o de trechos da Fiol (Ferrovia de Integra\u00e7\u00e3o Oeste-Leste), ligando o interior baiano ao Porto Sul, em Ilh\u00e9us (BA), pode viabilizar produ\u00e7\u00e3o de 50 a 60 Mt (milh\u00f5es de toneladas) de min\u00e9rio de ferro no sul do estado, prev\u00ea o Ibram (Instituto Brasileiro de Minera\u00e7\u00e3o). O segmento corresponde aos [&hellip;]<\/p>\n","protected":false},"author":55,"featured_media":92535,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[875],"tags":[],"class_list":["post-92835","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-do-mercado"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Ferrovia na BA viabiliza at\u00e9 60 Mt de min\u00e9rio de ferro, diz Ibram<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/abifer.org.br\/ferrovia-na-ba-viabiliza-ate-60-mt-de-minerio-de-ferro-diz-ibram\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ferrovia na BA viabiliza at\u00e9 60 Mt de min\u00e9rio de ferro, diz Ibram\" \/>\n<meta property=\"og:description\" content=\"Fonte: Ag\u00eancia iNFRA Data: 24\/02\/2026 A conclus\u00e3o de trechos da Fiol (Ferrovia de Integra\u00e7\u00e3o Oeste-Leste), ligando o interior baiano ao Porto Sul, em Ilh\u00e9us (BA), pode viabilizar produ\u00e7\u00e3o de 50 a 60 Mt (milh\u00f5es de toneladas) de min\u00e9rio de ferro no sul do estado, prev\u00ea o Ibram (Instituto Brasileiro de Minera\u00e7\u00e3o). O segmento corresponde aos [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/abifer.org.br\/en\/ferrovia-na-ba-viabiliza-ate-60-mt-de-minerio-de-ferro-diz-ibram\/\" \/>\n<meta property=\"og:site_name\" content=\"ABIFER\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/abiferoficial\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-26T20:22:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/abifer.org.br\/wp-content\/uploads\/2026\/02\/NOTICIAS-DO-MERCADO.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@abiferoficial\" \/>\n<meta name=\"twitter:site\" content=\"@abiferoficial\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"ABIFER\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/abifer.org.br\/en\/#organization\",\"name\":\"ABIFER\",\"url\":\"https:\/\/abifer.org.br\/en\/\",\"sameAs\":[\"https:\/\/www.facebook.com\/abiferoficial\/\",\"https:\/\/www.linkedin.com\/company\/abiferoficial\/\",\"https:\/\/twitter.com\/abiferoficial\"],\"logo\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/abifer.org.br\/en\/#logo\",\"inLanguage\":\"pt-BR\",\"url\":\"https:\/\/abifer.org.br\/wp-content\/uploads\/2018\/05\/ABF_001_LogoSlogan.jpg\",\"contentUrl\":\"https:\/\/abifer.org.br\/wp-content\/uploads\/2018\/05\/ABF_001_LogoSlogan.jpg\",\"width\":1182,\"height\":486,\"caption\":\"ABIFER\"},\"image\":{\"@id\":\"https:\/\/abifer.org.br\/en\/#logo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/abifer.org.br\/en\/#website\",\"url\":\"https:\/\/abifer.org.br\/en\/\",\"name\":\"ABIFER\",\"description\":\"Associa\u00e7\u00e3o Brasileira da Ind\u00fastria Ferrovi\u00e1ria\",\"publisher\":{\"@id\":\"https:\/\/abifer.org.br\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/abifer.org.br\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/abifer.org.br\/en\/ferrovia-na-ba-viabiliza-ate-60-mt-de-minerio-de-ferro-diz-ibram\/#primaryimage\",\"inLanguage\":\"pt-BR\",\"url\":\"https:\/\/abifer.org.br\/wp-content\/uploads\/2026\/02\/NOTICIAS-DO-MERCADO.jpg\",\"contentUrl\":\"https:\/\/abifer.org.br\/wp-content\/uploads\/2026\/02\/NOTICIAS-DO-MERCADO.jpg\",\"width\":1920,\"height\":1080},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/abifer.org.br\/en\/ferrovia-na-ba-viabiliza-ate-60-mt-de-minerio-de-ferro-diz-ibram\/#webpage\",\"url\":\"https:\/\/abifer.org.br\/en\/ferrovia-na-ba-viabiliza-ate-60-mt-de-minerio-de-ferro-diz-ibram\/\",\"name\":\"Ferrovia na BA viabiliza at\u00e9 60 Mt de min\u00e9rio de ferro, diz Ibram\",\"isPartOf\":{\"@id\":\"https:\/\/abifer.org.br\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/abifer.org.br\/en\/ferrovia-na-ba-viabiliza-ate-60-mt-de-minerio-de-ferro-diz-ibram\/#primaryimage\"},\"datePublished\":\"2026-02-26T20:22:33+00:00\",\"dateModified\":\"2026-02-26T20:22:33+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/abifer.org.br\/en\/ferrovia-na-ba-viabiliza-ate-60-mt-de-minerio-de-ferro-diz-ibram\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/abifer.org.br\/en\/ferrovia-na-ba-viabiliza-ate-60-mt-de-minerio-de-ferro-diz-ibram\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/abifer.org.br\/en\/ferrovia-na-ba-viabiliza-ate-60-mt-de-minerio-de-ferro-diz-ibram\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/abifer.org.br\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ferrovia na BA viabiliza at\u00e9 60 Mt de min\u00e9rio de ferro, diz Ibram\"}]},{\"@type\":\"Article\",\"@id\":\"https:\/\/abifer.org.br\/en\/ferrovia-na-ba-viabiliza-ate-60-mt-de-minerio-de-ferro-diz-ibram\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/abifer.org.br\/en\/ferrovia-na-ba-viabiliza-ate-60-mt-de-minerio-de-ferro-diz-ibram\/#webpage\"},\"author\":{\"@id\":\"https:\/\/abifer.org.br\/en\/#\/schema\/person\/90c38c3286f60a11b363834930f79a1f\"},\"headline\":\"Ferrovia na BA viabiliza at\u00e9 60 Mt de min\u00e9rio de ferro, diz Ibram\",\"datePublished\":\"2026-02-26T20:22:33+00:00\",\"dateModified\":\"2026-02-26T20:22:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/abifer.org.br\/en\/ferrovia-na-ba-viabiliza-ate-60-mt-de-minerio-de-ferro-diz-ibram\/#webpage\"},\"wordCount\":543,\"publisher\":{\"@id\":\"https:\/\/abifer.org.br\/en\/#organization\"},\"image\":{\"@id\":\"https:\/\/abifer.org.br\/en\/ferrovia-na-ba-viabiliza-ate-60-mt-de-minerio-de-ferro-diz-ibram\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/abifer.org.br\/wp-content\/uploads\/2026\/02\/NOTICIAS-DO-MERCADO.jpg\",\"articleSection\":[\"Not\u00edcias do Mercado\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/abifer.org.br\/en\/#\/schema\/person\/90c38c3286f60a11b363834930f79a1f\",\"name\":\"ABIFER\",\"url\":\"https:\/\/abifer.org.br\/author\/abifer\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ferrovia na BA viabiliza at\u00e9 60 Mt de min\u00e9rio de ferro, diz Ibram","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/abifer.org.br\/ferrovia-na-ba-viabiliza-ate-60-mt-de-minerio-de-ferro-diz-ibram\/","og_locale":"pt_BR","og_type":"article","og_title":"Ferrovia na BA viabiliza at\u00e9 60 Mt de min\u00e9rio de ferro, diz Ibram","og_description":"Fonte: Ag\u00eancia iNFRA Data: 24\/02\/2026 A conclus\u00e3o de trechos da Fiol (Ferrovia de Integra\u00e7\u00e3o Oeste-Leste), ligando o interior baiano ao Porto Sul, em Ilh\u00e9us (BA), pode viabilizar produ\u00e7\u00e3o de 50 a 60 Mt (milh\u00f5es de toneladas) de min\u00e9rio de ferro no sul do estado, prev\u00ea o Ibram (Instituto Brasileiro de Minera\u00e7\u00e3o). O segmento corresponde aos [&hellip;]","og_url":"https:\/\/abifer.org.br\/en\/ferrovia-na-ba-viabiliza-ate-60-mt-de-minerio-de-ferro-diz-ibram\/","og_site_name":"ABIFER","article_publisher":"https:\/\/www.facebook.com\/abiferoficial\/","article_published_time":"2026-02-26T20:22:33+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/abifer.org.br\/wp-content\/uploads\/2026\/02\/NOTICIAS-DO-MERCADO.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_creator":"@abiferoficial","twitter_site":"@abiferoficial","twitter_misc":{"Escrito por":"ABIFER","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Organization","@id":"https:\/\/abifer.org.br\/en\/#organization","name":"ABIFER","url":"https:\/\/abifer.org.br\/en\/","sameAs":["https:\/\/www.facebook.com\/abiferoficial\/","https:\/\/www.linkedin.com\/company\/abiferoficial\/","https:\/\/twitter.com\/abiferoficial"],"logo":{"@type":"ImageObject","@id":"https:\/\/abifer.org.br\/en\/#logo","inLanguage":"pt-BR","url":"https:\/\/abifer.org.br\/wp-content\/uploads\/2018\/05\/ABF_001_LogoSlogan.jpg","contentUrl":"https:\/\/abifer.org.br\/wp-content\/uploads\/2018\/05\/ABF_001_LogoSlogan.jpg","width":1182,"height":486,"caption":"ABIFER"},"image":{"@id":"https:\/\/abifer.org.br\/en\/#logo"}},{"@type":"WebSite","@id":"https:\/\/abifer.org.br\/en\/#website","url":"https:\/\/abifer.org.br\/en\/","name":"ABIFER","description":"Associa\u00e7\u00e3o Brasileira da Ind\u00fastria Ferrovi\u00e1ria","publisher":{"@id":"https:\/\/abifer.org.br\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/abifer.org.br\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"ImageObject","@id":"https:\/\/abifer.org.br\/en\/ferrovia-na-ba-viabiliza-ate-60-mt-de-minerio-de-ferro-diz-ibram\/#primaryimage","inLanguage":"pt-BR","url":"https:\/\/abifer.org.br\/wp-content\/uploads\/2026\/02\/NOTICIAS-DO-MERCADO.jpg","contentUrl":"https:\/\/abifer.org.br\/wp-content\/uploads\/2026\/02\/NOTICIAS-DO-MERCADO.jpg","width":1920,"height":1080},{"@type":"WebPage","@id":"https:\/\/abifer.org.br\/en\/ferrovia-na-ba-viabiliza-ate-60-mt-de-minerio-de-ferro-diz-ibram\/#webpage","url":"https:\/\/abifer.org.br\/en\/ferrovia-na-ba-viabiliza-ate-60-mt-de-minerio-de-ferro-diz-ibram\/","name":"Ferrovia na BA viabiliza at\u00e9 60 Mt de min\u00e9rio de ferro, diz Ibram","isPartOf":{"@id":"https:\/\/abifer.org.br\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/abifer.org.br\/en\/ferrovia-na-ba-viabiliza-ate-60-mt-de-minerio-de-ferro-diz-ibram\/#primaryimage"},"datePublished":"2026-02-26T20:22:33+00:00","dateModified":"2026-02-26T20:22:33+00:00","breadcrumb":{"@id":"https:\/\/abifer.org.br\/en\/ferrovia-na-ba-viabiliza-ate-60-mt-de-minerio-de-ferro-diz-ibram\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/abifer.org.br\/en\/ferrovia-na-ba-viabiliza-ate-60-mt-de-minerio-de-ferro-diz-ibram\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/abifer.org.br\/en\/ferrovia-na-ba-viabiliza-ate-60-mt-de-minerio-de-ferro-diz-ibram\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/abifer.org.br\/en\/"},{"@type":"ListItem","position":2,"name":"Ferrovia na BA viabiliza at\u00e9 60 Mt de min\u00e9rio de ferro, diz Ibram"}]},{"@type":"Article","@id":"https:\/\/abifer.org.br\/en\/ferrovia-na-ba-viabiliza-ate-60-mt-de-minerio-de-ferro-diz-ibram\/#article","isPartOf":{"@id":"https:\/\/abifer.org.br\/en\/ferrovia-na-ba-viabiliza-ate-60-mt-de-minerio-de-ferro-diz-ibram\/#webpage"},"author":{"@id":"https:\/\/abifer.org.br\/en\/#\/schema\/person\/90c38c3286f60a11b363834930f79a1f"},"headline":"Ferrovia na BA viabiliza at\u00e9 60 Mt de min\u00e9rio de ferro, diz Ibram","datePublished":"2026-02-26T20:22:33+00:00","dateModified":"2026-02-26T20:22:33+00:00","mainEntityOfPage":{"@id":"https:\/\/abifer.org.br\/en\/ferrovia-na-ba-viabiliza-ate-60-mt-de-minerio-de-ferro-diz-ibram\/#webpage"},"wordCount":543,"publisher":{"@id":"https:\/\/abifer.org.br\/en\/#organization"},"image":{"@id":"https:\/\/abifer.org.br\/en\/ferrovia-na-ba-viabiliza-ate-60-mt-de-minerio-de-ferro-diz-ibram\/#primaryimage"},"thumbnailUrl":"https:\/\/abifer.org.br\/wp-content\/uploads\/2026\/02\/NOTICIAS-DO-MERCADO.jpg","articleSection":["Not\u00edcias do Mercado"],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/abifer.org.br\/en\/#\/schema\/person\/90c38c3286f60a11b363834930f79a1f","name":"ABIFER","url":"https:\/\/abifer.org.br\/author\/abifer\/"}]}},"_links":{"self":[{"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/posts\/92835\/"}],"collection":[{"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/posts\/"}],"about":[{"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/types\/post\/"}],"author":[{"embeddable":true,"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/users\/55\/"}],"replies":[{"embeddable":true,"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/comments\/?post=92835"}],"version-history":[{"count":1,"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/posts\/92835\/revisions\/"}],"predecessor-version":[{"id":92836,"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/posts\/92835\/revisions\/92836\/"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/media\/92535\/"}],"wp:attachment":[{"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/media\/?parent=92835"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/categories\/?post=92835"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/tags\/?post=92835"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}