{"id":92879,"date":"2026-03-02T18:28:20","date_gmt":"2026-03-02T21:28:20","guid":{"rendered":"https:\/\/abifer.org.br\/?p=92879"},"modified":"2026-03-02T18:28:20","modified_gmt":"2026-03-02T21:28:20","slug":"antt-abre-dialogo-com-a-sociedade-sobre-o-futuro-da-ferrovia-tereza-cristina-em-santa-catarina","status":"publish","type":"post","link":"https:\/\/abifer.org.br\/en\/antt-abre-dialogo-com-a-sociedade-sobre-o-futuro-da-ferrovia-tereza-cristina-em-santa-catarina\/","title":{"rendered":"ANTT abre di\u00e1logo com a sociedade sobre o futuro da Ferrovia Tereza Cristina em Santa Catarina"},"content":{"rendered":"<pre style=\"text-align: right;\"><a href=\"https:\/\/www.gov.br\/antt\/pt-br\/assuntos\/ultimas-noticias\/antt-abre-dialogo-com-a-sociedade-sobre-o-futuro-da-ferrovia-tereza-cristina-em-santa-catarina\" target=\"_blank\" rel=\"noopener\"><strong><em>Fonte: ANTT\r\nData: 27\/02\/2026<\/em><\/strong><\/a><\/pre>\n<p>A Ag\u00eancia Nacional de Transportes Terrestres (ANTT) abriu oficialmente, nesta sexta-feira (27\/2), o processo de participa\u00e7\u00e3o social para discutir o futuro da Ferrovia Tereza Cristina, uma das principais infraestruturas log\u00edsticas do sul do pa\u00eds. A Ag\u00eancia realizar\u00e1 uma Audi\u00eancia P\u00fablica para ouvir a sociedade sobre a proposta de prorroga\u00e7\u00e3o antecipada do contrato de concess\u00e3o da malha ferrovi\u00e1ria operada pela Ferrovia Tereza Cristina S.A. (FTC), que possui cerca de 163 quil\u00f4metros de extens\u00e3o em Santa Catarina. O processo foi deliberado e aprovado por unanimidade durante a 1027\u00aa Reuni\u00e3o de Diretoria Colegiada (Redir). O diretor da ANTT, Felipe Queiroz, \u00e9 o relator do processo.<\/p>\n<p>A iniciativa busca garantir que decis\u00f5es estrat\u00e9gicas sobre a ferrovia sejam tomadas com transpar\u00eancia, participa\u00e7\u00e3o social e base t\u00e9cnica, permitindo que cidad\u00e3os, empresas, especialistas e gestores p\u00fablicos contribuam diretamente para o aprimoramento das condi\u00e7\u00f5es do contrato e dos investimentos previstos para os pr\u00f3ximos anos.<\/p>\n<p>Na pr\u00e1tica, a audi\u00eancia p\u00fablica representa um momento de escuta ativa da sociedade. A ANTT disponibilizar\u00e1 os estudos t\u00e9cnicos, a proposta de termo aditivo ao contrato e os documentos que fundamentam a poss\u00edvel prorroga\u00e7\u00e3o da concess\u00e3o, permitindo que qualquer interessado analise o material e envie sugest\u00f5es.<\/p>\n<p>A Ferrovia Tereza Cristina desempenha um papel fundamental para a log\u00edstica do sul catarinense. A malha atravessa 14 munic\u00edpios e conecta a regi\u00e3o carbon\u00edfera ao complexo termel\u00e9trico de Capivari de Baixo e ao porto de Imbituba, contribuindo para o transporte de cargas e para a din\u00e2mica econ\u00f4mica regional. Por ser uma ferrovia com forte inser\u00e7\u00e3o urbana, com passagens em n\u00edvel frequentes ao longo do trajeto, as decis\u00f5es sobre seu futuro t\u00eam impacto direto na seguran\u00e7a, na mobilidade urbana e na conviv\u00eancia com as cidades por onde passa.<\/p>\n<p>O processo de participa\u00e7\u00e3o social tamb\u00e9m ocorre em um momento importante de transforma\u00e7\u00e3o do setor energ\u00e9tico brasileiro. A ferrovia transporta atualmente grandes volumes de carv\u00e3o mineral, que representa a maior parte da carga movimentada na malha. Com o avan\u00e7o das pol\u00edticas de transi\u00e7\u00e3o energ\u00e9tica no pa\u00eds, discutir o futuro da infraestrutura ferrovi\u00e1ria torna-se essencial para planejar novos usos log\u00edsticos, garantir sustentabilidade econ\u00f4mica e assegurar a continuidade de um servi\u00e7o ferrovi\u00e1rio eficiente.<\/p>\n<p>Os estudos t\u00e9cnicos elaborados no \u00e2mbito do processo analisam aspectos como demanda de transporte, engenharia, opera\u00e7\u00e3o ferrovi\u00e1ria, modelagem econ\u00f4mico-financeira e impactos ambientais. A proposta de prorroga\u00e7\u00e3o tamb\u00e9m prev\u00ea a atualiza\u00e7\u00e3o de regras contratuais e a inclus\u00e3o de novos mecanismos de governan\u00e7a, gest\u00e3o de riscos e acompanhamento independente do desempenho da concess\u00e3o.<\/p>\n<p>Entre os instrumentos previstos est\u00e3o medidas modernas de gest\u00e3o regulat\u00f3ria, como a presen\u00e7a de verifica\u00e7\u00e3o independente de conformidade, atualiza\u00e7\u00e3o da matriz de riscos do contrato, mecanismos para solu\u00e7\u00e3o de disputas e diretrizes relacionadas \u00e0 sustentabilidade e \u00e0 resili\u00eancia clim\u00e1tica, incluindo programas voltados \u00e0 redu\u00e7\u00e3o de emiss\u00f5es de gases de efeito estufa.<\/p>\n<p>A participa\u00e7\u00e3o social ocorrer\u00e1 entre 9 de mar\u00e7o e 22 de abril de 2026, per\u00edodo em que qualquer cidad\u00e3o poder\u00e1 enviar contribui\u00e7\u00f5es por meio da p\u00e1gina oficial da audi\u00eancia p\u00fablica por meio do Sistema ParticipANTT.<\/p>\n<p>Al\u00e9m da fase de contribui\u00e7\u00f5es escritas, a Ag\u00eancia promover\u00e1 duas sess\u00f5es p\u00fablicas abertas ao p\u00fablico:<\/p>\n<p>&nbsp;<\/p>\n<p>\u00b7\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a011 de mar\u00e7o de 2026 \u2013 Crici\u00fama (SC), \u00e0s 14h, em sess\u00e3o presencial<\/p>\n<p>\u00b7\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a013 de mar\u00e7o de 2026 \u2013 Bras\u00edlia (DF), \u00e0s 10h, em formato h\u00edbrido (presencial e virtual)<\/p>\n<p>As sess\u00f5es tamb\u00e9m ser\u00e3o transmitidas ao vivo pelo canal da ANTT no YouTube, permitindo que pessoas de todo o pa\u00eds acompanhem os debates.<\/p>\n<p>Para a ANTT, ampliar os espa\u00e7os de di\u00e1logo com a sociedade \u00e9 parte essencial do processo regulat\u00f3rio. A participa\u00e7\u00e3o p\u00fablica permite que decis\u00f5es sobre infraestrutura e transporte sejam constru\u00eddas com base em evid\u00eancias t\u00e9cnicas e na escuta da popula\u00e7\u00e3o, fortalecendo a seguran\u00e7a jur\u00eddica, a qualidade dos servi\u00e7os e a confian\u00e7a nas institui\u00e7\u00f5es.<\/p>\n<p>Mais informa\u00e7\u00f5es sobre a audi\u00eancia p\u00fablica, incluindo os estudos t\u00e9cnicos e orienta\u00e7\u00f5es para participa\u00e7\u00e3o, estar\u00e3o dispon\u00edveis no portal da ANTT a partir de 27 de fevereiro de 2026.<\/p>\n<p>A iniciativa refor\u00e7a o compromisso da Ag\u00eancia com uma regula\u00e7\u00e3o transparente, participativa e orientada para as pessoas, reconhecendo que cada decis\u00e3o sobre infraestrutura impacta diretamente a vida de quem vive, trabalha e se desloca nas regi\u00f5es atendidas pelas ferrovias brasileiras.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fonte: ANTT Data: 27\/02\/2026 A Ag\u00eancia Nacional de Transportes Terrestres (ANTT) abriu oficialmente, nesta sexta-feira (27\/2), o processo de participa\u00e7\u00e3o social para discutir o futuro da Ferrovia Tereza Cristina, uma das principais infraestruturas log\u00edsticas do sul do pa\u00eds. A Ag\u00eancia realizar\u00e1 uma Audi\u00eancia P\u00fablica para ouvir a sociedade sobre a proposta de prorroga\u00e7\u00e3o antecipada do [&hellip;]<\/p>\n","protected":false},"author":55,"featured_media":92535,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[875],"tags":[],"class_list":["post-92879","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-do-mercado"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>ANTT abre di\u00e1logo com a sociedade sobre o futuro da Ferrovia Tereza Cristina em Santa Catarina<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/abifer.org.br\/antt-abre-dialogo-com-a-sociedade-sobre-o-futuro-da-ferrovia-tereza-cristina-em-santa-catarina\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ANTT abre di\u00e1logo com a sociedade sobre o futuro da Ferrovia Tereza Cristina em Santa Catarina\" \/>\n<meta property=\"og:description\" content=\"Fonte: ANTT Data: 27\/02\/2026 A Ag\u00eancia Nacional de Transportes Terrestres (ANTT) abriu oficialmente, nesta sexta-feira (27\/2), o processo de participa\u00e7\u00e3o social para discutir o futuro da Ferrovia Tereza Cristina, uma das principais infraestruturas log\u00edsticas do sul do pa\u00eds. A Ag\u00eancia realizar\u00e1 uma Audi\u00eancia P\u00fablica para ouvir a sociedade sobre a proposta de prorroga\u00e7\u00e3o antecipada do [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/abifer.org.br\/antt-abre-dialogo-com-a-sociedade-sobre-o-futuro-da-ferrovia-tereza-cristina-em-santa-catarina\/\" \/>\n<meta property=\"og:site_name\" content=\"ABIFER\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/abiferoficial\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-02T21:28:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/abifer.org.br\/wp-content\/uploads\/2026\/02\/NOTICIAS-DO-MERCADO.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@abiferoficial\" \/>\n<meta name=\"twitter:site\" content=\"@abiferoficial\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"ABIFER\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/abifer.org.br\/en\/#organization\",\"name\":\"ABIFER\",\"url\":\"https:\/\/abifer.org.br\/en\/\",\"sameAs\":[\"https:\/\/www.facebook.com\/abiferoficial\/\",\"https:\/\/www.linkedin.com\/company\/abiferoficial\/\",\"https:\/\/twitter.com\/abiferoficial\"],\"logo\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/abifer.org.br\/en\/#logo\",\"inLanguage\":\"pt-BR\",\"url\":\"https:\/\/abifer.org.br\/wp-content\/uploads\/2018\/05\/ABF_001_LogoSlogan.jpg\",\"contentUrl\":\"https:\/\/abifer.org.br\/wp-content\/uploads\/2018\/05\/ABF_001_LogoSlogan.jpg\",\"width\":1182,\"height\":486,\"caption\":\"ABIFER\"},\"image\":{\"@id\":\"https:\/\/abifer.org.br\/en\/#logo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/abifer.org.br\/en\/#website\",\"url\":\"https:\/\/abifer.org.br\/en\/\",\"name\":\"ABIFER\",\"description\":\"Associa\u00e7\u00e3o Brasileira da Ind\u00fastria Ferrovi\u00e1ria\",\"publisher\":{\"@id\":\"https:\/\/abifer.org.br\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/abifer.org.br\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/abifer.org.br\/antt-abre-dialogo-com-a-sociedade-sobre-o-futuro-da-ferrovia-tereza-cristina-em-santa-catarina\/#primaryimage\",\"inLanguage\":\"pt-BR\",\"url\":\"https:\/\/abifer.org.br\/wp-content\/uploads\/2026\/02\/NOTICIAS-DO-MERCADO.jpg\",\"contentUrl\":\"https:\/\/abifer.org.br\/wp-content\/uploads\/2026\/02\/NOTICIAS-DO-MERCADO.jpg\",\"width\":1920,\"height\":1080},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/abifer.org.br\/antt-abre-dialogo-com-a-sociedade-sobre-o-futuro-da-ferrovia-tereza-cristina-em-santa-catarina\/#webpage\",\"url\":\"https:\/\/abifer.org.br\/antt-abre-dialogo-com-a-sociedade-sobre-o-futuro-da-ferrovia-tereza-cristina-em-santa-catarina\/\",\"name\":\"ANTT abre di\u00e1logo com a sociedade sobre o futuro da Ferrovia Tereza Cristina em Santa Catarina\",\"isPartOf\":{\"@id\":\"https:\/\/abifer.org.br\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/abifer.org.br\/antt-abre-dialogo-com-a-sociedade-sobre-o-futuro-da-ferrovia-tereza-cristina-em-santa-catarina\/#primaryimage\"},\"datePublished\":\"2026-03-02T21:28:20+00:00\",\"dateModified\":\"2026-03-02T21:28:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/abifer.org.br\/antt-abre-dialogo-com-a-sociedade-sobre-o-futuro-da-ferrovia-tereza-cristina-em-santa-catarina\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/abifer.org.br\/antt-abre-dialogo-com-a-sociedade-sobre-o-futuro-da-ferrovia-tereza-cristina-em-santa-catarina\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/abifer.org.br\/antt-abre-dialogo-com-a-sociedade-sobre-o-futuro-da-ferrovia-tereza-cristina-em-santa-catarina\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/abifer.org.br\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ANTT abre di\u00e1logo com a sociedade sobre o futuro da Ferrovia Tereza Cristina em Santa Catarina\"}]},{\"@type\":\"Article\",\"@id\":\"https:\/\/abifer.org.br\/antt-abre-dialogo-com-a-sociedade-sobre-o-futuro-da-ferrovia-tereza-cristina-em-santa-catarina\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/abifer.org.br\/antt-abre-dialogo-com-a-sociedade-sobre-o-futuro-da-ferrovia-tereza-cristina-em-santa-catarina\/#webpage\"},\"author\":{\"@id\":\"https:\/\/abifer.org.br\/en\/#\/schema\/person\/90c38c3286f60a11b363834930f79a1f\"},\"headline\":\"ANTT abre di\u00e1logo com a sociedade sobre o futuro da Ferrovia Tereza Cristina em Santa Catarina\",\"datePublished\":\"2026-03-02T21:28:20+00:00\",\"dateModified\":\"2026-03-02T21:28:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/abifer.org.br\/antt-abre-dialogo-com-a-sociedade-sobre-o-futuro-da-ferrovia-tereza-cristina-em-santa-catarina\/#webpage\"},\"wordCount\":805,\"publisher\":{\"@id\":\"https:\/\/abifer.org.br\/en\/#organization\"},\"image\":{\"@id\":\"https:\/\/abifer.org.br\/antt-abre-dialogo-com-a-sociedade-sobre-o-futuro-da-ferrovia-tereza-cristina-em-santa-catarina\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/abifer.org.br\/wp-content\/uploads\/2026\/02\/NOTICIAS-DO-MERCADO.jpg\",\"articleSection\":[\"Not\u00edcias do Mercado\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/abifer.org.br\/en\/#\/schema\/person\/90c38c3286f60a11b363834930f79a1f\",\"name\":\"ABIFER\",\"url\":\"https:\/\/abifer.org.br\/author\/abifer\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ANTT abre di\u00e1logo com a sociedade sobre o futuro da Ferrovia Tereza Cristina em Santa Catarina","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/abifer.org.br\/antt-abre-dialogo-com-a-sociedade-sobre-o-futuro-da-ferrovia-tereza-cristina-em-santa-catarina\/","og_locale":"pt_BR","og_type":"article","og_title":"ANTT abre di\u00e1logo com a sociedade sobre o futuro da Ferrovia Tereza Cristina em Santa Catarina","og_description":"Fonte: ANTT Data: 27\/02\/2026 A Ag\u00eancia Nacional de Transportes Terrestres (ANTT) abriu oficialmente, nesta sexta-feira (27\/2), o processo de participa\u00e7\u00e3o social para discutir o futuro da Ferrovia Tereza Cristina, uma das principais infraestruturas log\u00edsticas do sul do pa\u00eds. A Ag\u00eancia realizar\u00e1 uma Audi\u00eancia P\u00fablica para ouvir a sociedade sobre a proposta de prorroga\u00e7\u00e3o antecipada do [&hellip;]","og_url":"https:\/\/abifer.org.br\/antt-abre-dialogo-com-a-sociedade-sobre-o-futuro-da-ferrovia-tereza-cristina-em-santa-catarina\/","og_site_name":"ABIFER","article_publisher":"https:\/\/www.facebook.com\/abiferoficial\/","article_published_time":"2026-03-02T21:28:20+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/abifer.org.br\/wp-content\/uploads\/2026\/02\/NOTICIAS-DO-MERCADO.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_creator":"@abiferoficial","twitter_site":"@abiferoficial","twitter_misc":{"Escrito por":"ABIFER","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Organization","@id":"https:\/\/abifer.org.br\/en\/#organization","name":"ABIFER","url":"https:\/\/abifer.org.br\/en\/","sameAs":["https:\/\/www.facebook.com\/abiferoficial\/","https:\/\/www.linkedin.com\/company\/abiferoficial\/","https:\/\/twitter.com\/abiferoficial"],"logo":{"@type":"ImageObject","@id":"https:\/\/abifer.org.br\/en\/#logo","inLanguage":"pt-BR","url":"https:\/\/abifer.org.br\/wp-content\/uploads\/2018\/05\/ABF_001_LogoSlogan.jpg","contentUrl":"https:\/\/abifer.org.br\/wp-content\/uploads\/2018\/05\/ABF_001_LogoSlogan.jpg","width":1182,"height":486,"caption":"ABIFER"},"image":{"@id":"https:\/\/abifer.org.br\/en\/#logo"}},{"@type":"WebSite","@id":"https:\/\/abifer.org.br\/en\/#website","url":"https:\/\/abifer.org.br\/en\/","name":"ABIFER","description":"Associa\u00e7\u00e3o Brasileira da Ind\u00fastria Ferrovi\u00e1ria","publisher":{"@id":"https:\/\/abifer.org.br\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/abifer.org.br\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"ImageObject","@id":"https:\/\/abifer.org.br\/antt-abre-dialogo-com-a-sociedade-sobre-o-futuro-da-ferrovia-tereza-cristina-em-santa-catarina\/#primaryimage","inLanguage":"pt-BR","url":"https:\/\/abifer.org.br\/wp-content\/uploads\/2026\/02\/NOTICIAS-DO-MERCADO.jpg","contentUrl":"https:\/\/abifer.org.br\/wp-content\/uploads\/2026\/02\/NOTICIAS-DO-MERCADO.jpg","width":1920,"height":1080},{"@type":"WebPage","@id":"https:\/\/abifer.org.br\/antt-abre-dialogo-com-a-sociedade-sobre-o-futuro-da-ferrovia-tereza-cristina-em-santa-catarina\/#webpage","url":"https:\/\/abifer.org.br\/antt-abre-dialogo-com-a-sociedade-sobre-o-futuro-da-ferrovia-tereza-cristina-em-santa-catarina\/","name":"ANTT abre di\u00e1logo com a sociedade sobre o futuro da Ferrovia Tereza Cristina em Santa Catarina","isPartOf":{"@id":"https:\/\/abifer.org.br\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/abifer.org.br\/antt-abre-dialogo-com-a-sociedade-sobre-o-futuro-da-ferrovia-tereza-cristina-em-santa-catarina\/#primaryimage"},"datePublished":"2026-03-02T21:28:20+00:00","dateModified":"2026-03-02T21:28:20+00:00","breadcrumb":{"@id":"https:\/\/abifer.org.br\/antt-abre-dialogo-com-a-sociedade-sobre-o-futuro-da-ferrovia-tereza-cristina-em-santa-catarina\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/abifer.org.br\/antt-abre-dialogo-com-a-sociedade-sobre-o-futuro-da-ferrovia-tereza-cristina-em-santa-catarina\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/abifer.org.br\/antt-abre-dialogo-com-a-sociedade-sobre-o-futuro-da-ferrovia-tereza-cristina-em-santa-catarina\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/abifer.org.br\/en\/"},{"@type":"ListItem","position":2,"name":"ANTT abre di\u00e1logo com a sociedade sobre o futuro da Ferrovia Tereza Cristina em Santa Catarina"}]},{"@type":"Article","@id":"https:\/\/abifer.org.br\/antt-abre-dialogo-com-a-sociedade-sobre-o-futuro-da-ferrovia-tereza-cristina-em-santa-catarina\/#article","isPartOf":{"@id":"https:\/\/abifer.org.br\/antt-abre-dialogo-com-a-sociedade-sobre-o-futuro-da-ferrovia-tereza-cristina-em-santa-catarina\/#webpage"},"author":{"@id":"https:\/\/abifer.org.br\/en\/#\/schema\/person\/90c38c3286f60a11b363834930f79a1f"},"headline":"ANTT abre di\u00e1logo com a sociedade sobre o futuro da Ferrovia Tereza Cristina em Santa Catarina","datePublished":"2026-03-02T21:28:20+00:00","dateModified":"2026-03-02T21:28:20+00:00","mainEntityOfPage":{"@id":"https:\/\/abifer.org.br\/antt-abre-dialogo-com-a-sociedade-sobre-o-futuro-da-ferrovia-tereza-cristina-em-santa-catarina\/#webpage"},"wordCount":805,"publisher":{"@id":"https:\/\/abifer.org.br\/en\/#organization"},"image":{"@id":"https:\/\/abifer.org.br\/antt-abre-dialogo-com-a-sociedade-sobre-o-futuro-da-ferrovia-tereza-cristina-em-santa-catarina\/#primaryimage"},"thumbnailUrl":"https:\/\/abifer.org.br\/wp-content\/uploads\/2026\/02\/NOTICIAS-DO-MERCADO.jpg","articleSection":["Not\u00edcias do Mercado"],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/abifer.org.br\/en\/#\/schema\/person\/90c38c3286f60a11b363834930f79a1f","name":"ABIFER","url":"https:\/\/abifer.org.br\/author\/abifer\/"}]}},"_links":{"self":[{"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/posts\/92879\/"}],"collection":[{"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/posts\/"}],"about":[{"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/types\/post\/"}],"author":[{"embeddable":true,"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/users\/55\/"}],"replies":[{"embeddable":true,"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/comments\/?post=92879"}],"version-history":[{"count":1,"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/posts\/92879\/revisions\/"}],"predecessor-version":[{"id":92880,"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/posts\/92879\/revisions\/92880\/"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/media\/92535\/"}],"wp:attachment":[{"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/media\/?parent=92879"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/categories\/?post=92879"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/tags\/?post=92879"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}