{"id":93423,"date":"2026-04-16T18:50:49","date_gmt":"2026-04-16T21:50:49","guid":{"rendered":"https:\/\/abifer.org.br\/?p=93423"},"modified":"2026-04-16T18:50:49","modified_gmt":"2026-04-16T21:50:49","slug":"mineracao-tem-faturamento-de-r-779-bilhoes-no-1o-tri-alta-de-6","status":"publish","type":"post","link":"https:\/\/abifer.org.br\/en\/mineracao-tem-faturamento-de-r-779-bilhoes-no-1o-tri-alta-de-6\/","title":{"rendered":"Minera\u00e7\u00e3o tem faturamento de R$ 77,9 bilh\u00f5es no 1\u00ba tri; alta de 6%"},"content":{"rendered":"<pre style=\"text-align: right;\"><a href=\"https:\/\/valor.globo.com\/empresas\/noticia\/2026\/04\/15\/setor-mineral-fatura-r-779-bilhoes-no-1o-trimestre-alta-de-6percent-diz-ibram.ghtml\" target=\"_blank\" rel=\"noopener\"><strong><em>Fonte: Valor\r\nData: 15\/05\/2026<\/em><\/strong><\/a><\/pre>\n<p>As mineradoras registram o faturamento de R$ 77,9 bilh\u00f5es no primeiro trimestre de 2026, com alta de 6% em rela\u00e7\u00e3o ao mesmo per\u00edodo do ano passado (R$ 73,8 bilh\u00f5es), informou nesta quarta-feira (15) o Ibram (Instituto Brasileiro de Minera\u00e7\u00e3o).<\/p>\n<p>O estado de Minas Gerais respondeu pela maior parte do faturamento no setor, nos primeiros tr\u00eas meses deste ano, com 38%. O Par\u00e1 aparece com a segunda maior participa\u00e7\u00e3o (35%), seguido por Bahia (6%).<\/p>\n<p>De acordo com o Ibram, a minera\u00e7\u00e3o no Brasil alcan\u00e7ou 230 mil empregos diretos no setor em fevereiro. Foram geradas 9 mil novas vagas entre janeiro de 2025 a fevereiro deste ano.<\/p>\n<p>No Brasil, o setor mineral exportou o total de 87,9 milh\u00f5es de toneladas (US$ 11,4 bilh\u00f5es) contra a importa\u00e7\u00e3o de 10 milh\u00f5es de toneladas (US$ 2,1 bilh\u00f5es) nos tr\u00eas primeiros meses do ano. Com o saldo positivo em US$ 9,29 bilh\u00f5es, o setor mineral respondeu por 66% do super\u00e1vit de US$ 14,17 bilh\u00f5es da balan\u00e7a comercial brasileira no per\u00edodo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fonte: Valor Data: 15\/05\/2026 As mineradoras registram o faturamento de R$ 77,9 bilh\u00f5es no primeiro trimestre de 2026, com alta de 6% em rela\u00e7\u00e3o ao mesmo per\u00edodo do ano passado (R$ 73,8 bilh\u00f5es), informou nesta quarta-feira (15) o Ibram (Instituto Brasileiro de Minera\u00e7\u00e3o). O estado de Minas Gerais respondeu pela maior parte do faturamento no [&hellip;]<\/p>\n","protected":false},"author":55,"featured_media":92535,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[875],"tags":[],"class_list":["post-93423","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-do-mercado"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Minera\u00e7\u00e3o tem faturamento de R$ 77,9 bilh\u00f5es no 1\u00ba tri; alta de 6%<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/abifer.org.br\/mineracao-tem-faturamento-de-r-779-bilhoes-no-1o-tri-alta-de-6\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Minera\u00e7\u00e3o tem faturamento de R$ 77,9 bilh\u00f5es no 1\u00ba tri; alta de 6%\" \/>\n<meta property=\"og:description\" content=\"Fonte: Valor Data: 15\/05\/2026 As mineradoras registram o faturamento de R$ 77,9 bilh\u00f5es no primeiro trimestre de 2026, com alta de 6% em rela\u00e7\u00e3o ao mesmo per\u00edodo do ano passado (R$ 73,8 bilh\u00f5es), informou nesta quarta-feira (15) o Ibram (Instituto Brasileiro de Minera\u00e7\u00e3o). O estado de Minas Gerais respondeu pela maior parte do faturamento no [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/abifer.org.br\/mineracao-tem-faturamento-de-r-779-bilhoes-no-1o-tri-alta-de-6\/\" \/>\n<meta property=\"og:site_name\" content=\"ABIFER\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/abiferoficial\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-16T21:50:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/abifer.org.br\/wp-content\/uploads\/2026\/02\/NOTICIAS-DO-MERCADO.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@abiferoficial\" \/>\n<meta name=\"twitter:site\" content=\"@abiferoficial\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"ABIFER\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/abifer.org.br\/en\/#organization\",\"name\":\"ABIFER\",\"url\":\"https:\/\/abifer.org.br\/en\/\",\"sameAs\":[\"https:\/\/www.facebook.com\/abiferoficial\/\",\"https:\/\/www.linkedin.com\/company\/abiferoficial\/\",\"https:\/\/twitter.com\/abiferoficial\"],\"logo\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/abifer.org.br\/en\/#logo\",\"inLanguage\":\"pt-BR\",\"url\":\"https:\/\/abifer.org.br\/wp-content\/uploads\/2018\/05\/ABF_001_LogoSlogan.jpg\",\"contentUrl\":\"https:\/\/abifer.org.br\/wp-content\/uploads\/2018\/05\/ABF_001_LogoSlogan.jpg\",\"width\":1182,\"height\":486,\"caption\":\"ABIFER\"},\"image\":{\"@id\":\"https:\/\/abifer.org.br\/en\/#logo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/abifer.org.br\/en\/#website\",\"url\":\"https:\/\/abifer.org.br\/en\/\",\"name\":\"ABIFER\",\"description\":\"Associa\u00e7\u00e3o Brasileira da Ind\u00fastria Ferrovi\u00e1ria\",\"publisher\":{\"@id\":\"https:\/\/abifer.org.br\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/abifer.org.br\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/abifer.org.br\/mineracao-tem-faturamento-de-r-779-bilhoes-no-1o-tri-alta-de-6\/#primaryimage\",\"inLanguage\":\"pt-BR\",\"url\":\"https:\/\/abifer.org.br\/wp-content\/uploads\/2026\/02\/NOTICIAS-DO-MERCADO.jpg\",\"contentUrl\":\"https:\/\/abifer.org.br\/wp-content\/uploads\/2026\/02\/NOTICIAS-DO-MERCADO.jpg\",\"width\":1920,\"height\":1080},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/abifer.org.br\/mineracao-tem-faturamento-de-r-779-bilhoes-no-1o-tri-alta-de-6\/#webpage\",\"url\":\"https:\/\/abifer.org.br\/mineracao-tem-faturamento-de-r-779-bilhoes-no-1o-tri-alta-de-6\/\",\"name\":\"Minera\u00e7\u00e3o tem faturamento de R$ 77,9 bilh\u00f5es no 1\u00ba tri; alta de 6%\",\"isPartOf\":{\"@id\":\"https:\/\/abifer.org.br\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/abifer.org.br\/mineracao-tem-faturamento-de-r-779-bilhoes-no-1o-tri-alta-de-6\/#primaryimage\"},\"datePublished\":\"2026-04-16T21:50:49+00:00\",\"dateModified\":\"2026-04-16T21:50:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/abifer.org.br\/mineracao-tem-faturamento-de-r-779-bilhoes-no-1o-tri-alta-de-6\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/abifer.org.br\/mineracao-tem-faturamento-de-r-779-bilhoes-no-1o-tri-alta-de-6\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/abifer.org.br\/mineracao-tem-faturamento-de-r-779-bilhoes-no-1o-tri-alta-de-6\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/abifer.org.br\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Minera\u00e7\u00e3o tem faturamento de R$ 77,9 bilh\u00f5es no 1\u00ba tri; alta de 6%\"}]},{\"@type\":\"Article\",\"@id\":\"https:\/\/abifer.org.br\/mineracao-tem-faturamento-de-r-779-bilhoes-no-1o-tri-alta-de-6\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/abifer.org.br\/mineracao-tem-faturamento-de-r-779-bilhoes-no-1o-tri-alta-de-6\/#webpage\"},\"author\":{\"@id\":\"https:\/\/abifer.org.br\/en\/#\/schema\/person\/90c38c3286f60a11b363834930f79a1f\"},\"headline\":\"Minera\u00e7\u00e3o tem faturamento de R$ 77,9 bilh\u00f5es no 1\u00ba tri; alta de 6%\",\"datePublished\":\"2026-04-16T21:50:49+00:00\",\"dateModified\":\"2026-04-16T21:50:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/abifer.org.br\/mineracao-tem-faturamento-de-r-779-bilhoes-no-1o-tri-alta-de-6\/#webpage\"},\"wordCount\":178,\"publisher\":{\"@id\":\"https:\/\/abifer.org.br\/en\/#organization\"},\"image\":{\"@id\":\"https:\/\/abifer.org.br\/mineracao-tem-faturamento-de-r-779-bilhoes-no-1o-tri-alta-de-6\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/abifer.org.br\/wp-content\/uploads\/2026\/02\/NOTICIAS-DO-MERCADO.jpg\",\"articleSection\":[\"Not\u00edcias do Mercado\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/abifer.org.br\/en\/#\/schema\/person\/90c38c3286f60a11b363834930f79a1f\",\"name\":\"ABIFER\",\"url\":\"https:\/\/abifer.org.br\/author\/abifer\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Minera\u00e7\u00e3o tem faturamento de R$ 77,9 bilh\u00f5es no 1\u00ba tri; alta de 6%","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/abifer.org.br\/mineracao-tem-faturamento-de-r-779-bilhoes-no-1o-tri-alta-de-6\/","og_locale":"pt_BR","og_type":"article","og_title":"Minera\u00e7\u00e3o tem faturamento de R$ 77,9 bilh\u00f5es no 1\u00ba tri; alta de 6%","og_description":"Fonte: Valor Data: 15\/05\/2026 As mineradoras registram o faturamento de R$ 77,9 bilh\u00f5es no primeiro trimestre de 2026, com alta de 6% em rela\u00e7\u00e3o ao mesmo per\u00edodo do ano passado (R$ 73,8 bilh\u00f5es), informou nesta quarta-feira (15) o Ibram (Instituto Brasileiro de Minera\u00e7\u00e3o). O estado de Minas Gerais respondeu pela maior parte do faturamento no [&hellip;]","og_url":"https:\/\/abifer.org.br\/mineracao-tem-faturamento-de-r-779-bilhoes-no-1o-tri-alta-de-6\/","og_site_name":"ABIFER","article_publisher":"https:\/\/www.facebook.com\/abiferoficial\/","article_published_time":"2026-04-16T21:50:49+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/abifer.org.br\/wp-content\/uploads\/2026\/02\/NOTICIAS-DO-MERCADO.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_creator":"@abiferoficial","twitter_site":"@abiferoficial","twitter_misc":{"Escrito por":"ABIFER","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Organization","@id":"https:\/\/abifer.org.br\/en\/#organization","name":"ABIFER","url":"https:\/\/abifer.org.br\/en\/","sameAs":["https:\/\/www.facebook.com\/abiferoficial\/","https:\/\/www.linkedin.com\/company\/abiferoficial\/","https:\/\/twitter.com\/abiferoficial"],"logo":{"@type":"ImageObject","@id":"https:\/\/abifer.org.br\/en\/#logo","inLanguage":"pt-BR","url":"https:\/\/abifer.org.br\/wp-content\/uploads\/2018\/05\/ABF_001_LogoSlogan.jpg","contentUrl":"https:\/\/abifer.org.br\/wp-content\/uploads\/2018\/05\/ABF_001_LogoSlogan.jpg","width":1182,"height":486,"caption":"ABIFER"},"image":{"@id":"https:\/\/abifer.org.br\/en\/#logo"}},{"@type":"WebSite","@id":"https:\/\/abifer.org.br\/en\/#website","url":"https:\/\/abifer.org.br\/en\/","name":"ABIFER","description":"Associa\u00e7\u00e3o Brasileira da Ind\u00fastria Ferrovi\u00e1ria","publisher":{"@id":"https:\/\/abifer.org.br\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/abifer.org.br\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"ImageObject","@id":"https:\/\/abifer.org.br\/mineracao-tem-faturamento-de-r-779-bilhoes-no-1o-tri-alta-de-6\/#primaryimage","inLanguage":"pt-BR","url":"https:\/\/abifer.org.br\/wp-content\/uploads\/2026\/02\/NOTICIAS-DO-MERCADO.jpg","contentUrl":"https:\/\/abifer.org.br\/wp-content\/uploads\/2026\/02\/NOTICIAS-DO-MERCADO.jpg","width":1920,"height":1080},{"@type":"WebPage","@id":"https:\/\/abifer.org.br\/mineracao-tem-faturamento-de-r-779-bilhoes-no-1o-tri-alta-de-6\/#webpage","url":"https:\/\/abifer.org.br\/mineracao-tem-faturamento-de-r-779-bilhoes-no-1o-tri-alta-de-6\/","name":"Minera\u00e7\u00e3o tem faturamento de R$ 77,9 bilh\u00f5es no 1\u00ba tri; alta de 6%","isPartOf":{"@id":"https:\/\/abifer.org.br\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/abifer.org.br\/mineracao-tem-faturamento-de-r-779-bilhoes-no-1o-tri-alta-de-6\/#primaryimage"},"datePublished":"2026-04-16T21:50:49+00:00","dateModified":"2026-04-16T21:50:49+00:00","breadcrumb":{"@id":"https:\/\/abifer.org.br\/mineracao-tem-faturamento-de-r-779-bilhoes-no-1o-tri-alta-de-6\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/abifer.org.br\/mineracao-tem-faturamento-de-r-779-bilhoes-no-1o-tri-alta-de-6\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/abifer.org.br\/mineracao-tem-faturamento-de-r-779-bilhoes-no-1o-tri-alta-de-6\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/abifer.org.br\/en\/"},{"@type":"ListItem","position":2,"name":"Minera\u00e7\u00e3o tem faturamento de R$ 77,9 bilh\u00f5es no 1\u00ba tri; alta de 6%"}]},{"@type":"Article","@id":"https:\/\/abifer.org.br\/mineracao-tem-faturamento-de-r-779-bilhoes-no-1o-tri-alta-de-6\/#article","isPartOf":{"@id":"https:\/\/abifer.org.br\/mineracao-tem-faturamento-de-r-779-bilhoes-no-1o-tri-alta-de-6\/#webpage"},"author":{"@id":"https:\/\/abifer.org.br\/en\/#\/schema\/person\/90c38c3286f60a11b363834930f79a1f"},"headline":"Minera\u00e7\u00e3o tem faturamento de R$ 77,9 bilh\u00f5es no 1\u00ba tri; alta de 6%","datePublished":"2026-04-16T21:50:49+00:00","dateModified":"2026-04-16T21:50:49+00:00","mainEntityOfPage":{"@id":"https:\/\/abifer.org.br\/mineracao-tem-faturamento-de-r-779-bilhoes-no-1o-tri-alta-de-6\/#webpage"},"wordCount":178,"publisher":{"@id":"https:\/\/abifer.org.br\/en\/#organization"},"image":{"@id":"https:\/\/abifer.org.br\/mineracao-tem-faturamento-de-r-779-bilhoes-no-1o-tri-alta-de-6\/#primaryimage"},"thumbnailUrl":"https:\/\/abifer.org.br\/wp-content\/uploads\/2026\/02\/NOTICIAS-DO-MERCADO.jpg","articleSection":["Not\u00edcias do Mercado"],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/abifer.org.br\/en\/#\/schema\/person\/90c38c3286f60a11b363834930f79a1f","name":"ABIFER","url":"https:\/\/abifer.org.br\/author\/abifer\/"}]}},"_links":{"self":[{"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/posts\/93423\/"}],"collection":[{"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/posts\/"}],"about":[{"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/types\/post\/"}],"author":[{"embeddable":true,"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/users\/55\/"}],"replies":[{"embeddable":true,"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/comments\/?post=93423"}],"version-history":[{"count":1,"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/posts\/93423\/revisions\/"}],"predecessor-version":[{"id":93424,"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/posts\/93423\/revisions\/93424\/"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/media\/92535\/"}],"wp:attachment":[{"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/media\/?parent=93423"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/categories\/?post=93423"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/abifer.org.br\/en\/wp-json\/wp\/v2\/tags\/?post=93423"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}